{"id":69664,"date":"2024-09-10T01:39:27","date_gmt":"2024-09-10T07:39:27","guid":{"rendered":"https:\/\/www.grieta.org.mx\/?p=69664"},"modified":"2024-09-12T01:50:43","modified_gmt":"2024-09-12T07:50:43","slug":"estudiantes-de-la-uam-xochimilco-se-van-a-paro-academico-por-inseguridad-ciudad-de-mexico","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2024\/09\/10\/estudiantes-de-la-uam-xochimilco-se-van-a-paro-academico-por-inseguridad-ciudad-de-mexico\/","title":{"rendered":"Estudiantes de la UAM-Xochimilco se van a paro acad\u00e9mico por inseguridad (Ciudad de M\u00e9xico)"},"content":{"rendered":"<div class=\"row justify-content-center g-0 align-items-center\">\n<div class=\"col-md-8 col-12 d-flex\">\n<div class=\"row g-0\">\n<div class=\"col\">\n<h6 class=\"texto-sm mb-0 work-sans font-italic\">10 septiembre, 2024<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Texto: Kau Sirenio<\/p>\n<p>Foto: Manuel Ta Safi<\/p>\n<p>Pie de P\u00e1gina<\/p>\n<p><strong>La negativa de la rector\u00eda para resolver la inseguridad llev\u00f3 a los universitarios anunciaran a parar las actividades por 48 horas<\/strong><\/p>\n<p>Estudiantes de la Universidad Aut\u00f3noma Metropolitana (UAM) Unidad Xochimilco iniciaron paro de 48 horas este lunes, ante la violencia e inseguridad en la instalaci\u00f3n universitaria. La protesta fue convocado por colectivos estudiantiles para exigir a la rector\u00eda que garantice la seguridad para la comunidad estudiantil.<br \/>\nSe\u00f1alan que el 6 de septiembre, un estudiante de esta casa de estudio fue agredido por personas desconocidas en las instalaciones universitaria; el incidente puso en evidencia la falta de capacitaci\u00f3n del personal de seguridad y protocolos de seguridad para hacer frente a la violencia.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-153217\" src=\"https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi3_paro_Kausir.jpg\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" srcset=\"https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi3_paro_Kausir.jpg 992w, https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi3_paro_Kausir-400x300.jpg 400w, https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi3_paro_Kausir-768x576.jpg 768w\" alt=\"\" width=\"992\" height=\"744\" \/><\/figure>\n<p>Ante estos hechos la comunidad estudiantil convoc\u00f3 a una asamblea estudiantil para analizar y tomar acuerdo de c\u00f3mo enfrentar la inseguridad en la universidad; en la discusi\u00f3n los alumnos se\u00f1alaron que las autoridades educativa no mostraron compromiso ni transparencia para resolver el problema, al contrario se negaron atender las demandas que los estudiantes les presentaron.<\/p>\n<p>La negativa de la rector\u00eda para resolver la inseguridad llev\u00f3 a los universitarios anunciaran a parar las actividades por 48 horas; este paro, es escalonada, primero habr\u00e1 un paro 24 horas, para definir propuestas, mientras esperan respuestas de las autoridades acad\u00e9micas, si no hay soluci\u00f3n pasaran otras 24 horas hasta recibir una colusi\u00f3n a su demanda.<\/p>\n<p>De acuerdo con los estudiantes, se permitir\u00e1 el \u201cacceso a laboratorios pr\u00e1cticos y experimentales, al bioterio, \u00e1reas cl\u00ednicas en hospitales y cl\u00ednicas estomatol\u00f3gicas, tomando en cuenta las necesidades espec\u00edficas de la divisi\u00f3n de Ciencias Biol\u00f3gicas y de la Salud (CBS)\u201d.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-153216\" src=\"https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi2_paro_Kausir.jpg\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" srcset=\"https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi2_paro_Kausir.jpg 992w, https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi2_paro_Kausir-400x300.jpg 400w, https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi2_paro_Kausir-768x576.jpg 768w\" alt=\"\" width=\"992\" height=\"744\" \/><\/figure>\n<p>Los universitarios condenaron los recientes hechos violentos en la universidad, y reclamaron la falta ineficacia para garantizar la seguridad; adem\u00e1s criticaron las propuestas de las autoridades educativas de usar torniquetes como medida de seguridad, porque no son las formas inadecuadas para resolver el problema seguridad.<\/p>\n<p>En el pronunciamiento que los alumnos de la casa de estudio Xochimilco pidieron que transparente los los hechos ocurridos el 6 de septiembre, y que aclare el protocolo de seguridad, as\u00ed como acompa\u00f1amiento en casos de violencia; Los colectivos de licenciaturas y posgrados mostraron apoyo al paro, y exigieron que se atiendan la problem\u00e1tica y establezcan canales efectivos de di\u00e1logo.<\/p>\n<p>Esta violencia afecta a las universidades en M\u00e9xico, los estudiantes del posgrado en Desarrollo Rural pidieron solidaridad a los movimientos estudiantiles y organizaciones sociales, demandaron cese a la criminalizaci\u00f3n y represi\u00f3n de las luchas estudiantiles. \u201cHacemos un llamado a la comunidad universitaria a la organizaci\u00f3n y articulaci\u00f3n frente a las violencias\u201d lee en el documento que circul\u00f3 en la asamblea universitaria.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-153218\" src=\"https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi4_paro_Kausir.jpg\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" srcset=\"https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi4_paro_Kausir.jpg 992w, https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi4_paro_Kausir-400x300.jpg 400w, https:\/\/piedepagina.mx\/wp-content\/uploads\/2024\/09\/Uam_xochi4_paro_Kausir-768x576.jpg 768w\" alt=\"\" width=\"992\" height=\"744\" \/><\/figure>\n<p>El paro se enmarca en una serie de incidentes similares en otras instituciones educativas del pa\u00eds, como el reciente ataque a un estudiante del CCH Naucalpan por grupos porriles; los estudiantes exigieron justicia para los 43 estudiantes normalistas de Ayotzinapa desaparecidos el 26 de septiembres de 2014, en Iguala Guerrero.<\/p>\n<p>El paro de labores contin\u00faa mientras la comunidad estudiantil discute su pliego petitorio, y espera que la rector\u00eda informe su plan de seguridad; estudiantes tienen previsto levantar el paro este mi\u00e9rcoles, mientras<br \/>\nque la Rector\u00eda de Unidad anunci\u00f3 en un comunicado en su portal oficial de UAM Xochimilco, \u201cA la comunidad universitaria, la Rector\u00eda y la Secretar\u00eda de la Unidad se mantienen abiertas al di\u00e1logo para que, de manera colectiva y a trav\u00e9s de los canales institucionales, se desarrollen e implementen las acciones que nos generen mejores condiciones de seguridad\u201d.<\/p>\n<p><a href=\"https:\/\/piedepagina.mx\/estudiantes-de-la-uam-xochimilco-se-van-a-paro-academico-por-inseguridad\/#:~:text=Estudiantes%20de%20la%20UAM%2DXochimilco%20se%20van%20a%20paro%20acad%C3%A9mico%20por%20inseguridad,-10%20septiembre%2C%202024&amp;text=estudiantil.&amp;text=personal%20de%20seguridad%20y%20protocolos,hacer%20frente%20a%20la%20violencia.&amp;text=se%20negaron%20atender%20las%20demandas%20que%20los%20estudiantes%20les%20presentaron.\" target=\"_blank\" rel=\"noopener\">https:\/\/piedepagina.mx\/estudiantes-de-la-uam-xochimilco-se-van-a-paro-academico-por-inseguridad\/#:~:text=Estudiantes%20de%20la%20UAM%2DXochimilco%20se%20van%20a%20paro%20acad%C3%A9mico%20por%20inseguridad,-10%20septiembre%2C%202024&amp;text=estudiantil.&amp;text=personal%20de%20seguridad%20y%20protocolos,hacer%20frente%20a%20la%20violencia.&amp;text=se%20negaron%20atender%20las%20demandas%20que%20los%20estudiantes%20les%20presentaron.<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>10 septiembre, 2024 Texto: Kau Sirenio Foto: Manuel Ta Safi Pie de P\u00e1gina La negativa de la rector\u00eda para resolver la inseguridad llev\u00f3 a los universitarios anunciaran a parar las &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2024\/09\/10\/estudiantes-de-la-uam-xochimilco-se-van-a-paro-academico-por-inseguridad-ciudad-de-mexico\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":69665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,14,916,2958,2150,1670,2065,2,83,1823],"tags":[2953],"class_list":["post-69664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-ciudad-de-mexico","category-privatizacion-del-la-educacion-publica","category-crisis-de-la-educacion-publica-en-la-ciudad-de-mexico","category-movilizaciones-en-la-universidad-autonoma-metropolitana","category-movilizaciones-y-protestas-de-estudiantes-de-la-ciudad-de-mexico","category-movilizaciones-y-protestas-de-habitantes-de-la-ciudad-de-mexico","category-noticias-nacionales","category-temas-nacionales","category-violencia-contra-estudiantes","tag-protestas-de-estudiantes","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2024\/09\/Estudiantes-de-la-UAM-Xochimilco-se-van-a-paro-academico-por-inseguridad.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-i7C","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":43996,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/02\/06\/entregan-cch-vallejo-tras-dos-dias-de-paro-ciudad-de-mexico\/","url_meta":{"origin":69664,"position":0},"title":"Entregan CCH Vallejo tras dos d\u00edas de paro (Ciudad de M\u00e9xico)","author":"grieta","date":"6 febrero, 2020","format":false,"excerpt":"El martes pasado, un grupo de alumnos decidi\u00f3 realizar un paro de labores. Foto: Cuartoscuro\/Archivo Notimex Las actividades acad\u00e9micas y administrativas se reanudar\u00e1n ma\u00f1ana viernes 7 en los horarios acostumbrados CIUDAD DE M\u00c9XICO. La Universidad Nacional Aut\u00f3noma de M\u00e9xico inform\u00f3 que esta tarde fueron entregadas a las autoridades las instalaciones\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Entregan-CCH-Vallejo-tras-dos-d%C3%ADas-de-paro-cdmx-feb.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Entregan-CCH-Vallejo-tras-dos-d%C3%ADas-de-paro-cdmx-feb.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Entregan-CCH-Vallejo-tras-dos-d%C3%ADas-de-paro-cdmx-feb.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":43859,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/01\/31\/por-violencia-sexual-y-criminalizacion-paro-de-actividades-en-siete-escuelas-de-la-unam-ciudad-de-mexico\/","url_meta":{"origin":69664,"position":1},"title":"Por violencia sexual y criminalizaci\u00f3n, paro de actividades en siete escuelas de la UNAM (Ciudad de M\u00e9xico)","author":"grieta","date":"31 enero, 2020","format":false,"excerpt":"Contral\u00ednea Cuatro escuelas de la Universidad Nacional Aut\u00f3noma de M\u00e9xico se sumaron a los paros de actividades en demanda de soluci\u00f3n a la violencia sexual de g\u00e9nero que se padece en los recintos universitarios y del cese a la criminalizaci\u00f3n contra el movimiento feminista que reivindica el derecho de las\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Por-violencia-sexual-y-criminalizaci%C3%B3n-paro-de-actividades-en-siete-escuelas-de-la-UNAM-cdmx-ene.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Por-violencia-sexual-y-criminalizaci%C3%B3n-paro-de-actividades-en-siete-escuelas-de-la-UNAM-cdmx-ene.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Por-violencia-sexual-y-criminalizaci%C3%B3n-paro-de-actividades-en-siete-escuelas-de-la-UNAM-cdmx-ene.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16846,"url":"https:\/\/www.grieta.org.mx\/index.php\/2016\/07\/22\/lucha-en-la-universidad-autonoma-metropolitana-por-mejores-condiciones-escolares\/","url_meta":{"origin":69664,"position":2},"title":"Lucha en la Universidad Aut\u00f3noma Metropolitana por mejores condiciones escolares","author":"grieta","date":"22 julio, 2016","format":false,"excerpt":"21\/07\/16. Estudiantes de la UAM anuncian movilizaci\u00f3n tras cerraz\u00f3n al di\u00e1logoSomos el medio 18\/07\/16. \u201c\u00bfA qu\u00e9 le temen los rectores?\u201d: estudiantes de la UAM Somos el medio 16\/07\/16. Estudiantes de la UAM reiteran propuesta de di\u00e1logo La Jornada 15\/07\/16. El silencio otorga: Rectora de UAM Xochimilco se niega a\u00a0dialogar Osmosis\u2026","rel":"","context":"En &quot;Ciudad de M\u00e9xico&quot;","block_context":{"text":"Ciudad de M\u00e9xico","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/ciudad-de-mexico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":41113,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/11\/13\/prepa-9-continua-en-paro-regresarian-a-clases-el-viernes-ciudad-de-mexico\/","url_meta":{"origin":69664,"position":3},"title":"Prepa 9 contin\u00faa en paro, regresar\u00edan a clases el viernes (Ciudad de M\u00e9xico)","author":"grieta","date":"13 noviembre, 2019","format":false,"excerpt":"Foto tomada de @Comunidad_UNAM Excelsior Por segundo d\u00eda consecutivo, un grupo de estudiantes mantiene cerrado el plantel ubicado en Insurgentes Norte 1698, colonia Lindavista CIUDAD DE M\u00c9XICO Alumnos de la Escuela Nacional Preparatoria n\u00famero 9 contin\u00faan este mi\u00e9rcoles el paro estudiantil para exigir que termine la violencia de g\u00e9nero en\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/Prepa-9-contin%C3%BAa-en-paro-regresar%C3%ADan-a-clases-el-viernes-cdmx-nov.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/Prepa-9-contin%C3%BAa-en-paro-regresar%C3%ADan-a-clases-el-viernes-cdmx-nov.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/Prepa-9-contin%C3%BAa-en-paro-regresar%C3%ADan-a-clases-el-viernes-cdmx-nov.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":40137,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/10\/11\/alumnos-de-la-unam-marchan-contra-violencia-de-genero-y-porros-ciudad-de-mexico\/","url_meta":{"origin":69664,"position":4},"title":"Alumnos de la UNAM marchan contra violencia de g\u00e9nero y porros (Ciudad de M\u00e9xico)","author":"grieta","date":"11 octubre, 2019","format":false,"excerpt":"El Heraldo de M\u00e9xico La movilizaci\u00f3n de estudiantes recorri\u00f3 algunas de las facultades de la Universidad Nacional, para posteriormente desplazarse sobre avenida Insurgentes Sur Estudiantes de la Facultad de Ciencias Pol\u00edticas y Sociales de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) realizaron este viernes una marcha en contra de la\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/10\/Alumnos-de-la-UNAM-marchan-contra-violencia-de-g%C3%A9nero-y-porros-oct-cdmx.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/10\/Alumnos-de-la-UNAM-marchan-contra-violencia-de-g%C3%A9nero-y-porros-oct-cdmx.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/10\/Alumnos-de-la-UNAM-marchan-contra-violencia-de-g%C3%A9nero-y-porros-oct-cdmx.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":44010,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/02\/06\/cecyt-7-del-ipn-analiza-realizar-paro-indefinido-ciudad-de-mexico\/","url_meta":{"origin":69664,"position":5},"title":"CECyT 7 del IPN analiza realizar paro indefinido (Ciudad de M\u00e9xico)","author":"grieta","date":"6 febrero, 2020","format":false,"excerpt":"Alumnos en Cecyt 7 del IPN. (Tomada de Rene Garc\u00eda) Selene Flores \/ Milenio En su pliego petitorio los alumnos del Centro de Estudios Cient\u00edficos y Tecnol\u00f3gicos (CECyT) 7 \u201cCuauht\u00e9moc\u201d, exigen entre otras cosas, el reabastecimiento de materiales de cada una de las especialidades t\u00e9cnicas y de los laboratorios de\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/CECyT-7-del-IPN-analiza-realizar-paro-indefinido-cdmx-feb.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/CECyT-7-del-IPN-analiza-realizar-paro-indefinido-cdmx-feb.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/CECyT-7-del-IPN-analiza-realizar-paro-indefinido-cdmx-feb.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/CECyT-7-del-IPN-analiza-realizar-paro-indefinido-cdmx-feb.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/69664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=69664"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/69664\/revisions"}],"predecessor-version":[{"id":69667,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/69664\/revisions\/69667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/69665"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=69664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=69664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=69664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}