{"id":69170,"date":"2024-06-10T06:28:04","date_gmt":"2024-06-10T12:28:04","guid":{"rendered":"https:\/\/www.grieta.org.mx\/?p=69170"},"modified":"2024-06-17T06:44:22","modified_gmt":"2024-06-17T12:44:22","slug":"personal-del-issste-cierra-calles-y-exige-mejores-condiciones-laborales-yucatan","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2024\/06\/10\/personal-del-issste-cierra-calles-y-exige-mejores-condiciones-laborales-yucatan\/","title":{"rendered":"Personal del ISSSTE cierra calles y exige mejores condiciones laborales (Yucat\u00e1n)"},"content":{"rendered":"<p>Reporteros Hoy <\/p>\n<p>Desde temprana hora de este lunes, trabajadores de la salud del ISSSTE cerraron la avenida Alfredo Barrera en el fraccionamiento Pensiones, para exigir al gobierno mejores condiciones laborales y denunciar presunta corrupci\u00f3n y desv\u00edo de recursos por parte del titular del Hospital Regional Elvia Carrillo Puerto.<\/p>\n<p>Entre los manifestantes se encuentran m\u00e9dicos suplentes, camilleros, enfermeros y personal administrativo, quienes piden pagos regularizados y el reconocimiento de la antig\u00fcedad laborada, demandas que aseguran no han sido atendidas.<\/p>\n<p>Portando pancartas, los trabajadores hicieron un llamado para que sus peticiones sean tomadas en cuenta. Advirtieron que, de no ser escuchados, permanecer\u00e1n bloqueando las calles, lo que ha generado un considerable caos vial en la zona.<\/p>\n<p>ACOM<\/p>\n<p><a href=\"https:\/\/reporteroshoy.mx\/noticias\/personal-del-issste-cierra-calles-y-exige-mejores-condiciones-laborales\/\" rel=\"noopener\" target=\"_blank\">https:\/\/reporteroshoy.mx\/noticias\/personal-del-issste-cierra-calles-y-exige-mejores-condiciones-laborales\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reporteros Hoy Desde temprana hora de este lunes, trabajadores de la salud del ISSSTE cerraron la avenida Alfredo Barrera en el fraccionamiento Pensiones, para exigir al gobierno mejores condiciones laborales &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2024\/06\/10\/personal-del-issste-cierra-calles-y-exige-mejores-condiciones-laborales-yucatan\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":69171,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,1072,918,910,2,3211,83,36],"tags":[634,2102,2367,2463,2841,492,3789],"class_list":["post-69170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-conflictos-laborales-en-yucatan","category-privatizacion-del-sector-salud","category-explotacion-y-precariedad-laboral","category-noticias-nacionales","category-precariedad-laboral-en-yucatan","category-temas-nacionales","category-yucatan","tag-condiciones-laborales","tag-conflicto-laboral","tag-crisis-en-el-sector-salud","tag-demandas-laborales","tag-explotacion-y-precariedad-laboral","tag-issste","tag-protestas-de-trabajadores-de-la-salud","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2024\/06\/Issste-e1718627953463.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-hZE","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":68576,"url":"https:\/\/www.grieta.org.mx\/index.php\/2024\/03\/04\/denuncian-corrupcion-en-asignacion-de-plazas-en-el-issste-yucatan\/","url_meta":{"origin":69170,"position":0},"title":"Denuncian corrupci\u00f3n en asignaci\u00f3n de plazas en el ISSSTE (Yucat\u00e1n)","author":"grieta","date":"4 marzo, 2024","format":false,"excerpt":"Alejandro Rubalcaba \/ Desde el Balc\u00f3n Empleados suplentes exigen certidumbre laboral y pago de sus quincenas M\u00e9rida, Yucat\u00e1n, a 4 de marzo de 2024.- Este lunes, personal m\u00e9dico y de enfermer\u00eda del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE) en Yucat\u00e1n exigieron su incorporaci\u00f3n a\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/Issste-1-e1709580215754.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/Issste-1-e1709580215754.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/Issste-1-e1709580215754.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/Issste-1-e1709580215754.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":68573,"url":"https:\/\/www.grieta.org.mx\/index.php\/2024\/02\/12\/trabajadores-del-issste-denuncian-falta-de-transparencia-en-asignacion-de-plazas-yucatan\/","url_meta":{"origin":69170,"position":1},"title":"Trabajadores del ISSSTE denuncian falta de transparencia en asignaci\u00f3n de plazas (Yucat\u00e1n)","author":"grieta","date":"12 febrero, 2024","format":false,"excerpt":"Paloma Reyes \/ Haz Ruido Protestaron en el hospital de Susul\u00e1 debido a que se otorgaron plazas sin boletinar a sindicalizados que llevaban tiempo en la bolsa de trabajo. M\u00e9rida, Yucat\u00e1n, 12 de febrero de 2024.-Trabajadores sindicalizados del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE)\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/issste-e1709578753364.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/issste-e1709578753364.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/issste-e1709578753364.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/issste-e1709578753364.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":71828,"url":"https:\/\/www.grieta.org.mx\/index.php\/2025\/06\/10\/ahora-la-utm-se-une-al-paro-yucatan\/","url_meta":{"origin":69170,"position":2},"title":"Ahora la UTM se une al paro (Yucat\u00e1n)","author":"grieta","date":"10 junio, 2025","format":false,"excerpt":"Herbeth Escalante \/ Haz Ruido Los docentes y el personal administrativo exigen mejores condiciones laborales y mejorar la infraestructura para sus estudiantes M\u00e9rida, Yucat\u00e1n, 10 de junio de 2025.- Desde temprana hora, docentes y personal administrativo cerraron con candados las rejas de las instalaciones de la Universidad Tecnol\u00f3gica Metropolitana (UTM)\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/06\/Utm-e1749645096482.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/06\/Utm-e1749645096482.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/06\/Utm-e1749645096482.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/06\/Utm-e1749645096482.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":69834,"url":"https:\/\/www.grieta.org.mx\/index.php\/2024\/09\/24\/anuncian-paro-laboral-en-diversas-universidades-de-yucatan-por-derechos-laborales\/","url_meta":{"origin":69170,"position":3},"title":"Anuncian Paro Laboral en Diversas Universidades de Yucat\u00e1n por Derechos Laborales","author":"grieta","date":"24 septiembre, 2024","format":false,"excerpt":"Erick Mart\u00edn Huh\/CAMBIO 22 Instituciones de educaci\u00f3n superior en el estado se preparan para suspender actividades el pr\u00f3ximo viernes en demanda de mejoras laborales VALLADOLID, YUCAT\u00c1N, 24 DE SEPTIEMBRE DE 2024.Diversas universidades de Yucat\u00e1n, incluidas el Tecnol\u00f3gico Superior Campus Valladolid, la Universidad Tecnol\u00f3gica Metropolitana de M\u00e9rida y la Universidad Tecnol\u00f3gica\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/09\/UniversidadesYucatan-e1727230420440.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/09\/UniversidadesYucatan-e1727230420440.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/09\/UniversidadesYucatan-e1727230420440.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/09\/UniversidadesYucatan-e1727230420440.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":68778,"url":"https:\/\/www.grieta.org.mx\/index.php\/2024\/04\/05\/no-estan-conformes-con-solo-3-meses-de-contrato-yucatan\/","url_meta":{"origin":69170,"position":4},"title":"No est\u00e1n conformes con s\u00f3lo 3 meses de contrato (Yucat\u00e1n)","author":"grieta","date":"5 abril, 2024","format":false,"excerpt":"Haz Ruido \u201cAntes h\u00e9roes, ahora desempleados\u201d, exclamaron trabajadores de la salud que protestaron en Yucat\u00e1n, porque a\u00fan no les asignan plazas. Tambi\u00e9n piden que no se politicen sus demandas. M\u00e9rida, Yucat\u00e1n, 5 de abril de 2024.- Trabajadoras y trabajadores de salud que pertenecen al IMSS-Bienestar volvieron a protestar en la\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/AntesHeroes-e1712339198125.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/AntesHeroes-e1712339198125.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/AntesHeroes-e1712339198125.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/AntesHeroes-e1712339198125.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":70958,"url":"https:\/\/www.grieta.org.mx\/index.php\/2025\/02\/07\/crisis-en-el-hospital-de-alta-especialidad-yucatan\/","url_meta":{"origin":69170,"position":5},"title":"Crisis en el hospital de alta especialidad (Yucat\u00e1n)","author":"grieta","date":"7 febrero, 2025","format":false,"excerpt":"Redacci\u00f3n\/Sol Yucat\u00e1n El martes pasado fueron colocadas mantas y pancartas en el Hospital Regional de Alta Especialidad de la Pen\u00ednsula de Yucat\u00e1n (HRAEPY) por parte de trabajadores de este nosocomio en el norte de M\u00e9rida quienes denunciaron la falta de medicamentos e insumos hospitalarios que se agudiz\u00f3 con la incorporaci\u00f3n\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/02\/Crisis-e1739408837835.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/02\/Crisis-e1739408837835.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/02\/Crisis-e1739408837835.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/02\/Crisis-e1739408837835.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/69170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=69170"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/69170\/revisions"}],"predecessor-version":[{"id":69172,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/69170\/revisions\/69172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/69171"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=69170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=69170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=69170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}