{"id":64929,"date":"2022-08-23T20:49:46","date_gmt":"2022-08-24T01:49:46","guid":{"rendered":"https:\/\/www.grieta.org.mx\/?p=64929"},"modified":"2022-08-23T20:49:46","modified_gmt":"2022-08-24T01:49:46","slug":"ninos-de-la-calle-entre-violencia-e-invisibilidad-para-el-gobierno-ciudad-de-mexico","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2022\/08\/23\/ninos-de-la-calle-entre-violencia-e-invisibilidad-para-el-gobierno-ciudad-de-mexico\/","title":{"rendered":"Ni\u00f1os de la calle, entre violencia e invisibilidad para el gobierno (Ciudad de M\u00e9xico)"},"content":{"rendered":"<p>Frida S\u00e1nchez \/ LaRaz\u00f3n<\/p>\n<p><strong>Comunidades est\u00e1n concentradas principalmente en tres alcald\u00edas; sufren odio, carencias y retraso en su desarrollo cognitivo, dice Luis Enrique Hern\u00e1ndez, activista social<\/strong><\/p>\n<p>Cleo y G\u00edo, de diez y siete a\u00f1os, respectivamente, son dos peque\u00f1os que a su corta edad ya se han enfrentado a una de las realidades m\u00e1s complicadas para los habitantes de cualquier urbe: vivir en las calles, un fen\u00f3meno que se presenta principalmente en tres alcald\u00edas: Cuauht\u00e9moc, Gustavo A. Madero y Venustiano Carranza.<\/p>\n<p id=\"m96-95-97\" class=\"paragraph con \">En el cruce entre Eje 1 Poniente y Puente de Alvarado, en la colonia Buenavista, las cobijas y colchonetas colocadas en la acera ya son parte del paisaje.<\/p>\n<p id=\"m101-100-102\" class=\"paragraph con \">Aqu\u00ed mismo, justo a las afueras del Metro Hidalgo, donde cientos de capitalinos transitan cada d\u00eda, hace cuatro meses fue hallado el cuerpo de un hombre de 70 a\u00f1os de edad que perdi\u00f3 la vida en la v\u00eda p\u00fablica, a la vista de todos.<\/p>\n<p id=\"m111-110-112\" class=\"paragraph con \">En esta esquina es donde estos hermanos, cuyos nombres fueron cambiados para proteger su identidad, comen, juegan y hacen su vida. Cleo, la mayor, est\u00e1 en una edad de muchos cambios y se enfrenta a su primer periodo menstrual. El peque\u00f1o G\u00edo va a pasar a tercer a\u00f1o de primaria, pero a\u00fan le cuesta trabajo leer.<\/p>\n<p id=\"m116-115-117\" class=\"paragraph con \">Ellos, al igual que los miles de menores que viven en estas condiciones en la Ciudad de M\u00e9xico, son invisibles para la sociedad y para las autoridades.<\/p>\n<p id=\"m121-120-122\" class=\"paragraph con \">Los ni\u00f1os que viven en las calles se enfrentan a un sinf\u00edn de problemas que hacen del suyo un entorno hostil, dice a La Raz\u00f3n Luis Enrique Hern\u00e1ndez, director de la organizaci\u00f3n civil El Caracol, la cual tiene m\u00e1s de 25 a\u00f1os de trabajo con menores en situaci\u00f3n de calle.<\/p>\n<p id=\"m126-125-127\" class=\"paragraph con \">Sufren odio, carencias, violencia, falta de cobertura de sus necesidades b\u00e1sicas, estigma y discriminaci\u00f3n de parte de la sociedad y de las autoridades, quienes los culpan de delitos que no cometen, los desalojan \u201cpensando que afean el entorno urbano\u201d o los institucionalizan a la fuerza, afirma el experto.<\/p>\n<p id=\"m136-135-137\" class=\"paragraph con \">Luis Enrique explica: \u201cEstos ni\u00f1os que van creciendo en la calle se enfrentan a un retraso en su desarrollo cognitivo de hasta dos a\u00f1os. Un beb\u00e9 que nace en la calle, cuando tenga cuatro a\u00f1os es probable que todav\u00eda tenga un desarrollo como de alguien de dos\u201d.<\/p>\n<p id=\"m141-140-142\" class=\"paragraph con \">Acusa que antes de dar alternativas a las j\u00f3venes que se embarazan en la calle, quienes no cuentan con documentaci\u00f3n, el Estado les retira a sus hijos.<\/p>\n<p id=\"m146-145-147\" class=\"paragraph con \">A\u00f1ade: \u201cLa pol\u00edtica que existe antes de ofrecerle a la mam\u00e1 una alternativa de protecci\u00f3n o desarrollo es decirle: usted no es apta e atender a este beb\u00e9\u201d.<\/p>\n<p id=\"m151-150-152\" class=\"paragraph con \">En las calles, las din\u00e1micas familiares y lo moralmente correcto cambian por completo. Cleo y G\u00edo viven con su madre \u2014aunque no lo sea biol\u00f3gicamente del var\u00f3n\u2014 de 31 a\u00f1os, y su padre, un hombre que se gana la vida limpiando parabrisas y que nunca ha tenido un hogar.<\/p>\n<p id=\"m156-155-157\" class=\"paragraph con \">Ellos conforman lo que se conoce como una \u201cfamilia de calle\u201d, es decir, gente que no necesariamente son parientes de sangre, pero que en las calles cumplen estos roles.<\/p>\n<p id=\"m161-160-162\" class=\"paragraph con \">La menor Cleo s\u00ed lleva los apellidos de su madre, pero el peque\u00f1o G\u00edo no, pues se uni\u00f3 a esta familia tras el abandono de su padre biol\u00f3gico, cuyo nombre es impronunciable para \u00e9l.<\/p>\n<h2 id=\"m166-165-167\" class=\"encabezado2 \">El \u00faltimo recuento fue hace cinco a\u00f1os<\/h2>\n<p id=\"m171-170-172\" class=\"paragraph con \">Uno de los vac\u00edos que existen en la Ciudad de M\u00e9xico referente a las poblaciones de la calle, es la falta de censos que permitan tener conocimiento de la cantidad de peque\u00f1os que viven en estas condiciones.<\/p>\n<p id=\"m176-175-177\" class=\"paragraph con \">De acuerdo con el Censo de Poblaciones Callejeras de 2017, el \u00faltimo conteo que se ha hecho al respecto, hasta ese a\u00f1o en la ciudad hab\u00eda unas seis mil 754 personas en situaci\u00f3n de calle, la mayor\u00eda concentrada en \u00fanicamente tres de las 16 alcald\u00edas. De esa cifra, 11.26 por ciento correspond\u00eda a ni\u00f1as y ni\u00f1os. Es decir, hasta hace un lustro se estimaba que en la capital hab\u00eda unos 760 menores de edad en esta circunstancia.<\/p>\n<p id=\"m181-180-182\" class=\"paragraph con \">Sin embargo, para 2020, con motivo de realizar un diagn\u00f3stico ante la pandemia de Covid-19 y sus alcances en esta poblaci\u00f3n, la Secretar\u00eda de Inclusi\u00f3n y Bienestar Social (Sibiso) afirm\u00f3 que para marzo de ese a\u00f1o sumaban mil 226 personas en situaci\u00f3n de calle en la ciudad, cifra que baj\u00f3 a 932 personas para diciembre de ese a\u00f1o.<\/p>\n<p id=\"m186-185-187\" class=\"paragraph con \">Mientras G\u00edo corretea a uno de sus dos perros \u2014dos animales que duermen arriba de las instalaciones del Metro\u2014, su madre afirma a este medio que a ella le gustar\u00eda que sus hijos tuvieran una vida \u201cmuy diferente\u201d a la que ella experiment\u00f3 en su ni\u00f1ez.<\/p>\n<p id=\"m191-190-192\" class=\"paragraph con \">Aunque se trata de una mujer de edad joven, ya ha sufrido mucho en su vida. Dej\u00f3 a su madre a los 15 a\u00f1os, despu\u00e9s de soportar malos tratos y falta de cuidados.<\/p>\n<p id=\"m196-195-197\" class=\"paragraph con \">\u201cMi vida no ha sido muy buena, yo trabaj\u00e9 desde los cinco a\u00f1os, mi mam\u00e1 tomaba mucho, cri\u00e9 a mi carnal, pr\u00e1cticamente no tuve ni\u00f1ez, toda mi vida fue trabajar, cuidar a mi hermano, ya despu\u00e9s me sal\u00ed de mi casa, dije: en vez de mantener a mi jefa y la vida que estoy viviendo, mejor voy a tener hijos\u201d, explica.<\/p>\n<p id=\"m201-200-202\" class=\"paragraph con \">Para ella, lo m\u00e1s dif\u00edcil de vivir en la calle ha sido aprender a ser madre y lidiar con el temor de que le quiten a uno de sus hijos, pues asegura que las autoridades ya le retiraron al m\u00e1s peque\u00f1o G\u00edo en una ocasi\u00f3n.<\/p>\n<p id=\"m206-205-207\" class=\"paragraph con \">\u201cYo he vivido toda mi vida en la calle, no soy una persona de respeto, soy una chava de la calle, aqu\u00ed es pura bandita, no como en un hogar\u201d, explic\u00f3.<\/p>\n<p><a href=\"https:\/\/www.razon.com.mx\/ciudad\/ninos-calle-violencia-e-invisibilidad-gobierno-495319\" target=\"_blank\" rel=\"noopener\">https:\/\/www.razon.com.mx\/ciudad\/ninos-calle-violencia-e-invisibilidad-gobierno-495319<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frida S\u00e1nchez \/ LaRaz\u00f3n Comunidades est\u00e1n concentradas principalmente en tres alcald\u00edas; sufren odio, carencias y retraso en su desarrollo cognitivo, dice Luis Enrique Hern\u00e1ndez, activista social Cleo y G\u00edo, de &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2022\/08\/23\/ninos-de-la-calle-entre-violencia-e-invisibilidad-para-el-gobierno-ciudad-de-mexico\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":21928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,1819,1827,2,2797,83],"tags":[],"class_list":["post-64929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad-de-mexico","category-la-ninez-bajo-la-tormenta-capitalista-en-la-ciudad-de-mexico","category-la-ninez-en-la-tormenta-capitalista","category-noticias-nacionales","category-pobreza-en-la-ciudad-de-mexico","category-temas-nacionales","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-gTf","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":43667,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/01\/28\/padres-de-ninos-con-cancer-exigiran-informacion-de-compra-de-medicamentos-ciudad-de-mexico\/","url_meta":{"origin":64929,"position":0},"title":"Padres de ni\u00f1os con c\u00e1ncer exigir\u00e1n informaci\u00f3n de compra de medicamentos (Ciudad de M\u00e9xico)","author":"grieta","date":"28 enero, 2020","format":false,"excerpt":"Padres de ni\u00f1os enfermos de c\u00e1ncer, anunciaron que presentar\u00e1 un pliego petitorio a la Secretar\u00eda de Gobernaci\u00f3n \/ Foto Especial Nora Bucio \/ MVS Noticias Los padres incluyeron en su pliego petitorio la solicitud de fechas exactas de llegada del medicamento y saber la calidad del mencionado. Padres de ni\u00f1os\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/01\/Padres-de-ni%C3%B1os-con-c%C3%A1ncer-exigir%C3%A1n-informaci%C3%B3n-de-compra-de-medicamentos-cdmx-ene.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/01\/Padres-de-ni%C3%B1os-con-c%C3%A1ncer-exigir%C3%A1n-informaci%C3%B3n-de-compra-de-medicamentos-cdmx-ene.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/01\/Padres-de-ni%C3%B1os-con-c%C3%A1ncer-exigir%C3%A1n-informaci%C3%B3n-de-compra-de-medicamentos-cdmx-ene.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/01\/Padres-de-ni%C3%B1os-con-c%C3%A1ncer-exigir%C3%A1n-informaci%C3%B3n-de-compra-de-medicamentos-cdmx-ene.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":32792,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/04\/26\/reportan-mas-de-4-mil-menores-asesinados-en-tres-anos-en-mexico\/","url_meta":{"origin":64929,"position":1},"title":"Reportan m\u00e1s de 4 mil menores asesinados en tres a\u00f1os en M\u00e9xico","author":"grieta","date":"26 abril, 2019","format":false,"excerpt":"Lizett Ximena Mej\u00eda\/Excelsior CIUDAD DE M\u00c9XICO. Desde el 2015 hasta el d\u00eda de hoy han sido asesinados 4 mil 299 ni\u00f1os, ni\u00f1as y adolescentes en M\u00e9xico. De acuerdo con la Red por los Derechos de la Infancia en M\u00e9xico (REDIM), los homicidios aumentaron 42% en estos \u00faltimos tres a\u00f1os debido\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/05\/2137754.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":27542,"url":"https:\/\/www.grieta.org.mx\/index.php\/2018\/11\/03\/en-la-cdmx-catrinas-marchan-contra-feminicidios\/","url_meta":{"origin":64929,"position":2},"title":"En la CDMX Catrinas marchan contra feminicidios","author":"grieta","date":"3 noviembre, 2018","format":false,"excerpt":"","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-03-at-10.51.40-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-03-at-10.51.40-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-03-at-10.51.40-2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-03-at-10.51.40-2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-03-at-10.51.40-2.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":65945,"url":"https:\/\/www.grieta.org.mx\/index.php\/2022\/12\/04\/colima-entre-los-estados-mas-inseguros-para-ninas-y-adolescentes\/","url_meta":{"origin":64929,"position":3},"title":"Colima, entre los estados m\u00e1s inseguros para ni\u00f1as y adolescentes","author":"grieta","date":"4 diciembre, 2022","format":false,"excerpt":"Imagen: Diario Avanzada Heidi de Le\u00f3n Guti\u00e9rrez \/ Diario Avanzada Colima, M\u00e9xico, Avanzada (04\/12\/2022).- Colima se encuentra entre los 14 estados m\u00e1s inseguros para las ni\u00f1as y adolescentes, de acuerdo al monitoreo que realiz\u00f3 la organizaci\u00f3n: Aqu\u00ed estamos: feminicidio infantil en M\u00e9xico. El reporte fue elaborado por un grupo de\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/12\/image-25-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/12\/image-25-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/12\/image-25-1.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":45218,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/02\/25\/familiares-de-ninos-con-cancer-y-pacientes-con-vih-clausuran-palacio-nacional-ciudad-de-mexico\/","url_meta":{"origin":64929,"position":4},"title":"Familiares de ni\u00f1os con c\u00e1ncer y pacientes con VIH \u201cclausuran\u201d Palacio Nacional (Ciudad de M\u00e9xico)","author":"grieta","date":"25 febrero, 2020","format":false,"excerpt":"Los diversos contingentes formaron un grupo de 35 personas que se plantaron junto a la puerta. Foto: Daniel Ojeda Gerardo Su\u00e1rez \/ El Heraldo de M\u00e9xico Los inconformes pegaron varios sellos con la frase \"clausurado\" en la puerta central del inmueble donde despacha el Presidente Familiares de ni\u00f1os con c\u00e1ncer\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Familiares-de-ni%C3%B1os-con-c%C3%A1ncer-y-pacientes-con-VIH-clausuran-Palacio-Nacional-cdmx-feb.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Familiares-de-ni%C3%B1os-con-c%C3%A1ncer-y-pacientes-con-VIH-clausuran-Palacio-Nacional-cdmx-feb.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Familiares-de-ni%C3%B1os-con-c%C3%A1ncer-y-pacientes-con-VIH-clausuran-Palacio-Nacional-cdmx-feb.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Familiares-de-ni%C3%B1os-con-c%C3%A1ncer-y-pacientes-con-VIH-clausuran-Palacio-Nacional-cdmx-feb.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/Familiares-de-ni%C3%B1os-con-c%C3%A1ncer-y-pacientes-con-VIH-clausuran-Palacio-Nacional-cdmx-feb.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":42609,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/12\/27\/arman-colecta-de-juguetes-para-hijos-de-victimas-de-feminicidio-ciudad-de-mexico\/","url_meta":{"origin":64929,"position":5},"title":"Arman colecta de juguetes para hijos de v\u00edctimas de feminicidio (Ciudad de M\u00e9xico)","author":"grieta","date":"27 diciembre, 2019","format":false,"excerpt":"Karla Almaraz \/ Chilango Todos pueden donar juguetes o frazadas El colectivo Ni una menos M\u00e9xico organiz\u00f3 una colecta de juguetes feminista, para regalarlos a los hijos de mujeres que han sido v\u00edctimas de feminicidios. Adem\u00e1s de juguetes , las personas podr\u00e1n donar frazadas. Todo ser\u00e1 entregado a los peque\u00f1os.\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Arman-colecta-de-juguetes-para-hijos-de-v%C3%ADctimas-de-feminicidio-cdmx-dic.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/64929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=64929"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/64929\/revisions"}],"predecessor-version":[{"id":64930,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/64929\/revisions\/64930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/21928"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=64929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=64929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=64929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}