{"id":64924,"date":"2022-07-23T16:12:35","date_gmt":"2022-07-23T21:12:35","guid":{"rendered":"https:\/\/www.grieta.org.mx\/?p=64924"},"modified":"2022-08-22T16:21:04","modified_gmt":"2022-08-22T21:21:04","slug":"ambientalistas-protestan-y-son-amenazados-quintana-roo","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2022\/07\/23\/ambientalistas-protestan-y-son-amenazados-quintana-roo\/","title":{"rendered":"Ambientalistas protestan\u2026 y son amenazados (Quintana Roo)"},"content":{"rendered":"<p>Octavio Mart\u00ednez \/ Revista Proceso<\/p>\n<blockquote><p>La reanudaci\u00f3n de los trabajos del Tren Maya, en violaci\u00f3n a los mandatos judiciales, provoc\u00f3 las inmediatas protestas de organizaciones ambientalistas y promoventes de los amparos contra la obra en Quintana Roo. Se\u00f1alan que el gobernador Carlos Joaqu\u00edn ha sido omiso en proteger los recursos del estado, especialmente la selva, y acusan a la Sedena de intimidar a periodistas y activistas.<\/p><\/blockquote>\n<p>PLAYA DEL CARMEN, Q. Roo (Proceso).- Los grupos ambientalistas de Quintana Roo recibieron llamados de alerta por la reactivaci\u00f3n del desmonte de selva para el tramo 5 del Tren Maya el jueves 14, cuando a 3.5 kil\u00f3metros del centro de Tulum, en la carretera con direcci\u00f3n a la zona arqueol\u00f3gica de Cob\u00e1, maquinaria pesada comenz\u00f3 a tumbar \u00e1rboles.<\/p>\n<p>Ese mismo d\u00eda, pero en la Ruta de los Cenotes, en Puerto Morelos, a 35 kil\u00f3metros al sur de Canc\u00fan, ocurr\u00eda una situaci\u00f3n similar.<\/p>\n<p>Asimismo, trabajadores del Fonatur supervisaban con drones desde el mi\u00e9rcoles 20 un punto ubicado a 12 kil\u00f3metros del centro de Playa del Carmen, donde a finales de febrero inici\u00f3 la apertura de la brecha de selva sin permisos de impacto ambiental, lo que provoc\u00f3 protestas de organizaciones ambientalistas.<\/p>\n<p>En ese lugar, por donde se ingresa al relleno sanitario del municipio de Solidaridad, se encuentra el empalme del Tramo 5 Norte y Sur del Tren Maya en Quintana Roo. Personal de Fonatur consultado dio a conocer que la maquinaria pesada retornar\u00e1 este mes y deber\u00e1n introducirla entre los reto\u00f1os de los \u00e1rboles talados. De esa manera, las labores para concluir el proyecto sexenal prometido por Andr\u00e9s Manuel L\u00f3pez Obrador habr\u00e1n sido plenamente reactivadas, pese a las \u00f3rdenes judiciales de que fueran suspendidos.<\/p>\n<p>Las protestas fueron inmediatas en Tulum y en Playa del Carmen, por cuya selva pasar\u00e1 la mayor parte del Tramo 5. Para Jos\u00e9 Urbina Bravo, buzo espele\u00f3logo promovente del amparo indirecto 884\/2022, que cuenta con el beneficio de una suspensi\u00f3n definitiva dentro del juicio de garant\u00edas, es una muestra de que el gobierno federal no respeta los argumentos cient\u00edficos ni jur\u00eddicos para proteger la selva maya, que incluye la red de r\u00edos subterr\u00e1neos m\u00e1s extensa del mundo y corre el riesgo de colapsar con el peso del ferrocarril.<\/p>\n<p>\u201cDe la misma forma que iniciaron el proyecto de una forma turbia oponi\u00e9ndose al conocimiento cient\u00edfico y sobre la ley, lo continuaron con la presentaci\u00f3n de la pseudo MIA de Fonatur, en la que parece una confesi\u00f3n de que no conocen la zona. Como los conocimientos legales y cient\u00edficos sobrepasaron las capacidades de Fonatur, han comenzado a romper la ley con la argucia en la que se comprueba que no saben lo que est\u00e1n haciendo y persiguen un proyecto que s\u00f3lo cumple con un calendario pol\u00edtico, s\u00f3lo quieren el galard\u00f3n, la presea de que terminaron el proyecto\u201d, expone Urbina Bravo.<\/p>\n<p>Y critica al gobernador por no tener un posicionamiento de defensa del patrimonio natural: \u201cCarlos Joaqu\u00edn (Conz\u00e1lez) ha sido tremendamente sumiso, tremendamente pasivo al accionar del gobierno federal en su estado. Los da\u00f1os a su territorio son incalculables, la violentaci\u00f3n de la ley es incuestionable y \u00e9l no ha hablado por los ciudadanos que han alzado la voz por el medio ambiente ni por el territorio que ten\u00eda que proteger\u201d.<\/p>\n<p>El gobernador ha acompa\u00f1ado a L\u00f3pez Obrador en las m\u00faltiples giras de supervisi\u00f3n de las obras. Esta semana el mandatario federal dijo que no descartaba darle un lugar en su administraci\u00f3n a Joaqu\u00edn Gonz\u00e1lez una vez concluido su periodo en septiembre pr\u00f3ximo.<\/p>\n<p>Comenta Urbina Bravo: \u201cLa conclusi\u00f3n se dar\u00e1 con su trabajo en el gabinete, si vemos si contin\u00faa con esta l\u00ednea de sumisi\u00f3n sabremos que fue un premio; si propone y se\u00f1ala errores, quiz\u00e1 no sea llamado\u201d.<\/p>\n<p>Fragmento del reportaje publicado en la edici\u00f3n 2386 de la revista Proceso<\/p>\n<p><a href=\"https:\/\/www.proceso.com.mx\/reportajes\/2022\/7\/23\/ambientalistas-protestan-son-amenazados-290129.html\" rel=\"noopener\" target=\"_blank\">https:\/\/www.proceso.com.mx\/reportajes\/2022\/7\/23\/ambientalistas-protestan-son-amenazados-290129.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Octavio Mart\u00ednez \/ Revista Proceso La reanudaci\u00f3n de los trabajos del Tren Maya, en violaci\u00f3n a los mandatos judiciales, provoc\u00f3 las inmediatas protestas de organizaciones ambientalistas y promoventes de los &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2022\/07\/23\/ambientalistas-protestan-y-son-amenazados-quintana-roo\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":64925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,3,922,926,944,952,2,28,1876,2026],"tags":[2986,2987,3514,1878],"class_list":["post-64924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-megaproyectos","category-megaproyectos-estados","category-mp-campeche","category-mp-quintana-roo","category-mp-yucatan","category-noticias-nacionales","category-quintana-roo","category-resistencia-al-tren-maya-en-la-peninsula-de-yucatan-quintana-roo","category-tren-maya","tag-amenazas-a-opositores-al-tren-maya","tag-impacto-ecologico-por-tren-maya","tag-protestas-contra-tren-maya","tag-tren-maya","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/Ambientalistas-e1661203079281.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-gTa","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":68844,"url":"https:\/\/www.grieta.org.mx\/index.php\/2024\/04\/29\/ambientalistas-clausuran-las-oficinas-de-semarnat-tras-calificarla-de-ecocida-quintana-roo\/","url_meta":{"origin":64924,"position":0},"title":"Ambientalistas &#8220;clausuran&#8221; las oficinas de Semarnat tras calificarla de ecocida (Quintana Roo)","author":"grieta","date":"29 abril, 2024","format":false,"excerpt":"Leslie Gordillo \/ NOTICARIBE PENINSULAR CANC\u00daN.- Un grupo de ambientalistas, representante de diferentes organismos y asociaciones civiles, se manifestaron en la zona hotelera de Canc\u00fan y clausuraron de manera simb\u00f3lica las oficinas de la Secretar\u00eda de Medio Ambiente y Recursos Naturales (Semarnat). La denuncia es que la Semarnat ha sido\u2026","rel":"","context":"En &quot;Campeche&quot;","block_context":{"text":"Campeche","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/ambientalitas-e1715552774254.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/ambientalitas-e1715552774254.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/ambientalitas-e1715552774254.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/04\/ambientalitas-e1715552774254.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":64684,"url":"https:\/\/www.grieta.org.mx\/index.php\/2022\/08\/05\/ambientalistas-detienen-maquinaria-en-obras-del-tren-maya-quintana-roo\/","url_meta":{"origin":64924,"position":1},"title":"Ambientalistas detienen maquinaria en obras del Tren Maya (Quintana Roo)","author":"grieta","date":"5 agosto, 2022","format":false,"excerpt":"Octavio Mart\u00ednez \/ Novedades Quintana Roo Las obras del Tren Maya Tramo 5 Sur fueron detenidas temporalmente la ma\u00f1ana de ayer por ambientalistas en Akumal, tras la revocaci\u00f3n de las suspensiones definitivas otorgadas dentro de juicios de amparo. Los inconformes llegaron al desmonte de dicho poblado donde realizaron una protesta\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/TrenAmbientalistas-e1659805095576.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/TrenAmbientalistas-e1659805095576.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/TrenAmbientalistas-e1659805095576.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/TrenAmbientalistas-e1659805095576.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":68649,"url":"https:\/\/www.grieta.org.mx\/index.php\/2024\/03\/22\/con-bloqueo-a-playa-del-carmen-ambientalistas-exigen-freno-a-obras-del-tren-maya-tramo-5-sur-quintana-roo\/","url_meta":{"origin":64924,"position":2},"title":"Con bloqueo a Playa del Carmen, ambientalistas exigen freno a obras del Tren Maya tramo 5 sur (Quintana Roo)","author":"grieta","date":"22 marzo, 2024","format":false,"excerpt":"Octavio Mart\u00ednez \/ Revista Proceso PLAYA DEL CARMEN, Q. Roo (apro).- Ambientalistas y simpatizantes del colectivo S\u00e9lvame del Tren realizaron bloqueos a la carretera federal 307, que sirve de acceso a Playa del Carmen, para exigir que el gobierno federal acate la suspensi\u00f3n judicial de los trabajos del Tren Maya\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/BloqueoPlaya-e1711311550223.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/BloqueoPlaya-e1711311550223.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/BloqueoPlaya-e1711311550223.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/03\/BloqueoPlaya-e1711311550223.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":47874,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/04\/13\/las-vias-torcidas-del-tren-maya-video\/","url_meta":{"origin":64924,"position":3},"title":"Las v\u00edas torcidas del tren maya (Video)","author":"grieta","date":"13 abril, 2020","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=k8FRX9eT0YY","rel":"","context":"En &quot;16. Pueblo Maya&quot;","block_context":{"text":"16. Pueblo Maya","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/espejos-de-la-resistencia\/16-pueblo-maya\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/ViasTorcidasTrenMaya.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/ViasTorcidasTrenMaya.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/ViasTorcidasTrenMaya.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/ViasTorcidasTrenMaya.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":70639,"url":"https:\/\/www.grieta.org.mx\/index.php\/2024\/12\/07\/contrato-del-tren-maya-contra-jaguares-venados-y-tapires-desata-indignacion-entre-ambientalistas\/","url_meta":{"origin":64924,"position":4},"title":"Contrato del Tren Maya contra jaguares, venados y tapires desata indignaci\u00f3n entre ambientalistas","author":"grieta","date":"7 diciembre, 2024","format":false,"excerpt":"Octavio Mart\u00ednez \/ Revista Proceso Tras revelarse la asignaci\u00f3n de un contrato de la empresa Tren Maya, que califica a jaguares y venados, entre otros animales, como fauna nociva para el proyecto, organizaciones ambientalistas se manifestaron en Quintana Roo y Ciudad de M\u00e9xico contra la designaci\u00f3n. PLAYA DEL CARMEN, Q.\u2026","rel":"","context":"En &quot;Campeche&quot;","block_context":{"text":"Campeche","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/12\/Fauna-e1733709245363.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/12\/Fauna-e1733709245363.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/12\/Fauna-e1733709245363.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2024\/12\/Fauna-e1733709245363.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35945,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/05\/expansion-de-megaproyectos-en-la-peninsula-de-yucatan-video\/","url_meta":{"origin":64924,"position":5},"title":"Expansi\u00f3n de Megaproyectos en la Pen\u00ednsula de Yucat\u00e1n (Video)","author":"grieta","date":"5 julio, 2019","format":false,"excerpt":"https:\/\/youtu.be\/qLBARIAaBsI","rel":"","context":"En &quot;Campeche&quot;","block_context":{"text":"Campeche","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/qLBARIAaBsI\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/64924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=64924"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/64924\/revisions"}],"predecessor-version":[{"id":64926,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/64924\/revisions\/64926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/64925"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=64924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=64924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=64924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}