{"id":54778,"date":"2020-11-03T12:34:47","date_gmt":"2020-11-03T18:34:47","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=54778"},"modified":"2020-11-07T12:50:58","modified_gmt":"2020-11-07T18:50:58","slug":"exigen-pobladores-de-san-blas-mejores-servicios-medicos-nayarit","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2020\/11\/03\/exigen-pobladores-de-san-blas-mejores-servicios-medicos-nayarit\/","title":{"rendered":"Exigen pobladores de San Blas mejores servicios m\u00e9dicos (Nayarit)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"54779\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2020\/11\/03\/exigen-pobladores-de-san-blas-mejores-servicios-medicos-nayarit\/1604446763_1604437982_manifestantes\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes.jpg\" data-orig-size=\"800,543\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1604446763_1604437982_manifestantes\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes-300x204.jpg\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes.jpg\" class=\"size-full wp-image-54779 aligncenter\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes.jpg\" alt=\"\" width=\"800\" height=\"543\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes.jpg 800w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes-300x204.jpg 300w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes-768x521.jpg 768w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes-737x500.jpg 737w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Foto: Meridiano.mx<\/p>\n<p>Fernando P\u00e9rez Ulloa-Misael Ulloa Isiordia \/ Meridiano.mx<\/p>\n<p>Esta ma\u00f1ana de martes un reducido grupo de hombres y mujeres originarios del municipio de San Blas, se manifestaron en las calles de Tepic para exigirles a las autoridades correspondientes un mejor servicio de salud en los diferentes poblados de esta cabecera municipal.<\/p>\n<p>Al respecto, la profesora Loiza L\u00f3pez, dio a conocer que a pesar de que en este poblado de Jalcocotan existe una cl\u00ednica de salud no se est\u00e1n atendiendo a los pacientes porque no se cuenta con los insumos necesarios: \u201csolicitado el apoyo para que nos volteen a ver referente a la salud, a la salud en Jalcocot\u00e1n porque ah\u00ed se construyo una cl\u00ednica con la finalidad de que de desahogaran todas las comunidades de alrededor y desahogar aqu\u00ed el Hospital Central, tristemente est\u00e1 la cl\u00ednica, nuestro respeto para todo el personal m\u00e9dico que labora ah\u00ed, pero si es necesario que le inviertan recursos, por ejemplo al \u00e1rea de toco cirug\u00eda para que se realicen partos, cesar\u00edas y cirug\u00edas de urgencia, los tanques de oxigeno est\u00e1n llenos pero se ocupan los empotrados para que funcionen la aspiraci\u00f3n de aire, m\u00e1s medicamento y que funcione el laboratorio que funcione para que la gente humilde no tenga que trasladarse aqu\u00ed a Tepic, si no que ah\u00ed mismo se atiendan las urgencias, la ambulancia es muy importante adem\u00e1s del m\u00e9dico pediatra, ginec\u00f3logo, anestesi\u00f3logo\u201d.<\/p>\n<p>Es importante destacar, que la entrevistada se hacia acompa\u00f1ar por vecinos del poblado de Mecat\u00e1n y de Huaristemba, quienes al igual que los pobladores de Jalcocot\u00e1n carecen de atenci\u00f3n y de buenos servicios m\u00e9dicos: \u201cse ocupan m\u00e9dicos las 24 horas en Huaristemba, Pintade\u00f1o, Huaynamota, Jos\u00e9 Mar\u00eda Mercado, Reforma Agraria, de igual manera el pueblo esta olvidado y siempre hemos dicho la salud es muy importante porque somos seres humanos, pero no hay eco en nuestras palabras\u201d.<\/p>\n<p>Por lo expuesto, la profesora envi\u00f3 un mensaje al gobernador del estado, Antonio Echevarr\u00eda Garc\u00eda: \u201cal Gobernador del Estado, pues que voltee a ver no nada m\u00e1s al municipio de San Blas creo que esta problem\u00e1tica est\u00e1 en todo el Estado de Nayarit y si nos da tristeza que mucha gente se ha muerto por falta de medicamentos, por falta de ambulancia o por los medios necesarios que los m\u00e9dicos hacen hasta lo imposible que est\u00e1n laborando no puedan abordar o atender y tristemente gente ha fallecido, queremos decirle a las autoridades correspondiente que nos atiendan, que acudan y nos den respuesta a esta llamado urgente\u201d.<\/p>\n<p><a href=\"https:\/\/meridiano.mx\/seccion\/Nayarit\/65785\/exigen-pobladores-de-san-blas-mejores-servicios-m_dicos\">https:\/\/meridiano.mx\/seccion\/Nayarit\/65785\/exigen-pobladores-de-san-blas-mejores-servicios-m_dicos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Meridiano.mx Fernando P\u00e9rez Ulloa-Misael Ulloa Isiordia \/ Meridiano.mx Esta ma\u00f1ana de martes un reducido grupo de hombres y mujeres originarios del municipio de San Blas, se manifestaron en las &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2020\/11\/03\/exigen-pobladores-de-san-blas-mejores-servicios-medicos-nayarit\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":54779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,918,2573,23,2,83],"tags":[3133,2367,1718,3134,3284,3206,1596],"class_list":["post-54778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-privatizacion-del-sector-salud","category-crisis-del-sector-salud-en-nayarit","category-nayarit","category-noticias-nacionales","category-temas-nacionales","tag-crisis-del-sector-salud","tag-crisis-en-el-sector-salud","tag-desprecio-contra-indigenas","tag-falta-de-atencion-medica","tag-falta-de-insumos-en-hospitales","tag-protestas-pueblos-indigenas","tag-pueblos-originarios","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604446763_1604437982_manifestantes.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-efw","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":47189,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/04\/01\/protesta-personal-de-la-secretaria-de-salud-nayarit\/","url_meta":{"origin":54778,"position":0},"title":"Protesta personal de la Secretar\u00eda de Salud (Nayarit)","author":"grieta","date":"1 abril, 2020","format":false,"excerpt":"Foto: Realidades de Nayarit Mildre Ben\u00edtez Robledo \/ Realidades deNayarit Tepic, Nayarit; 01-abril-2020.- Pese a que los trabajadores de la Salud han pedido en diversas ocasiones al Gobierno Estatal que les surtan lo necesario, para hacerle frente a la pandemia que ha dejado miles de muertes en varios pa\u00edses del\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/protesta-768x480.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/protesta-768x480.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/protesta-768x480.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/04\/protesta-768x480.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72093,"url":"https:\/\/www.grieta.org.mx\/index.php\/2025\/07\/18\/hospital-tondoroque-nuevamente-en-crisis-sin-medicamento-y-falta-de-aire-acondicionado-nayarit\/","url_meta":{"origin":54778,"position":1},"title":"Hospital Tondoroque nuevamente en crisis; sin medicamento y falta de aire acondicionado (Nayarit)","author":"grieta","date":"18 julio, 2025","format":false,"excerpt":"imagen: CPS El Hospital de Tondoroque, en Bah\u00eda de Banderas, atraviesa una de sus peores crisis: enfrenta desabasto de medicamentos y, nuevamente, su sistema de aire acondicionado se averi\u00f3, justo en medio de la intensa ola de calor que afecta a la regi\u00f3n. Pacientes internados y del \u00e1rea de urgencias\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-18-at-7.16.26-PM-1.jpeg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-18-at-7.16.26-PM-1.jpeg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-18-at-7.16.26-PM-1.jpeg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-18-at-7.16.26-PM-1.jpeg.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-18-at-7.16.26-PM-1.jpeg.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":59093,"url":"https:\/\/www.grieta.org.mx\/index.php\/2021\/04\/26\/issste-niega-medicamentos-con-costos-que-van-desde-los-mil-hasta-los-21-mil-pesos-manifestantes-nayarit\/","url_meta":{"origin":54778,"position":2},"title":"ISSSTE niega medicamentos con costos que van desde los mil hasta los 21 mil pesos: Manifestantes (Nayarit)","author":"grieta","date":"26 abril, 2021","format":false,"excerpt":"Foto: Relatosnayarit Fernando Ulloa P\u00e9rez \/ Meridiano.MX Tepic Nayarit.- La ma\u00f1ana de este lunes alrededor de 100 personas de diferentes edades y de diversos extractos sociales, bloquearon el paseo de la Loma a la altura de la cl\u00ednica del ISSSTE para exigir que esta instituci\u00f3n medica les entregue de manera\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/denuncian-negligencia-en-el-issste-nayarit-29012.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/denuncian-negligencia-en-el-issste-nayarit-29012.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/denuncian-negligencia-en-el-issste-nayarit-29012.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/denuncian-negligencia-en-el-issste-nayarit-29012.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":46522,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/03\/17\/nayarit-no-esta-preparado-para-la-pandemia-afirman-trabajadores-de-la-secretaria-de-salud\/","url_meta":{"origin":54778,"position":3},"title":"Nayarit no esta preparado para la pandemia. Afirman trabajadores de la Secretaria de Salud","author":"grieta","date":"17 marzo, 2020","format":false,"excerpt":"Foto: Ilustrativa Redacci\u00f3n \/ Realidades de Nayarit En redes sociales los mismos trabajadores de la Secretaria de Salud del Estado de Nayarit, solicitaron a las autoridades del estado la dotaci\u00f3n de insumos y material para poder enfrentar en su momento la pandemia del COVID19. Afirman no estar preparados con infraestructura,\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/03\/hospital-general-tepic-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/03\/hospital-general-tepic-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/03\/hospital-general-tepic-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":65984,"url":"https:\/\/www.grieta.org.mx\/index.php\/2022\/12\/22\/exige-comunidad-lgbt-justicia-para-cletho-giovanni-nayarit\/","url_meta":{"origin":54778,"position":4},"title":"Exige comunidad LGBT+ justicia para Cletho Giovanni (Nayarit)","author":"grieta","date":"22 diciembre, 2022","format":false,"excerpt":"Imagen: Meridiano.mx Fernando P\u00e9rez Ulloa A trav\u00e9s de las redes sociales la comunidad LGBT+ dio a conocer que el joven Cletho Giovanni, quien era originario del poblado de Amapa, municipio de Santiago Ixcuintla, falleci\u00f3 la madrugada de hoy mi\u00e9rcoles en el Hospital Civil de esta capital. En el breve comunicado\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/12\/320974441_854085559128233_7353229079492881034_n-696x483-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/12\/320974441_854085559128233_7353229079492881034_n-696x483-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/12\/320974441_854085559128233_7353229079492881034_n-696x483-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":54781,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/11\/04\/por-falta-de-agua-toman-manifestantes-el-libramiento-de-tepic-nayarit\/","url_meta":{"origin":54778,"position":5},"title":"Por falta de agua toman manifestantes el Libramiento de Tepic (Nayarit)","author":"grieta","date":"4 noviembre, 2020","format":false,"excerpt":"Foto: Misalel Ulloa Isiordia Los manifestantes exigen el servicio de agua potable y solicitan la presencia del titular del SIAPA Tepic, Oscar Medina para el funcionario municipal cumpla su palabra. Fernando Ulloa P\u00e9rez \/ Meridiano.mx Ante la falta del servicio de agua potable desde hace m\u00e1s de 8 d\u00edas, la\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604535109_1604533679_valle_real.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604535109_1604533679_valle_real.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604535109_1604533679_valle_real.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/11\/1604535109_1604533679_valle_real.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/54778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=54778"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/54778\/revisions"}],"predecessor-version":[{"id":54780,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/54778\/revisions\/54780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/54779"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=54778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=54778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=54778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}