{"id":39630,"date":"2019-09-17T23:00:54","date_gmt":"2019-09-18T04:00:54","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=39630"},"modified":"2019-09-26T23:06:45","modified_gmt":"2019-09-27T04:06:45","slug":"dolores-hidalgo-y-otros-seis-municipios-guanajuatenses-se-oponen-a-minera-a-cielo-abierto","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2019\/09\/17\/dolores-hidalgo-y-otros-seis-municipios-guanajuatenses-se-oponen-a-minera-a-cielo-abierto\/","title":{"rendered":"Dolores Hidalgo, y otros seis municipios guanajuatenses se oponen a minera a cielo abierto"},"content":{"rendered":"<blockquote><p>Pobladores de la zona del cerro del Gallo se oponen a yacimiento de oro concesionado a empresa canadiense<\/p><\/blockquote>\n<figure id=\"attachment_39631\" aria-describedby=\"caption-attachment-39631\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"39631\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/09\/17\/dolores-hidalgo-y-otros-seis-municipios-guanajuatenses-se-oponen-a-minera-a-cielo-abierto\/gto-minera\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/09\/gto-minera.jpg\" data-orig-size=\"768,479\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"gto minera\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Desde el pasado julio, pobladores de al menos 21 comunidades se han manifestado p\u00fablicamente e contra de la mina de oro de Argonaut Gold\/  Foto: Antonieta Herrera&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/09\/gto-minera-300x187.jpg\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/09\/gto-minera.jpg\" class=\"wp-image-39631\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/09\/gto-minera.jpg\" alt=\"\" width=\"800\" height=\"499\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/09\/gto-minera.jpg 768w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/09\/gto-minera-300x187.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-39631\" class=\"wp-caption-text\">Desde el pasado julio, pobladores de al menos 21 comunidades se han manifestado p\u00fablicamente e contra de la mina de oro de Argonaut Gold\/ Foto: Antonieta Herrera<\/figcaption><\/figure>\n<p>Antonieta Herrera | El Sol del Bajio, 17b de septiembre de 2019<\/p>\n<p>DOLORES HIDALGO. Campesinos de 21 comunidades del municipio de Dolores Hidalgo y de otros seis municipios de Guanajuato se oponen a que se abra una mina a cielo abierto en el cerro del Gallo, en la comunidad de San Ant\u00f3n.<\/p>\n<p>El conflicto es por 25 mil hect\u00e1reas concesionadas para explotaci\u00f3n minera otorgada por el gobierno federal desde hace 50 a\u00f1os a la compa\u00f1\u00eda canadiense Argonaut Gold que ahora quiere aprovechar, por lo cual las organizaciones: Coalici\u00f3n en Defensa de la Cuenca de la Independencia (Codecin), el Colectivo Guardianes de la Cuenca, y Acci\u00f3n Colectiva Socioambiental, junto con las 21 comunidades, se han manifestado en contra.<\/p>\n<p>La principal raz\u00f3n para oponerse a la mina es el temor a quedarse sin agua o a recibirla con altos niveles de contaminaci\u00f3n, ya que la Comisi\u00f3n Nacional del Agua (Conagua) otorg\u00f3 a la minera t\u00edtulos de concesi\u00f3n para extraer hasta un mill\u00f3n 440 mil metros c\u00fabicos al a\u00f1o, dijo Gustavo<\/p>\n<p>Lozano, abogado de la organizaci\u00f3n Acci\u00f3n Colectiva Socioambiental. Lozano advirti\u00f3 adem\u00e1s por los da\u00f1os de salud que generar\u00e1 a los habitantes, pues seg\u00fan \u00e9l, las perforaciones de la minera contaminar\u00e1 el agua con metales pesados y no ser\u00e1 apta ni para consumo humano ni para el riego de cultivos. Tambi\u00e9n advirti\u00f3 que la extracci\u00f3n de oro requiere el rociar cianuro en la tierra para que los polvos del mineral puedan formar los lingotes, lo cual afectar\u00e1 sus cultivos.<\/p>\n<p>Por su parte, la empresa no ha podido concretar el estudio de impacto ambiental de la Secretar\u00eda de Medio Ambiente y RecursosNaturales (Semarnat), el permiso de uso de suelo y construcci\u00f3n emitidos por el municipio y la autorizaci\u00f3n de los propietarios de la tierra, los cuales son requisitos para abrir la mina.<\/p>\n<p>La minera entreg\u00f3 la \u00faltima solicitud ala Semarnat el 5 de septiembre de 2019. Sin embargo, la dependencia ya hab\u00eda dado su negativa a la empresa en cuatro solicitudes anteriores.<\/p>\n<p><a href=\"https:\/\/www.elsoldemexico.com.mx\/republica\/sociedad\/dolores-hidalgo-y-otros-seis-municipios-guanajuatenses-se-oponen-a-minera-a-cielo-abierto-4189694.html\">https:\/\/www.elsoldemexico.com.mx\/republica\/sociedad\/dolores-hidalgo-y-otros-seis-municipios-guanajuatenses-se-oponen-a-minera-a-cielo-abierto-4189694.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pobladores de la zona del cerro del Gallo se oponen a yacimiento de oro concesionado a empresa canadiense Antonieta Herrera | El Sol del Bajio, 17b de septiembre de 2019 &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/09\/17\/dolores-hidalgo-y-otros-seis-municipios-guanajuatenses-se-oponen-a-minera-a-cielo-abierto\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":39631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,2739,1066,2803,17,2751,2690],"tags":[2216,2846],"class_list":["post-39630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-conflictos-por-mineria-en-guanajuato","category-contaminacion-ambiental-en-guanajuato","category-crisis-del-agua-en-guanajuato","category-guanajuato","category-resistencia-contra-mineras-en-guanajuato","category-resistencias","tag-conflictos-por-mineria","tag-lucha-contra-la-mineria","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/09\/gto-minera.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-ajc","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":62877,"url":"https:\/\/www.grieta.org.mx\/index.php\/2021\/11\/10\/con-marcha-retoman-lucha-contra-mina-a-cielo-abierto-en-dolores-hidalgo-guanajuato\/","url_meta":{"origin":39630,"position":0},"title":"Con marcha, retoman lucha contra mina a cielo abierto en Dolores Hidalgo (Guanajuato)","author":"grieta","date":"10 noviembre, 2021","format":false,"excerpt":"por Alfonsina Avila noviembre 10, 2021, Zona Franca Guanajuato. Organizaciones y ciudadanos convocan a una manifestaci\u00f3n para el 21 de noviembre para defender el territorio y evitar la instalaci\u00f3n de una mina a cielo abierto en el Cerro del Gallo, en Dolores Hidalgo, por parte de la empresa canadiense Argonaut\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/11\/unnamed-3-5.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":62885,"url":"https:\/\/www.grieta.org.mx\/index.php\/2021\/11\/23\/marchan-por-alejar-de-dolores-hidalgo-el-proyecto-de-mina-a-cielo-abierto-guanajuato\/","url_meta":{"origin":39630,"position":1},"title":"Marchan por alejar de Dolores Hidalgo el proyecto de mina a cielo abierto (Guanajuato)","author":"grieta","date":"23 noviembre, 2021","format":false,"excerpt":"Mil personas realizan protesta pac\u00edfica en defensa de la Cuenca de la Independencia, sus recursos, su industria, y la salud y la vida de sus m\u00e1s de 600 mil habitantes POPLab, 23 de nov. 2021, Con informaci\u00f3n de Martha Silva. Fotos: Alonso Merino Lubetzky El Movimiento Social Contra la Miner\u00eda\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/12\/DH43-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/12\/DH43-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/12\/DH43-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/12\/DH43-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/12\/DH43-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/12\/DH43-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":41521,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/11\/24\/advierten-crisis-hidrica-en-dolores-hidalgo-si-se-explota-mina-en-el-cerro-del-gallo-guanajuato\/","url_meta":{"origin":39630,"position":2},"title":"Advierten crisis h\u00eddrica en Dolores Hidalgo si se explota mina en el Cerro del Gallo (Guanajuato","author":"grieta","date":"24 noviembre, 2019","format":false,"excerpt":"En el conversatorio \u201cAgua y miner\u00eda\u201d realizado la tarde de este s\u00e1bado en el Museo Bicentenario, se habl\u00f3 sobre el problema existente del agua en la Cuenca de la Independencia, as\u00ed como aun la gran afectaci\u00f3n que sufrir\u00edan los pobladores si se llega a implementar la explotaci\u00f3n de la mina\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/cerritodelgallo2-focus-0-0-983-557.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/cerritodelgallo2-focus-0-0-983-557.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/cerritodelgallo2-focus-0-0-983-557.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/cerritodelgallo2-focus-0-0-983-557.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":52689,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/07\/22\/manifestacion-virtual-no-a-la-mina-en-dolores-hidalgo-guanajuato\/","url_meta":{"origin":39630,"position":3},"title":"Manifestaci\u00f3n Virtual \u201cNo a la Mina\u201d En Dolores Hidalgo  (Guanajuato)","author":"grieta","date":"22 julio, 2020","format":false,"excerpt":"En conmemoraci\u00f3n del \u201cDia Mundial Contra la Miner\u00eda a Cielo Abierto\u201d, activistas se manifestaron virtualmente para reiterar su inconformidad por la pretensi\u00f3n de explotaci\u00f3n que tiene la minera canadiense Argonaut Gold, sobre la mina en el Cerro Del Gallo, en la comunidad de San Ant\u00f3n de las minas, en Dolores\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/08\/0p.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/08\/0p.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/08\/0p.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/08\/0p.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/08\/0p.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":67975,"url":"https:\/\/www.grieta.org.mx\/index.php\/2023\/07\/18\/agrupaciones-protestan-contra-explotacion-del-cerro-del-gallo-en-dolores-hidalgo-por-minera-canadiense-guanajuato\/","url_meta":{"origin":39630,"position":4},"title":"Agrupaciones protestan contra explotaci\u00f3n del cerro del Gallo en Dolores Hidalgo por minera canadiense (Guanajuato)","author":"grieta","date":"18 julio, 2023","format":false,"excerpt":"Roberto L\u00f3pez Martes, Peri\u00f3dico Correo, 18 Julio, 2023 Dolores Hidalgo, Guanajuato.- A prop\u00f3sito del d\u00eda mundial contra la miner\u00eda a cielo abierto, el pr\u00f3ximo 22 de julio, tres agrupaciones se reunieron para dar a conocer que se mantienen en lucha contra la explotaci\u00f3n del cerro del Gallo, en San Ant\u00f3n\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/cerro-610432957.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/cerro-610432957.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/cerro-610432957.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/cerro-610432957.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/cerro-610432957.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41518,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/11\/21\/preparan-conversatorio-en-dolores-hidalgo-agua-y-mineria-guanajuato\/","url_meta":{"origin":39630,"position":5},"title":"Preparan conversatorio en Dolores Hidalgo \u201cAgua y Miner\u00eda\u201d (Guanajuato)","author":"grieta","date":"21 noviembre, 2019","format":false,"excerpt":"La Coalici\u00f3n en Defensa de la Cuenca de la Independencia CODECIN, Centro de Desarrollo Agropecuario A.C. CEDESA y el Colectivo Guardianes de la Cuenca convocan al conversatorio \u201cAgua y Miner\u00eda\u201d este s\u00e1bado 23 de Noviembre en el museo Bicentenario. Zona Franca, 21 de noviembre de 2019 Dolores Hidalgo Gto. Activistas\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/h0.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/h0.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/h0.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/h0.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/39630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=39630"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/39630\/revisions"}],"predecessor-version":[{"id":39632,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/39630\/revisions\/39632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/39631"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=39630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=39630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=39630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}