{"id":37097,"date":"2019-07-25T12:57:16","date_gmt":"2019-07-25T17:57:16","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=37097"},"modified":"2019-07-29T13:16:59","modified_gmt":"2019-07-29T18:16:59","slug":"el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/25\/el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento\/","title":{"rendered":"El Estado de M\u00e9xico y sus mujeres desaparecidas: los casos van en aumento"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37098\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/25\/el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high.png\" data-orig-size=\"836,359\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high-300x129.png\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high.png\" class=\"alignleft wp-image-37098\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high.png\" alt=\"\" width=\"800\" height=\"344\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high.png 836w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high-300x129.png 300w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico-high-768x330.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Lau Almaraz\/CC News<\/p>\n<blockquote><p>Brenda y Alexandra son los casos m\u00e1s recientes en el Edomex. El 55 por ciento de las desapariciones corresponden a menores de edad.<\/p><\/blockquote>\n<p>Brenda Cruz Garc\u00eda desapareci\u00f3 el pasado 14 de julio, cuando tom\u00f3 un taxi que la llevar\u00eda a la terminal de autobuses en Amanalco, en Toluca, en el Estado de M\u00e9xico. Ah\u00ed se encontrar\u00eda con su novio, sin embargo, nunca lleg\u00f3 a su destino. Alexandra, de 15 a\u00f1os, desapareci\u00f3 el 12 de julio cuando sali\u00f3 de casa de su madre, en Villa Nicol\u00e1s Romero, tambi\u00e9n en el Estado de M\u00e9xico. Las dos fueron encontradas sin vida en distintos puntos del territorio mexiquense en las \u00faltimas semanas.<\/p>\n<p>Las desapariciones de mujeres van en aumento en el Estado de M\u00e9xico y, como informa Infobae, no son casos aislados. Tal y como reporta el portal noticioso, la entidad federativa recibe alrededor de 30 millones de pesos anuales para combatir la inseguridad desde el a\u00f1o 2015 y, parad\u00f3jicamente, las desapariciones y los feminicidios van en aumento.<\/p>\n<figure id=\"attachment_37099\" aria-describedby=\"caption-attachment-37099\" style=\"width: 567px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37099\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/25\/el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento\/desaparecidas-en-el-edomex-high\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.jpg\" data-orig-size=\"567,712\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"desaparecidas-en-el-edomex-high\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Brenda no lleg\u00f3 a su destino en Toluca. Su cuerpo fue encontrado en un paraje de Almoloya. (Foto: CC News)&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high-239x300.jpg\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.jpg\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.jpg\" alt=\"\" width=\"567\" height=\"712\" class=\"size-full wp-image-37099\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.jpg 567w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high-239x300.jpg 239w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high-398x500.jpg 398w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><figcaption id=\"caption-attachment-37099\" class=\"wp-caption-text\">Brenda no lleg\u00f3 a su destino en Toluca. Su cuerpo fue encontrado en un paraje de Almoloya. (Foto: CC News)<\/figcaption><\/figure>\n<p><strong>\u00bfFunciona la Alerta de G\u00e9nero?<\/strong><\/p>\n<p>Veamos. Desde que se instaur\u00f3 la Alerta de G\u00e9nero el 28 de julio del 2015, se destinan a ella 30 millones de pesos, los cuales se distribuyen en 11 municipios en los que se activ\u00f3 dicha alerta: Ecatepec, Nezahualc\u00f3yotl, Valle de Chalco, Toluca, Tlalnepantla, Chimalhuac\u00e1n, Naucalpan, Tultitl\u00e1n, Ixtapaluca, Cuautitl\u00e1n Izcalli y Chalco.<\/p>\n<p>A Ixtapaluca, Tultitl\u00e1n, Valle de Chalco, Naucalpan y Nezahualc\u00f3yotl, se entregan entre 2.6 y 2.2 millones de pesos, mientras que a Chimalhuac\u00e1n, se le destinan 1.4 millones para mitigar la Alerta de G\u00e9nero, siendo este municipio el que menos recibe para estos efectos, de acuerdo a la Comisi\u00f3n Especial de Seguimiento a los Feminicidios del congreso local.<\/p>\n<p>Sin embargo, despu\u00e9s de cuatro a\u00f1os, las cifras han aumentado de manera considerable tanto en desapariciones como en feminicidios. La Alerta de G\u00e9nero, aunque ha sido activada en estos municipios y a la que se destina una fuerte cantidad de dinero, al parecer, no est\u00e1 funcionando.<\/p>\n<figure id=\"attachment_37100\" aria-describedby=\"caption-attachment-37100\" style=\"width: 836px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37100\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/25\/el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento\/aumentan-mujeres-desaparecidas-en-edomex-high\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-mujeres-desaparecidas-en-edomex-high.jpg\" data-orig-size=\"836,438\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"aumentan-mujeres-desaparecidas-en-edomex-high\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Son las menores de edad las que m\u00e1s desaparecen en el Estado de M\u00e9xico. (Foto: Milenio)&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-mujeres-desaparecidas-en-edomex-high-300x157.jpg\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-mujeres-desaparecidas-en-edomex-high.jpg\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-mujeres-desaparecidas-en-edomex-high.jpg\" alt=\"\" width=\"836\" height=\"438\" class=\"size-full wp-image-37100\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-mujeres-desaparecidas-en-edomex-high.jpg 836w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-mujeres-desaparecidas-en-edomex-high-300x157.jpg 300w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/aumentan-mujeres-desaparecidas-en-edomex-high-768x402.jpg 768w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><figcaption id=\"caption-attachment-37100\" class=\"wp-caption-text\">Son las menores de edad las que m\u00e1s desaparecen en el Estado de M\u00e9xico. (Foto: Milenio)<\/figcaption><\/figure>\n<p><strong>55 por ciento de las desaparecidas, son menores de edad<\/strong><\/p>\n<p>Ni\u00f1as, adolescentes, j\u00f3venes, adultas. Ser mujer en M\u00e9xico es complicado, sin embargo, ser mujer en el Estado de M\u00e9xico es todav\u00eda m\u00e1s riesgoso, tomando en cuenta los n\u00fameros presentados apenas en mayo pasado, durante la audiencia p\u00fablica del 172 Periodo de Sesiones de la Comisi\u00f3n Interamericana de Derechos Humanos.<\/p>\n<p>Si ser mujer en el Estado de M\u00e9xico es dif\u00edcil, ser mujer y menor de edad en la entidad gobernada por Alfredo del Mazo, es escalofriante, al menos en n\u00fameros, pues de las mil 73 mujeres desaparecidas en esta parte del territorio nacional, el 55 por ciento son menores de edad. Hasta mayo pasado, Ecatepec ocupaba el primer lugar con 266 desapariciones, Nezahualc\u00f3yotl en segundo sitio con 221, seguido de Toluca con 210.<\/p>\n<p>En cuarto lugar se presenta Chimalhuac\u00e1n con 127 desapariciones de mujeres; en quinto est\u00e1 Valle de Chalco con 96, le siguen Ixtapaluca con 87 y Cuautitl\u00e1n Izcalli, con 66 mujeres desaparecidas.<\/p>\n<figure id=\"attachment_37101\" aria-describedby=\"caption-attachment-37101\" style=\"width: 836px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37101\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/25\/el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento\/desaparecidas-en-el-edomex-high-2\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.png\" data-orig-size=\"836,464\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"desaparecidas-en-el-edomex-high\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Noticieros Televisa present\u00f3 las estad\u00edsticas de desapariciones en mayo pasado. (Foto: Noticieros Televisa)&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high-300x167.png\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.png\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.png\" alt=\"\" width=\"836\" height=\"464\" class=\"size-full wp-image-37101\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.png 836w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high-300x167.png 300w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high-768x426.png 768w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><figcaption id=\"caption-attachment-37101\" class=\"wp-caption-text\">Noticieros Televisa present\u00f3 las estad\u00edsticas de desapariciones en mayo pasado. (Foto: Noticieros Televisa)<\/figcaption><\/figure>\n<p><strong>Natalia Olmedo D\u00edaz, una desaparecida m\u00e1s en el Estado de M\u00e9xico<\/strong><\/p>\n<p>Si bien Coacalco no ha sido considerado entre los 11 municipios en los que se ha activado la Alerta de G\u00e9nero, el tema de la desaparici\u00f3n de mujeres tambi\u00e9n ha ocupado a los vecinos de las distintas colonias que habitan en esta parte del Estado de M\u00e9xico.<\/p>\n<p>El caso de Natalia Olmedo D\u00edaz tambi\u00e9n ha sido motivo de menci\u00f3n en diversos medios de comunicaci\u00f3n, incluido Infobae. Esta joven de apenas 15 a\u00f1os, desapareci\u00f3 de su domicilio ubicado en San Francisco Coacalco, en la secci\u00f3n H\u00e9roes, el pasado 15 de julio. Tanto familiares como amigos, han pedido la distribuci\u00f3n de su fotograf\u00eda para localizarla lo m\u00e1s pronto posible pues no hab\u00eda motivos para que se fuera de casa.<\/p>\n<p>Una historia similar es la de Diana Greta Santiago Quiroz, una joven que se uni\u00f3 a las estad\u00edsticas de mujeres menores de edad desaparecidas en Ixtapaluca. Con apenas 17 a\u00f1os, la menor no regres\u00f3 a casa tras acudir a clases en el Colegio de Bachilleres, Plantel 18, en marzo pasado. Su familia asegura que no hay motivos para que hubiera huido de casa, al igual que Natalia.<\/p>\n<figure id=\"attachment_37102\" aria-describedby=\"caption-attachment-37102\" style=\"width: 687px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37102\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/25\/el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento\/desaparecidas-en-el-estado-de-mexico-high\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-estado-de-mexico-high.jpg\" data-orig-size=\"687,910\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"desaparecidas-en-el-estado-de-mexico-high\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Esta es la ficha de desaparici\u00f3n de Natalia Olmedo D\u00edaz, en Los H\u00e9roes, Coacalco. (Foto: Especial)&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-estado-de-mexico-high-226x300.jpg\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-estado-de-mexico-high.jpg\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-estado-de-mexico-high.jpg\" alt=\"\" width=\"687\" height=\"910\" class=\"size-full wp-image-37102\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-estado-de-mexico-high.jpg 687w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-estado-de-mexico-high-226x300.jpg 226w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-estado-de-mexico-high-377x500.jpg 377w\" sizes=\"auto, (max-width: 687px) 100vw, 687px\" \/><figcaption id=\"caption-attachment-37102\" class=\"wp-caption-text\">Esta es la ficha de desaparici\u00f3n de Natalia Olmedo D\u00edaz, en Los H\u00e9roes, Coacalco. (Foto: Especial)<\/figcaption><\/figure>\n<p><strong>Temas de trata, explotaci\u00f3n laboral o sexual<\/strong><\/p>\n<p>De acuerdo a datos presentados por la directora de la red &#8220;Eslabones por los Derechos Humanos&#8221;, Valentina Peralta, la desaparici\u00f3n de mujeres menores de edad se da por diversos factores y objetivos: &#8220;El fen\u00f3meno de la desaparici\u00f3n tiene muchos objetivos, sobre todo en el caso de las mujeres que desaparecen entre los 10, 12, 18, 19 a\u00f1os de edad, siempre se puede pensar en un tema de trata, de explotaci\u00f3n laboral o sexual&#8221;.<\/p>\n<p>En el \u00faltimo reporte elaborado por Litigio Estrat\u00e9gico de Derechos Humanos, en conjunto con el Instituto Mexicano de Derechos Humanos y Democracia (IMDHD), denominado &#8220;Diagn\u00f3stico: Mujeres Desaparecidas en el Estado de M\u00e9xico&#8221;, en nuestro pa\u00eds existe un total de 35 mil 424 personas desaparecidas, de las cuales al Estado de M\u00e9xico le corresponden 3 mil 861. De esa cantidad, el 46 por ciento corresponde a desapariciones de mujeres.<\/p>\n<p><a href=\"https:\/\/news.culturacolectiva.com\/mexico\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico\/\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/news.culturacolectiva.com\/mexico\/aumentan-casos-de-mujeres-desaparecidas-en-el-estado-de-mexico\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lau Almaraz\/CC News Brenda y Alexandra son los casos m\u00e1s recientes en el Edomex. El 55 por ciento de las desapariciones corresponden a menores de edad. Brenda Cruz Garc\u00eda desapareci\u00f3 &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/07\/25\/el-estado-de-mexico-y-sus-mujeres-desaparecidas-los-casos-van-en-aumento\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":37101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,87,1204,16,367,1013,2,83],"tags":[121,2351,94],"class_list":["post-37097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-desaparecidos","category-desaparecidos-en-el-estado-de-mexico","category-estado-de-mexico","category-feminicidios-analisis","category-feminicios-en-el-estado-de-mexico","category-noticias-nacionales","category-temas-nacionales","tag-desaparecidos","tag-desaparicion-de-mujeres","tag-violencia-contra-mujeres","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/desaparecidas-en-el-edomex-high.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-9El","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":53727,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/09\/11\/incendian-sede-de-codhem-en-ecatepec-tras-detencion-de-feministas-estado-de-mexico\/","url_meta":{"origin":37097,"position":0},"title":"Incendian sede de CODHEM en Ecatepec tras detenci\u00f3n de feministas (Estado de M\u00e9xico)","author":"grieta","date":"11 septiembre, 2020","format":false,"excerpt":"Foto: Twiter \/ @Andalalucha Carlos Guevara \/ El Sol de M\u00e9xico Un grupo de aproximadamente 50 mujeres llegaron al recinto ubicado en o en la Avenida Morelos para manifestarse en contra de la violencia policial y feminicidios Mujeres feministas incendiaron este viernes las instalaciones de la visitadur\u00eda general de la\u2026","rel":"","context":"En &quot;Abuso policiaco y tortura en el Estado de M\u00e9xico&quot;","block_context":{"text":"Abuso policiaco y tortura en el Estado de M\u00e9xico","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/estado-de-mexico\/abuso-policiaco-y-tortura-en-el-estado-de-mexico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/Incendian-sede-de-CODHEM-en-Ecatepec-tras-detencion-de-feministas-edomex-sept.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/Incendian-sede-de-CODHEM-en-Ecatepec-tras-detencion-de-feministas-edomex-sept.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/Incendian-sede-de-CODHEM-en-Ecatepec-tras-detencion-de-feministas-edomex-sept.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/Incendian-sede-de-CODHEM-en-Ecatepec-tras-detencion-de-feministas-edomex-sept.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":42147,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/12\/13\/protestaron-familias-y-clausuraron-la-fgjem-fiscal-los-desaira-estado-de-mexico\/","url_meta":{"origin":37097,"position":1},"title":"Protestaron familias y clausuraron la FGJEM; Fiscal los desaira (Estado de M\u00e9xico)","author":"grieta","date":"13 diciembre, 2019","format":false,"excerpt":"Iv\u00e1n Ju\u00e1rez \/ Quiadrat\u00edn EdoMex Toluca, Edomex, 13 de diciembre de 2019.-Para pedir resultados ante el aumento de casos de feminicidios y desapariciones, activistas junto con familiares de v\u00edctimas protestaron, adem\u00e1s, clausuraron el edificio central de la Fiscal\u00eda General de Justicia del Estado de M\u00e9xico. Las personas se reunieron en\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Protestaron-familias-y-clausuraron-la-FGJEM-Fiscal-los-desaira-edomex-dic.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Protestaron-familias-y-clausuraron-la-FGJEM-Fiscal-los-desaira-edomex-dic.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Protestaron-familias-y-clausuraron-la-FGJEM-Fiscal-los-desaira-edomex-dic.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Protestaron-familias-y-clausuraron-la-FGJEM-Fiscal-los-desaira-edomex-dic.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":44013,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/03\/09\/onu-alerta-sobre-mas-de-9-000-mujeres-desaparecidas-en-mexico\/","url_meta":{"origin":37097,"position":2},"title":"ONU alerta sobre m\u00e1s de 9.000 mujeres desaparecidas en M\u00e9xico","author":"grieta","date":"9 marzo, 2019","format":false,"excerpt":"Una protesta contra el feminicidio y la violencia contra las mujeres en Ciudad de M\u00e9xico, el 2 de febrero de 2019. Edgard Garrido \/ Reuters RT Los feminicidios en el pa\u00eds aumentaron 104 % en los \u00faltimos tres a\u00f1os. La Oficina del Alto Comisionado de la ONU para los Derechos\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/ONU-alerta-sobre-m%C3%A1s-de-9.000-mujeres-desaparecidas-en-M%C3%A9xico.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/ONU-alerta-sobre-m%C3%A1s-de-9.000-mujeres-desaparecidas-en-M%C3%A9xico.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/ONU-alerta-sobre-m%C3%A1s-de-9.000-mujeres-desaparecidas-en-M%C3%A9xico.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/ONU-alerta-sobre-m%C3%A1s-de-9.000-mujeres-desaparecidas-en-M%C3%A9xico.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30911,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/03\/08\/al-menos-siete-feminicidios-mensuales-de-ninas-y-adolescentes-redim\/","url_meta":{"origin":37097,"position":3},"title":"Al menos siete feminicidios mensuales de ni\u00f1as y adolescentes: REDIM","author":"grieta","date":"8 marzo, 2019","format":false,"excerpt":"L\u00f3pez D\u00f3riga Digital La cifra de adolescentes v\u00edctimas de feminicidios a nivel nacional se duplic\u00f3 de 2015 a 2018, al pasar de 422 a 861 casos La Red por los Derechos de la Infancia en M\u00e9xico (REDIM) asegur\u00f3 que la violencia machista y omisi\u00f3n de las autoridades son responsables de\u2026","rel":"","context":"En &quot;Chihuahua&quot;","block_context":{"text":"Chihuahua","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/chihuahua\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/Al-menos-siete-feminicidios-mensuales-de-ni%C3%B1as-y-adolescentes-REDIM-nl-mzo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/Al-menos-siete-feminicidios-mensuales-de-ni%C3%B1as-y-adolescentes-REDIM-nl-mzo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/Al-menos-siete-feminicidios-mensuales-de-ni%C3%B1as-y-adolescentes-REDIM-nl-mzo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/Al-menos-siete-feminicidios-mensuales-de-ni%C3%B1as-y-adolescentes-REDIM-nl-mzo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":56683,"url":"https:\/\/www.grieta.org.mx\/index.php\/2021\/01\/19\/cronica-de-un-grito-para-encontrarte-norma-dianey-garcia-estado-de-mexico\/","url_meta":{"origin":37097,"position":4},"title":"CR\u00d3NICA DE UN GRITO PARA ENCONTRARTE, NORMA DIANEY GARC\u00cdA (Estado de M\u00e9xico)","author":"grieta","date":"19 enero, 2021","format":false,"excerpt":"Texto y fotograf\u00edas: Brenda Mart\u00ednez Carrera \/ Revista Balad\u00ed \u201c\u00bfQui\u00e9n osa salir a marchar en pleno confinamiento por la pandemia de COVID-19, en un domingo, con el cielo despejado y el clima templado?\u201d,\u00a0 probablemente se preguntar\u00edan los automovilistas y espectadores que paseaban por el tianguis cuando un contingenteparti\u00f3 de avenida\u2026","rel":"","context":"En &quot;Abuso policiaco y tortura en el Estado de M\u00e9xico&quot;","block_context":{"text":"Abuso policiaco y tortura en el Estado de M\u00e9xico","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/estado-de-mexico\/abuso-policiaco-y-tortura-en-el-estado-de-mexico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/02\/CRONICA-DE-UN-GRITO-PARA-ENCONTRARTE-NORMA-DIANEY-GARCIA-edomex-feb.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/02\/CRONICA-DE-UN-GRITO-PARA-ENCONTRARTE-NORMA-DIANEY-GARCIA-edomex-feb.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/02\/CRONICA-DE-UN-GRITO-PARA-ENCONTRARTE-NORMA-DIANEY-GARCIA-edomex-feb.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/02\/CRONICA-DE-UN-GRITO-PARA-ENCONTRARTE-NORMA-DIANEY-GARCIA-edomex-feb.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/02\/CRONICA-DE-UN-GRITO-PARA-ENCONTRARTE-NORMA-DIANEY-GARCIA-edomex-feb.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":30481,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/03\/05\/las-mujeres-desaparecidas-en-la-inmediaciones-de-la-capital-de-mexico-duplican-la-media-nacional\/","url_meta":{"origin":37097,"position":5},"title":"Las mujeres desaparecidas en la inmediaciones de la capital de M\u00e9xico duplican la media nacional","author":"grieta","date":"5 marzo, 2019","format":false,"excerpt":"Eliana Gilet\/Sputnik Mientras que la media nacional indica que 25% de los casos de personas desaparecidas son ni\u00f1as o mujeres, en el Estado de M\u00e9xico \u2014justo alrededor de la capital nacional\u2014 ese porcentaje trepa hasta el 46% de los casos. El 31% de ellas tienen entre 15 y 17 a\u00f1os.\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/1085875431.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/1085875431.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/1085875431.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/03\/1085875431.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/37097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=37097"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/37097\/revisions"}],"predecessor-version":[{"id":37103,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/37097\/revisions\/37103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/37101"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=37097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=37097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=37097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}