{"id":28219,"date":"2019-01-07T21:38:37","date_gmt":"2019-01-08T03:38:37","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=28219"},"modified":"2019-01-08T21:53:28","modified_gmt":"2019-01-09T03:53:28","slug":"nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2019\/01\/07\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato\/","title":{"rendered":"Nadie los reclam\u00f3 y fueron enterrados en alguna fosa com\u00fan de Guanajuato"},"content":{"rendered":"<p>Luz Elena Escobar, Le\u00f3n Guanajuato. AM-Le\u00f3n Guanajuato. 7 de enero de 2019<\/p>\n<blockquote><p>Carecen municipios de registros sobre cuerpos sin identificar o sin reclamar por familiares; algunos ni tumba general tienen.<\/p><\/blockquote>\n<p><img decoding=\"async\" data-attachment-id=\"28220\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/01\/07\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a.jpg\" data-orig-size=\"1000,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Aspecto de la fosa com\u00fan ubicada en el Pante\u00f3n Municipal Norte, en la colonia Las Trojes. Una mujer acostumbra adornarla cada a\u00f1o en honor de los difuntos que nadie recuerda. Foto: Archivo.&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a-300x180.jpg\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a.jpg\" class=\"size-full wp-image-28220\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a.jpg\" alt=\"\" width=\"100%\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a.jpg 1000w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a-300x180.jpg 300w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a-768x461.jpg 768w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a-833x500.jpg 833w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Once baleados, dos ahogados, 10 golpeados, tres estrangulados, un degollado, un atropellado, dos desmembrados, dos apu\u00f1alados, un asfixiado, un desnutrido, siete infartados, as\u00ed como tres fetos son apenas 44 registros de causa de muerte de los 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos de Celaya.<\/p>\n<p>Todas fueron enterrados sin recibir una ofrenda, flores, la luz de las velas, una plegaria e incluso sin tener qui\u00e9n llorara su partida.<\/p>\n<p>V\u00eda acceso a la informaci\u00f3n se obtuvieron datos de 26 de los 46 municipios del Estado, entre los que Celaya encabeza la lista de cuerpos sin identificar o reclamar de 2012 a septiembre pasado.<\/p>\n<p><strong>Sin sepultura propia<\/strong><\/p>\n<p>Once baleados, dos ahogados, 10 golpeados, tres estrangulados, un degollado, un atropellado, dos desmembrados, dos apu\u00f1alados, un asfixiado, un desnutrido, siete infartados, as\u00ed como tres fetos son apenas 44 registros de causa de muerte de los 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos de Celaya.<\/p>\n<p>Todas fueron enterrados sin recibir una ofrenda, flores, la luz de las velas, una plegaria e incluso sin tener qui\u00e9n llorara su partida.<\/p>\n<p>V\u00eda acceso a la informaci\u00f3n se obtuvieron datos de 26 de los 46 municipios del Estado, entre los que Celaya encabeza la lista de cuerpos sin identificar o reclamar de 2012 a septiembre pasado.<\/p>\n<p>Sin sepultura propia<\/p>\n<p>Pese a que los datos proporcionados por el Municipio identifican 44 causas de muerte, se desconoce el sexo de 84 cad\u00e1veres y s\u00f3lo se sabe que nueve eran varones.<br \/>\n<img decoding=\"async\" data-attachment-id=\"28221\" data-permalink=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/01\/07\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato\/vazam82mr0srpgf8ye9ynooe\/\" data-orig-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/vazam82mr0srpgf8ye9ynooe.jpg\" data-orig-size=\"675,390\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"vazam82mr0srpgf8ye9ynooe\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/vazam82mr0srpgf8ye9ynooe-300x173.jpg\" data-large-file=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/vazam82mr0srpgf8ye9ynooe.jpg\" class=\"aligncenter size-full wp-image-28221\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/vazam82mr0srpgf8ye9ynooe.jpg\" alt=\"\" width=\"100%\" srcset=\"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/vazam82mr0srpgf8ye9ynooe.jpg 675w, https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/vazam82mr0srpgf8ye9ynooe-300x173.jpg 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/><\/p>\n<p>De 25 municipios tuvieron como destino final la fosa com\u00fan donde se entierran varios cad\u00e1veres sin tener una sepultura propia al no haber sido reclamados o identificados por sus familiares, sin recibir una l\u00e1grima o un adi\u00f3s.<\/p>\n<p>Personal de la Procuradur\u00eda General de Justicia del Estado (PGJE) inform\u00f3 que de 2012 al 31 de agosto pasado se tiene un registro de 360 muertos no identificados, as\u00ed como identificados pero no reclamados.<\/p>\n<p><strong>Cuentan con resultados periciales forenses<\/strong><\/p>\n<p>\u201cAl hallazgo de un cad\u00e1ver que no es posible su identificaci\u00f3n y no es reclamado, se resguarda en el Servicio M\u00e9dico Forense (Semefo) para integrar las indagatorias considerando las particularidades de la investigaci\u00f3n de cada caso\u201d.<\/p>\n<p>\u201cAdem\u00e1s se recaba, entre otros datos, los resultados periciales forenses (odontolog\u00eda y gen\u00e9tica), a afecto que, una vez agotadas las diligencias y protocolos establecidos la autoridad ministerial ordena la inhumaci\u00f3n del cad\u00e1ver\u201d, explicaron autoridades.<\/p>\n<p><strong>Carecen panteones de registro<\/strong><br \/>\nDe los 46 municipios de la entidad, 18 informaron que no cuentan con registros de env\u00edo de cuerpos a sus panteones p\u00fablicos, en otros casos aseguraron que no tienen fosa com\u00fan en los cementerios.<\/p>\n<p>De estos Ayuntamientos el que m\u00e1s sorprendi\u00f3 por su negativa a proporcionar datos es Irapuato; am solicit\u00f3 la informaci\u00f3n en tres ocasiones, pero fue negada porque \u201cno pudieron comprender la pregunta\u201d, a diferencia de los 45 municipios restantes.<\/p>\n<p>Lo anterior pese a tener el antecedente de un alto \u00edndice en ejecuciones, adem\u00e1s de ser el segundo municipio m\u00e1s poblado de la entidad.<\/p>\n<p><strong>No proporciona informaci\u00f3n<\/strong><br \/>\nOtros casos contradictorios son San Diego de la Uni\u00f3n y San Felipe, donde en una primera solicitud realizada antes del cambio de administraci\u00f3n municipal contestaron que no contaban con registro de cuerpos enviados a la fosa com\u00fan, pero en una segunda solicitud que recibi\u00f3 la actual administraci\u00f3n s\u00ed brindaron las cifras.<\/p>\n<p>Durante mes y medio se busc\u00f3 tratar el tema con la Procuradur\u00eda General de Justicia del Estado de Guanajuato (PGJE), pero no hubo respuesta.<\/p>\n<p>Se explic\u00f3 al responsable de Comunicaci\u00f3n Social de la dependencia el contenido del reportaje y en un segundo momento a otro integrante del \u00e1rea. En un tercer acercamiento se envi\u00f3 un cuestionario el 19 de octubre pasado a trav\u00e9s de la Direcci\u00f3n de Comunicaci\u00f3n Social de Gobierno del Estado, pero previo a la publicaci\u00f3n tampoco se tuvo respuesta.<\/p>\n<p><strong>Lidera Celaya en cad\u00e1veres sin reclamar<\/strong><\/p>\n<p>Celaya es el municipio con m\u00e1s decesos sin reclamar, pues tiene un registro de 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos.<\/p>\n<p>Le sigue Le\u00f3n en segundo lugar con 49, de los cuales 44 son hombres, cuatro mujeres y uno sin identificar el sexo; sin embargo, se desconoce las causas de muerte.<\/p>\n<p>Once baleados, dos ahogados, 10 golpeados, tres estrangulados, un degollado, un atropellado, dos desmembrados, dos apu\u00f1alados, un asfixiado, un desnutrido, siete infartados, as\u00ed como tres fetos son apenas 44 registros de causa de muerte de los 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos de Celaya.<\/p>\n<p>Todas fueron enterrados sin recibir una ofrenda, flores, la luz de las velas, una plegaria e incluso sin tener qui\u00e9n llorara su partida.<\/p>\n<p>V\u00eda acceso a la informaci\u00f3n se obtuvieron datos de 26 de los 46 municipios del Estado, entre los que Celaya encabeza la lista de cuerpos sin identificar o reclamar de 2012 a septiembre pasado.<\/p>\n<p>Sin sepultura propia<\/p>\n<p>Pese a que los datos proporcionados por el Municipio identifican 44 causas de muerte, se desconoce el sexo de 84 cad\u00e1veres y s\u00f3lo se sabe que nueve eran varones.<\/p>\n<p>De 25 municipios tuvieron como destino final la fosa com\u00fan donde se entierran varios cad\u00e1veres sin tener una sepultura propia al no haber sido reclamados o identificados por sus familiares, sin recibir una l\u00e1grima o un adi\u00f3s.<\/p>\n<p>Personal de la Procuradur\u00eda General de Justicia del Estado (PGJE) inform\u00f3 que de 2012 al 31 de agosto pasado se tiene un registro de 360 muertos no identificados, as\u00ed como identificados pero no reclamados.<\/p>\n<p>Cuentan con resultados periciales forenses<\/p>\n<p>\u201cAl hallazgo de un cad\u00e1ver que no es posible su identificaci\u00f3n y no es reclamado, se resguarda en el Servicio M\u00e9dico Forense (Semefo) para integrar las indagatorias considerando las particularidades de la investigaci\u00f3n de cada caso\u201d.<\/p>\n<p>\u201cAdem\u00e1s se recaba, entre otros datos, los resultados periciales forenses (odontolog\u00eda y gen\u00e9tica), a afecto que, una vez agotadas las diligencias y protocolos establecidos la autoridad ministerial ordena la inhumaci\u00f3n del cad\u00e1ver\u201d, explicaron autoridades.<\/p>\n<p>Carecen panteones de registro<\/p>\n<p>De los 46 municipios de la entidad, 18 informaron que no cuentan con registros de env\u00edo de cuerpos a sus panteones p\u00fablicos, en otros casos aseguraron que no tienen fosa com\u00fan en los cementerios.<\/p>\n<p>De estos Ayuntamientos el que m\u00e1s sorprendi\u00f3 por su negativa a proporcionar datos es Irapuato; am solicit\u00f3 la informaci\u00f3n en tres ocasiones, pero fue negada porque \u201cno pudieron comprender la pregunta\u201d, a diferencia de los 45 municipios restantes.<\/p>\n<p>Lo anterior pese a tener el antecedente de un alto \u00edndice en ejecuciones, adem\u00e1s de ser el segundo municipio m\u00e1s poblado de la entidad.<\/p>\n<p>No proporciona informaci\u00f3n<\/p>\n<p>Otros casos contradictorios son San Diego de la Uni\u00f3n y San Felipe, donde en una primera solicitud realizada antes del cambio de administraci\u00f3n municipal contestaron que no contaban con registro de cuerpos enviados a la fosa com\u00fan, pero en una segunda solicitud que recibi\u00f3 la actual administraci\u00f3n s\u00ed brindaron las cifras.<\/p>\n<p>Durante mes y medio se busc\u00f3 tratar el tema con la Procuradur\u00eda General de Justicia del Estado de Guanajuato (PGJE), pero no hubo respuesta.<\/p>\n<p>Se explic\u00f3 al responsable de Comunicaci\u00f3n Social de la dependencia el contenido del reportaje y en un segundo momento a otro integrante del \u00e1rea. En un tercer acercamiento se envi\u00f3 un cuestionario el 19 de octubre pasado a trav\u00e9s de la Direcci\u00f3n de Comunicaci\u00f3n Social de Gobierno del Estado, pero previo a la publicaci\u00f3n tampoco se tuvo respuesta.<\/p>\n<p>Lidera Celaya en cad\u00e1veres sin reclamar<\/p>\n<p>Celaya es el municipio con m\u00e1s decesos sin reclamar, pues tiene un registro de 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos.<\/p>\n<p>Le sigue Le\u00f3n en segundo lugar con 49, de los cuales 44 son hombres, cuatro mujeres y uno sin identificar el sexo; sin embargo, se desconoce las causas de muerte.<\/p>\n<p>Contin\u00faa Salamanca con 21: son cinco hombres, dos mujeres y 14 sin identificar g\u00e9nero. San Miguel de Allende tiene 18 cuerpos y s\u00f3lo se conoce la causa de muerte de un hombre que fue baleado.<\/p>\n<p>Once baleados, dos ahogados, 10 golpeados, tres estrangulados, un degollado, un atropellado, dos desmembrados, dos apu\u00f1alados, un asfixiado, un desnutrido, siete infartados, as\u00ed como tres fetos son apenas 44 registros de causa de muerte de los 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos de Celaya.<\/p>\n<p>Todas fueron enterrados sin recibir una ofrenda, flores, la luz de las velas, una plegaria e incluso sin tener qui\u00e9n llorara su partida.<\/p>\n<p>V\u00eda acceso a la informaci\u00f3n se obtuvieron datos de 26 de los 46 municipios del Estado, entre los que Celaya encabeza la lista de cuerpos sin identificar o reclamar de 2012 a septiembre pasado.<\/p>\n<p>Sin sepultura propia<\/p>\n<p>Pese a que los datos proporcionados por el Municipio identifican 44 causas de muerte, se desconoce el sexo de 84 cad\u00e1veres y s\u00f3lo se sabe que nueve eran varones.<\/p>\n<p>De 25 municipios tuvieron como destino final la fosa com\u00fan donde se entierran varios cad\u00e1veres sin tener una sepultura propia al no haber sido reclamados o identificados por sus familiares, sin recibir una l\u00e1grima o un adi\u00f3s.<\/p>\n<p>Personal de la Procuradur\u00eda General de Justicia del Estado (PGJE) inform\u00f3 que de 2012 al 31 de agosto pasado se tiene un registro de 360 muertos no identificados, as\u00ed como identificados pero no reclamados.<\/p>\n<p>Cuentan con resultados periciales forenses<\/p>\n<p>\u201cAl hallazgo de un cad\u00e1ver que no es posible su identificaci\u00f3n y no es reclamado, se resguarda en el Servicio M\u00e9dico Forense (Semefo) para integrar las indagatorias considerando las particularidades de la investigaci\u00f3n de cada caso\u201d.<\/p>\n<p>\u201cAdem\u00e1s se recaba, entre otros datos, los resultados periciales forenses (odontolog\u00eda y gen\u00e9tica), a afecto que, una vez agotadas las diligencias y protocolos establecidos la autoridad ministerial ordena la inhumaci\u00f3n del cad\u00e1ver\u201d, explicaron autoridades.<\/p>\n<p>Carecen panteones de registro<\/p>\n<p>De los 46 municipios de la entidad, 18 informaron que no cuentan con registros de env\u00edo de cuerpos a sus panteones p\u00fablicos, en otros casos aseguraron que no tienen fosa com\u00fan en los cementerios.<\/p>\n<p>De estos Ayuntamientos el que m\u00e1s sorprendi\u00f3 por su negativa a proporcionar datos es Irapuato; am solicit\u00f3 la informaci\u00f3n en tres ocasiones, pero fue negada porque \u201cno pudieron comprender la pregunta\u201d, a diferencia de los 45 municipios restantes.<\/p>\n<p>Lo anterior pese a tener el antecedente de un alto \u00edndice en ejecuciones, adem\u00e1s de ser el segundo municipio m\u00e1s poblado de la entidad.<\/p>\n<p>No proporciona informaci\u00f3n<\/p>\n<p>Otros casos contradictorios son San Diego de la Uni\u00f3n y San Felipe, donde en una primera solicitud realizada antes del cambio de administraci\u00f3n municipal contestaron que no contaban con registro de cuerpos enviados a la fosa com\u00fan, pero en una segunda solicitud que recibi\u00f3 la actual administraci\u00f3n s\u00ed brindaron las cifras.<\/p>\n<p>Durante mes y medio se busc\u00f3 tratar el tema con la Procuradur\u00eda General de Justicia del Estado de Guanajuato (PGJE), pero no hubo respuesta.<\/p>\n<p>Se explic\u00f3 al responsable de Comunicaci\u00f3n Social de la dependencia el contenido del reportaje y en un segundo momento a otro integrante del \u00e1rea. En un tercer acercamiento se envi\u00f3 un cuestionario el 19 de octubre pasado a trav\u00e9s de la Direcci\u00f3n de Comunicaci\u00f3n Social de Gobierno del Estado, pero previo a la publicaci\u00f3n tampoco se tuvo respuesta.<\/p>\n<p>Lidera Celaya en cad\u00e1veres sin reclamar<\/p>\n<p>Celaya es el municipio con m\u00e1s decesos sin reclamar, pues tiene un registro de 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos.<\/p>\n<p>Le sigue Le\u00f3n en segundo lugar con 49, de los cuales 44 son hombres, cuatro mujeres y uno sin identificar el sexo; sin embargo, se desconoce las causas de muerte.<\/p>\n<p>Contin\u00faa Salamanca con 21: son cinco hombres, dos mujeres y 14 sin identificar g\u00e9nero. San Miguel de Allende tiene 18 cuerpos y s\u00f3lo se conoce la causa de muerte de un hombre que fue baleado.<\/p>\n<p><strong>Sin identificar<\/strong><br \/>\nEn San Felipe son 13: ocho hombres, dos mujeres y tres sin identificar, de los cuales se sabe que dos eran ni\u00f1os y un reci\u00e9n nacido; el \u00faltimo cuerpo enviado a la fosa com\u00fan ingres\u00f3 el pasado 3 de octubre.<\/p>\n<p>La situaci\u00f3n en Guanajuato capital fue un registro de 11 hombres y una mujer; las causas: dos baleados, uno muerto a golpes, dos por trombosis pulmonar, uno por broncoaspiraci\u00f3n y el resto por problemas respiratorios.<\/p>\n<p>Fueron 11 hombres en Cortazar, s\u00f3lo se identific\u00f3 la causa de muerte de dos baleados y hay un fallecido a golpes.<br \/>\n<strong><br \/>\nEn otros municipios<\/strong><br \/>\nSan Jos\u00e9 Iturbide con 10: dos hombres muertos a golpes y dos mujeres, una fallecida por golpes y otra baleada. Mientras que de seis no se conoce el g\u00e9nero.<\/p>\n<p>Silao tambi\u00e9n tiene un reporte de 10 decesos, todos varones; s\u00f3lo se conoce que uno perdi\u00f3 la vida a causa de un infarto.<\/p>\n<p>El resto de los 17 municipios registra de uno a nueve cad\u00e1veres; por ejemplo, Comonfort tiene s\u00f3lo un hombre fallecido a golpes, Coroneo un joven de 20 a\u00f1os que muri\u00f3 por un disparo en la cabeza y Romita un ahogado en marzo pasado.<\/p>\n<p>En Tarandacuao son dos hombres, uno degollado; y en Villagr\u00e1n es una mujer ahogada y dos hombres, uno de ellos falleci\u00f3 a consecuencia de m\u00faltiples golpes.<\/p>\n<p>Once baleados, dos ahogados, 10 golpeados, tres estrangulados, un degollado, un atropellado, dos desmembrados, dos apu\u00f1alados, un asfixiado, un desnutrido, siete infartados, as\u00ed como tres fetos son apenas 44 registros de causa de muerte de los 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos de Celaya.<\/p>\n<p>Todas fueron enterrados sin recibir una ofrenda, flores, la luz de las velas, una plegaria e incluso sin tener qui\u00e9n llorara su partida.<\/p>\n<p>V\u00eda acceso a la informaci\u00f3n se obtuvieron datos de 26 de los 46 municipios del Estado, entre los que Celaya encabeza la lista de cuerpos sin identificar o reclamar de 2012 a septiembre pasado.<\/p>\n<p>Sin sepultura propia<\/p>\n<p>Pese a que los datos proporcionados por el Municipio identifican 44 causas de muerte, se desconoce el sexo de 84 cad\u00e1veres y s\u00f3lo se sabe que nueve eran varones.<\/p>\n<p>De 25 municipios tuvieron como destino final la fosa com\u00fan donde se entierran varios cad\u00e1veres sin tener una sepultura propia al no haber sido reclamados o identificados por sus familiares, sin recibir una l\u00e1grima o un adi\u00f3s.<\/p>\n<p>Personal de la Procuradur\u00eda General de Justicia del Estado (PGJE) inform\u00f3 que de 2012 al 31 de agosto pasado se tiene un registro de 360 muertos no identificados, as\u00ed como identificados pero no reclamados.<\/p>\n<p>Cuentan con resultados periciales forenses<\/p>\n<p>\u201cAl hallazgo de un cad\u00e1ver que no es posible su identificaci\u00f3n y no es reclamado, se resguarda en el Servicio M\u00e9dico Forense (Semefo) para integrar las indagatorias considerando las particularidades de la investigaci\u00f3n de cada caso\u201d.<\/p>\n<p>\u201cAdem\u00e1s se recaba, entre otros datos, los resultados periciales forenses (odontolog\u00eda y gen\u00e9tica), a afecto que, una vez agotadas las diligencias y protocolos establecidos la autoridad ministerial ordena la inhumaci\u00f3n del cad\u00e1ver\u201d, explicaron autoridades.<\/p>\n<p>Carecen panteones de registro<\/p>\n<p>De los 46 municipios de la entidad, 18 informaron que no cuentan con registros de env\u00edo de cuerpos a sus panteones p\u00fablicos, en otros casos aseguraron que no tienen fosa com\u00fan en los cementerios.<\/p>\n<p>De estos Ayuntamientos el que m\u00e1s sorprendi\u00f3 por su negativa a proporcionar datos es Irapuato; am solicit\u00f3 la informaci\u00f3n en tres ocasiones, pero fue negada porque \u201cno pudieron comprender la pregunta\u201d, a diferencia de los 45 municipios restantes.<\/p>\n<p>Lo anterior pese a tener el antecedente de un alto \u00edndice en ejecuciones, adem\u00e1s de ser el segundo municipio m\u00e1s poblado de la entidad.<\/p>\n<p>No proporciona informaci\u00f3n<\/p>\n<p>Otros casos contradictorios son San Diego de la Uni\u00f3n y San Felipe, donde en una primera solicitud realizada antes del cambio de administraci\u00f3n municipal contestaron que no contaban con registro de cuerpos enviados a la fosa com\u00fan, pero en una segunda solicitud que recibi\u00f3 la actual administraci\u00f3n s\u00ed brindaron las cifras.<\/p>\n<p>Durante mes y medio se busc\u00f3 tratar el tema con la Procuradur\u00eda General de Justicia del Estado de Guanajuato (PGJE), pero no hubo respuesta.<\/p>\n<p>Se explic\u00f3 al responsable de Comunicaci\u00f3n Social de la dependencia el contenido del reportaje y en un segundo momento a otro integrante del \u00e1rea. En un tercer acercamiento se envi\u00f3 un cuestionario el 19 de octubre pasado a trav\u00e9s de la Direcci\u00f3n de Comunicaci\u00f3n Social de Gobierno del Estado, pero previo a la publicaci\u00f3n tampoco se tuvo respuesta.<\/p>\n<p>Lidera Celaya en cad\u00e1veres sin reclamar<\/p>\n<p>Celaya es el municipio con m\u00e1s decesos sin reclamar, pues tiene un registro de 93 cuerpos enviados a la fosa com\u00fan en los panteones p\u00fablicos.<\/p>\n<p>Le sigue Le\u00f3n en segundo lugar con 49, de los cuales 44 son hombres, cuatro mujeres y uno sin identificar el sexo; sin embargo, se desconoce las causas de muerte.<\/p>\n<p>Contin\u00faa Salamanca con 21: son cinco hombres, dos mujeres y 14 sin identificar g\u00e9nero. San Miguel de Allende tiene 18 cuerpos y s\u00f3lo se conoce la causa de muerte de un hombre que fue baleado.<\/p>\n<p>Sin identificar<\/p>\n<p>En San Felipe son 13: ocho hombres, dos mujeres y tres sin identificar, de los cuales se sabe que dos eran ni\u00f1os y un reci\u00e9n nacido; el \u00faltimo cuerpo enviado a la fosa com\u00fan ingres\u00f3 el pasado 3 de octubre.<\/p>\n<p>La situaci\u00f3n en Guanajuato capital fue un registro de 11 hombres y una mujer; las causas: dos baleados, uno muerto a golpes, dos por trombosis pulmonar, uno por broncoaspiraci\u00f3n y el resto por problemas respiratorios.<\/p>\n<p>Fueron 11 hombres en Cortazar, s\u00f3lo se identific\u00f3 la causa de muerte de dos baleados y hay un fallecido a golpes.<\/p>\n<p>En otros municipios<\/p>\n<p>San Jos\u00e9 Iturbide con 10: dos hombres muertos a golpes y dos mujeres, una fallecida por golpes y otra baleada. Mientras que de seis no se conoce el g\u00e9nero.<\/p>\n<p>Silao tambi\u00e9n tiene un reporte de 10 decesos, todos varones; s\u00f3lo se conoce que uno perdi\u00f3 la vida a causa de un infarto.<\/p>\n<p>El resto de los 17 municipios registra de uno a nueve cad\u00e1veres; por ejemplo, Comonfort tiene s\u00f3lo un hombre fallecido a golpes, Coroneo un joven de 20 a\u00f1os que muri\u00f3 por un disparo en la cabeza y Romita un ahogado en marzo pasado.<\/p>\n<p>En Tarandacuao son dos hombres, uno degollado; y en Villagr\u00e1n es una mujer ahogada y dos hombres, uno de ellos falleci\u00f3 a consecuencia de m\u00faltiples golpes.<br \/>\n<strong><br \/>\nAl detalle<\/strong><\/p>\n<p>La fosa com\u00fan es un hoyo profundo que puede albergar hasta 40 cuerpos, los cuales son cubiertos con arena y cal, formando capas. Es decir, se encima un cad\u00e1ver sobre otro.<\/p>\n<p>El dep\u00f3sito en la fosa com\u00fan puede ser de dos formas: por exhumaci\u00f3n administrativa, que es un cuerpo que cumple el plazo permitido de entierro en el pante\u00f3n y los restos no son reclamados por el familiar; y los cuerpos no reclamados ni identificados desde el Servicio M\u00e9dico Forense (Semefo).<\/p>\n<p>Estos cuerpos catalogados en los registros oficiales \u00fanicamente como \u201cNN\u201d, que significa \u201cNing\u00fan Nombre\u201d, o como \u201cSI\u201d (Sin Identificar), permanecieron en c\u00e1mara de refrigeraci\u00f3n con una capacidad para almacenar entre 30 y 40 muertos que luego son enterrados en el anonimato.<\/p>\n<p><a href=\"https:\/\/www.am.com.mx\/2019\/01\/07\/local\/leon-caen-olvidados-en-fosa-comun-guanajuato-sin-identificar-537419\">https:\/\/www.am.com.mx\/2019\/01\/07\/local\/leon-caen-olvidados-en-fosa-comun-guanajuato-sin-identificar-537419<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luz Elena Escobar, Le\u00f3n Guanajuato. AM-Le\u00f3n Guanajuato. 7 de enero de 2019 Carecen municipios de registros sobre cuerpos sin identificar o sin reclamar por familiares; algunos ni tumba general tienen. &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2019\/01\/07\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":28220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,1432,17,471,2],"tags":[121,1133],"class_list":{"0":"post-28219","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-cintillo","8":"category-desaparecidos-en-guanajuato","9":"category-guanajuato","11":"category-noticias-nacionales","12":"tag-desaparecidos","13":"tag-incremento-en-la-violencia","14":"entry"},"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/01\/nadie-los-reclamo-y-fueron-enterrados-en-alguna-fosa-comun-de-guanajuato-485637ea0f6a24719ab4747ebf16d81a.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-7l9","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":64238,"url":"https:\/\/www.grieta.org.mx\/index.php\/2022\/05\/13\/colectivos-hallan-18-cuerpos-en-fosa-clandestina-de-guanajuato\/","url_meta":{"origin":28219,"position":0},"title":"Colectivos hallan 18 cuerpos en fosa clandestina de Guanajuato","author":"grieta","date":"13 mayo, 2022","format":false,"excerpt":"El colectivo \u201cMadres Guerreras de Le\u00f3n\u201d informaron que recuperaron los restos de 10 hombres y ocho mujeres, que fueron inhumados; en un punto cercano a la comunidad de Comanja, fue desmantelado un centro de operaciones del C\u00e1rtel Jalisco Nueva Generaci\u00f3n en noviembre del 2020. Por Ver\u00f3nica Espinosa, Proceso viernes, 13\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/05\/f800x450-154748_206194_5050.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/05\/f800x450-154748_206194_5050.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/05\/f800x450-154748_206194_5050.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/05\/f800x450-154748_206194_5050.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":58158,"url":"https:\/\/www.grieta.org.mx\/index.php\/2021\/03\/18\/hallan-22-cuerpos-en-fosa-de-celaya-autoridades-esperan-encontrar-mas\/","url_meta":{"origin":28219,"position":1},"title":"Hallan 22 cuerpos en fosa de Celaya; autoridades esperan encontrar m\u00e1s","author":"grieta","date":"18 marzo, 2021","format":false,"excerpt":"Autoridades presumen que el predio donde fueron hallados los restos humanos podr\u00eda guardar la mayor cantidad de hallazgos en Guanajuato hasta el momento. AFP, Animal Po\u00edtico, 18 de marzo de 2021 Los cad\u00e1veres de al menos 22 personas fueron localizados en una fosa clandestina en el municipio de Celaya, en\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/cuartoscuro_783110_digital.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/cuartoscuro_783110_digital.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/cuartoscuro_783110_digital.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/cuartoscuro_783110_digital.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/cuartoscuro_783110_digital.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/cuartoscuro_783110_digital.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":64501,"url":"https:\/\/www.grieta.org.mx\/index.php\/2022\/05\/16\/en-guanajuato-se-reportan-91-fosas-clandestinas-encontradas-durante-el-2021-y-2022\/","url_meta":{"origin":28219,"position":2},"title":"En Guanajuato se reportan 91 fosas clandestinas encontradas durante el 2021 y 2022","author":"grieta","date":"16 mayo, 2022","format":false,"excerpt":"En 2021 y lo que va del 2022 se hallaron 91 fosas clandestinas en Guanajuato, de acuerdo con los registros de la Comisi\u00f3n Estatal de B\u00fasqueda de Personas Desaparecidas (CEB). AM, Le\u00f3n Gunajauato Por Daniel Gilberto Mart\u00ednez Mac\u00edas lunes, 16 de mayo de 2022 Guanajuato.- En 2021 y lo que\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/07\/f800x450-353291_404737_5050.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/07\/f800x450-353291_404737_5050.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/07\/f800x450-353291_404737_5050.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/07\/f800x450-353291_404737_5050.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":67854,"url":"https:\/\/www.grieta.org.mx\/index.php\/2023\/09\/18\/buscadoras-acuden-a-hallazgo-de-fosa-y-policia-de-irapuato-responde-con-detencion-y-amenazas-guanajuato\/","url_meta":{"origin":28219,"position":3},"title":"Buscadoras acuden a hallazgo de fosa y Polic\u00eda de Irapuato responde con detenci\u00f3n y amenazas (Guanajuato)","author":"grieta","date":"18 septiembre, 2023","format":false,"excerpt":"Imagen: Zona Docs \u201cTe faltan unos buenos putazos\u201d fue la amenaza de preventivos municipales a Karla Mart\u00ednez, integrante de la Brigada Independiente al llegar a una fosa resguardada por la corporaci\u00f3n en la comunidad El Conejo Edith Dom\u00ednguez \/ Zona Docs Guanajuato se ha convertido en el estado m\u00e1s violento\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/PORTADA_POP-LAB_AGRESIONES-BUSCADORAS-GUANAJUATO-1068x391-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/PORTADA_POP-LAB_AGRESIONES-BUSCADORAS-GUANAJUATO-1068x391-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/PORTADA_POP-LAB_AGRESIONES-BUSCADORAS-GUANAJUATO-1068x391-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/PORTADA_POP-LAB_AGRESIONES-BUSCADORAS-GUANAJUATO-1068x391-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/10\/PORTADA_POP-LAB_AGRESIONES-BUSCADORAS-GUANAJUATO-1068x391-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":52976,"url":"https:\/\/www.grieta.org.mx\/index.php\/2020\/08\/25\/gobierno-de-guanajuato-niega-tener-fosas-clandestinas-prensa-registra-109\/","url_meta":{"origin":28219,"position":4},"title":"Gobierno de Guanajuato niega tener fosas clandestinas; prensa registra 109","author":"grieta","date":"25 agosto, 2020","format":false,"excerpt":"Por Redacci\u00f3n Animal Pol\u00edtico 25 de agosto de 2020 Entre 2009 y 2020, de acuerdo con informaci\u00f3n de medios locales, en el estado de Guanajuato se han encontrado 109 fosas clandestinas, de las cuales se han exhumado 268 cuerpos. Seg\u00fan el Informe sobre la situaci\u00f3n de fosas clandestinas en el\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/cuartoscuro_773029_digital-e1598375600495.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/cuartoscuro_773029_digital-e1598375600495.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/cuartoscuro_773029_digital-e1598375600495.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/cuartoscuro_773029_digital-e1598375600495.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/cuartoscuro_773029_digital-e1598375600495.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/09\/cuartoscuro_773029_digital-e1598375600495.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":65771,"url":"https:\/\/www.grieta.org.mx\/index.php\/2022\/11\/21\/todos-celebrando-el-cervantino-y-nosotras-desenterrando-cuerpos-la-otra-cara-que-se-vive-en-guanajuato\/","url_meta":{"origin":28219,"position":5},"title":"&#8220;Todos celebrando el Cervantino y nosotras desenterrando cuerpos&#8221;: la otra cara que se vive en Guanajuato","author":"grieta","date":"21 noviembre, 2022","format":false,"excerpt":"Bibiana Mendoza, fundadora de Hasta Encontrarte, comparte la historia que se vive en uno de los estados m\u00e1s pr\u00f3speros y violentos de M\u00e9xico, donde desde octubre, el colectivo y un grupo de forenses han exhumado 53 fundas con restos que intentan identificar AFP \/ El universal, 21\/XI\/2022 Mientras sonaban aplausos\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/11\/https-__www.eluniversal.com_.mx_sites_default_files_2022_11_21_desapariciones_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/11\/https-__www.eluniversal.com_.mx_sites_default_files_2022_11_21_desapariciones_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/11\/https-__www.eluniversal.com_.mx_sites_default_files_2022_11_21_desapariciones_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/11\/https-__www.eluniversal.com_.mx_sites_default_files_2022_11_21_desapariciones_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/11\/https-__www.eluniversal.com_.mx_sites_default_files_2022_11_21_desapariciones_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/28219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=28219"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/28219\/revisions"}],"predecessor-version":[{"id":28222,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/28219\/revisions\/28222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/28220"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=28219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=28219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=28219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}