{"id":17351,"date":"2016-06-14T22:21:41","date_gmt":"2016-06-15T03:21:41","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=17351"},"modified":"2016-07-21T22:27:06","modified_gmt":"2016-07-22T03:27:06","slug":"queretaro-niega-gobierno-panista-desapariciones-forzadas","status":"publish","type":"post","link":"https:\/\/www.grieta.org.mx\/index.php\/2016\/06\/14\/queretaro-niega-gobierno-panista-desapariciones-forzadas\/","title":{"rendered":"Quer\u00e9taro: Niega Gobierno panista desapariciones forzadas"},"content":{"rendered":"<p>Iv\u00e1n Aldama Garnica\/Libertad de palabra<\/p>\n<p>Quer\u00e9taro, Qro.- El documento tiene diferente n\u00famero de oficio y es firmado por un funcionario distinto, pero su contenido es similar al que fuera p\u00fablico por este semanario hace un a\u00f1o.<\/p>\n<p>En la entonces Procuradur\u00eda de Quer\u00e9taro \u2013ahora Fiscal\u00eda\u2013, que encabeza Alejandro Echeverr\u00eda Cornejo, reportaron al Comit\u00e9 de Seguimiento de la \u201cLey para Prevenir, Investigar, Sancionar y Reparar la Desaparici\u00f3n de Personas en el Estado de Quer\u00e9taro\u201d, que no existen casos de personas que encuadren en los delitos de desaparici\u00f3n forzada o desaparici\u00f3n por particulares.<\/p>\n<p>\u201cDe los 408 reportes de personas no localizadas vigentes, hasta el momento no existen datos para afirmar que se configuren delitos de desaparici\u00f3n forzada o desaparici\u00f3n por particulares en t\u00e9rminos de los art\u00edculos 4 y 5 de la Ley para Prevenir, Investigar, Sancionar y Reparar la Desaparici\u00f3n Forzada en el Estado de Quer\u00e9taro\u201d, se lee en el oficio n\u00famero DIDH\/825\/2016 que firma la licenciada Gisela B\u00e1rcenas Mandujano, directora de Derechos Humanos de la actual Fiscal\u00eda de Quer\u00e9taro.<br \/>\nGobernador de Quer\u00e9taro y su secretario de Gobierno.<\/p>\n<p>La cita es semejante a la que reprodujo Libertad de Palabra en su edici\u00f3n 375 de febrero de 2015, cuando a\u00fan gobernaba el priista Jos\u00e9 Eduardo Calzada Rovirosa.<\/p>\n<p>\u201cNo existe averiguaci\u00f3n previa, carpeta de investigaci\u00f3n, o proceso alguno que haya iniciado por hechos probablemente constitutivos de delito de Desaparici\u00f3n Forzada, ni por el delito de Desaparici\u00f3n de Personas por Particulares\u201d, report\u00f3 en un oficio al mismo Comit\u00e9, el entonces procurador Arsenio Dur\u00e1n Becerra.<\/p>\n<p>En el Gobierno del panista Francisco Dom\u00ednguez Servi\u00e9n, como en el de su antecesor, consideran que no existen casos de desaparici\u00f3n forzada de personas o por particulares en Quer\u00e9taro.<\/p>\n<p>Por el contrario, reportan que existen 408 casos de personas \u201cno localizadas\u201d, algunas de las cuales, dicen, se fueron voluntariamente o porque en su familia eran v\u00edctimas de violencia o abuso.<\/p>\n<blockquote><p> \u201cYo quiero trabajar con ustedes, yo alc\u00e9 la voz por ustedes, cuando estaba en campa\u00f1a, que la autoridad, el Gobierno que termina nunca los atendi\u00f3, nunca quiso enfrentar, nunca quiso decirles el n\u00famero de desaparecidas y desparecidos, y el procurador pasado nunca quiso hablar del tema\u201d:<\/p>\n<p>    el gobernador Francisco Dom\u00ednguez el 10 de noviembre de 2015.\n<\/p><\/blockquote>\n<p>El documento que la directora de Derechos Humanos de la Procuradur\u00eda de Quer\u00e9taro dirige a Miguel Nava Alvarado, presidente del Comit\u00e9, y que tiene como fecha el 11 de mayo de 2016, se da cuenta de que hasta el 30 de abril del presente a\u00f1o existen 408 casos de personas no localizadas, las cuales desglosan de la siguiente manera:<\/p>\n<p>1 por accidente; 70 por migraci\u00f3n; 21 por motivos laborales; 13 por problemas de adicci\u00f3n; 19 por problemas de salud; 42 por problemas familiares; 13 por relaciones personales; 13 v\u00edctimas de alg\u00fan delito; y 216 por voluntad propia.<\/p>\n<p>Si bien, las autoridades de la Procuradur\u00eda indican que se trata de datos recabados por el personal de la Unidad Especializada en B\u00fasqueda de Personas (UEBP) conformada en enero de este a\u00f1o, no detallan los delitos que fueron cometidos en 13 de los 408 casos.<\/p>\n<p>Tampoco agregan el periodo al que pertenece esta cifra de 408 personas que consideran como \u201cno localizadas\u201d, es decir a qu\u00e9 a\u00f1o corresponden todos y cada uno de los casos.<\/p>\n<p>El martes 10 de mayo, familiares de personas desaparecidas, integradas en la asociaci\u00f3n Desaparecidos Justicia, denunciaron una incompetencia e ineptitud de las autoridades queretanas para buscar y localizar a sus seres queridos, en especial de los servidores p\u00fablicos que integran la UEBP.<\/p>\n<p>\u201c\u2026 no sabe ni tiene la menor idea de c\u00f3mo buscar a nuestros hijos, los agentes del Ministerio P\u00fablico que integran dicha unidad, son completamente ignorantes e incapaces de llevar a cabo la investigaci\u00f3n de nuestros casos, insisten en buscar e investigar detr\u00e1s del escritorio enviando s\u00f3lo oficios de colaboraci\u00f3n, adem\u00e1s de violar nuestros derechos y los de los nuestros con su falta de sensibilidad e ignorancia sobre derechos humanos\u201d, dijo la representante de Desaparecidos Justicia, Yadira Gonz\u00e1lez Hern\u00e1ndez, quien busca a su hermano Juan desde 2006.<\/p>\n<p>Tan s\u00f3lo en esta asociaci\u00f3n denunciaron, durante su protesta afuera de la sede del Gobierno Estatal, que tienen 27 casos de personas desaparecidas.<br \/>\nEn Quer\u00e9taro las autoridades dicen que no hay desaparecidos.<\/p>\n<p>Sin embargo, la entonces SubProcuradora de Prevenci\u00f3n del Delito, Atenci\u00f3n a V\u00edctimas y Derechos Humanos dela Procuradur\u00eda de Quer\u00e9taro, Margarita Luna T\u00e9llez Gir\u00f3n, aclar\u00f3 que algunos de los casos que denuncian en esta asociaci\u00f3n ocurrieron en otros estados del pa\u00eds.<\/p>\n<p>La funcionaria que hoy tiene el cargo de Vice Fiscal de Derechos Humanos y Desarrollo Institucional en la Fiscal\u00eda, dijo que no recordaba la proporci\u00f3n de los casos de Desaparecidos Justicia que no ocurrieron en el estado de Quer\u00e9taro y ofreci\u00f3 proporcionarla en una entrevista en su oficina; pero despu\u00e9s repuso que por confidencialidad no deb\u00eda entregarlos datos.<\/p>\n<p>\u201cEs una falta de respeto para las v\u00edctimas\u201d, dijo.<\/p>\n<p>Los integrantes de Desaparecidos Justicia tambi\u00e9n demandaron al mandatario estatal, Francisco Dom\u00ednguez, una reuni\u00f3n para el mi\u00e9rcoles 18 de mayo \u2013que no ocurri\u00f3\u2013, tras acusar que no ha asumido el compromiso \u2013que realiz\u00f3 en noviembre de 2015\u2013 de hacer equipo con ellos para trabajar y avanzar en los casos de personas desaparecidas.<\/p>\n<p>\u201c\u2026 lamentamos que a sus palabras se la ha llevado el viento y que la confianza que en ese momento nos pidi\u00f3, ha sido rota por su gobierno, ya que no han hecho otra cosa m\u00e1s que mentirnos y revictimizarnos con su ignorancia e incapacidad para buscar a nuestros hijos\u201d, expusieron durante la protesta del 10 de mayo afuera de la oficina del mandatario.<\/p>\n<p>Durante parte de su administraci\u00f3n, el ex gobernador priista, Jos\u00e9 Eduardo Calzada Rovirosa, tambi\u00e9n evadi\u00f3 atender las demandas de los integrantes de Desaparecidos Justicia.<br \/>\nLA QUINTA Y CONTANDO<\/p>\n<p>Por quinta vez, desde su creaci\u00f3n a finales del 2014, fue cancelada la sesi\u00f3n del Comit\u00e9 de Seguimiento de la \u201cLey para Prevenir, Investigar, Sancionar y Reparar la Desaparici\u00f3n de Personas en el Estado de Quer\u00e9taro\u201d.<\/p>\n<p>La constante en el Gobierno del priista Jos\u00e9 Eduardo Calzada Rovirosa fue la inasistencia de gran parte de sus 38 integrantes (en donde hay representantes de los tres poderes del Estado, de los 18 municipios o de medios de comunicaci\u00f3n), pero durante el Gobierno de su sucesor, Francisco Dom\u00ednguez Servi\u00e9n, los funcionarios involucrados tampoco asisten.<\/p>\n<p>La d\u00e9cima sesi\u00f3n del Comit\u00e9 de Seguimiento, prevista para el jueves 12 de mayo, tuvo que ser suspendida por la inasistencia de 12 de sus miembros, lo cual entorpece los trabajos para elaborar el Programa Estatal para prevenir y combatir esta problem\u00e1tica en la entidad, se\u00f1al\u00f3 el presidente de dicho Comit\u00e9, Miguel Nava Alvarado.<\/p>\n<p><a href=\"http:\/\/www.libertaddepalabra.com\/2016\/06\/queretaro-niega-gobierno-panista-desapariciones-forzadas\/\" target=\"_blank\">http:\/\/www.libertaddepalabra.com\/2016\/06\/queretaro-niega-gobierno-panista-desapariciones-forzadas\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iv\u00e1n Aldama Garnica\/Libertad de palabra Quer\u00e9taro, Qro.- El documento tiene diferente n\u00famero de oficio y es firmado por un funcionario distinto, pero su contenido es similar al que fuera p\u00fablico &hellip; <a href=\"https:\/\/www.grieta.org.mx\/index.php\/2016\/06\/14\/queretaro-niega-gobierno-panista-desapariciones-forzadas\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":21928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80],"tags":[121],"class_list":["post-17351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","tag-desaparecidos","entry"],"jetpack_featured_media_url":"https:\/\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-4vR","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":67101,"url":"https:\/\/www.grieta.org.mx\/index.php\/2023\/06\/19\/en-jalisco-solo-4-de-cada-100-personas-detenidas-por-el-delito-de-desaparicion-reciben-sentencias-condenatorias\/","url_meta":{"origin":17351,"position":0},"title":"En Jalisco, s\u00f3lo 4 de cada 100 personas detenidas por el delito de desaparici\u00f3n reciben sentencias condenatorias","author":"grieta","date":"19 junio, 2023","format":false,"excerpt":"Imagen: Zona Docs Darwin Franco \/ Zona Docs En Jalisco, la impunidad en torno a la comisi\u00f3n de los delitos de desaparici\u00f3n forzada y desaparici\u00f3n cometida por particulares\u00a0es del 96%, esto significa que s\u00f3lo cuatro de cada 100 detenciones por la presunta comisi\u00f3n de estos delitos han culminado con una\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/06\/photo1684468153-2-1068x848-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/06\/photo1684468153-2-1068x848-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/06\/photo1684468153-2-1068x848-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/06\/photo1684468153-2-1068x848-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/06\/photo1684468153-2-1068x848-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4632,"url":"https:\/\/www.grieta.org.mx\/index.php\/2015\/11\/10\/familiares-de-desaparecidos-marchan-en-queretaro\/","url_meta":{"origin":17351,"position":1},"title":"Familiares de desaparecidos marchan en Quer\u00e9taro","author":"grieta","date":"10 noviembre, 2015","format":false,"excerpt":"Eric Pacheco\/Proceso El gobernador de Quer\u00e9taro, el panista Francisco Dom\u00ednguez Servi\u00e9n, admiti\u00f3 esta tarde que, luego de un mes y 10 d\u00edas de tomar el cargo, ignora la cifra de personas desaparecidas en el estado. Familiares de personas desaparecidas marcharon desde la Universidad Aut\u00f3noma de Quer\u00e9taro hasta las afueras de\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":41102,"url":"https:\/\/www.grieta.org.mx\/index.php\/2019\/11\/07\/tenemos-la-recomendacion-pero-lo-que-nosotros-queremos-es-a-hector-brenda-rangel-queretaro\/","url_meta":{"origin":17351,"position":2},"title":"\u201cTenemos la recomendaci\u00f3n, pero lo que nosotros queremos es a H\u00e9ctor\u201d: Brenda Rangel (Quer\u00e9taro)","author":"grieta","date":"7 noviembre, 2019","format":false,"excerpt":"Mauricio Hern\u00e1ndez \/ C\u00f3digo Quer\u00e9taro A punto de cumplirse 10 a\u00f1os sin que se conozca el paradero de H\u00e9ctor Rangel Ortiz, Irene Lugo Hern\u00e1ndez y Milton Hugo Aguilar Torres, la recomendaci\u00f3n emitida por la Comisi\u00f3n Nacional de los Derechos Humanos (CNDH) ha causado sorpresa entre los familiares de los tres\u2026","rel":"","context":"En &quot;Abuso policiaco y tortura en Quer\u00e9taro&quot;","block_context":{"text":"Abuso policiaco y tortura en Quer\u00e9taro","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/queretaro\/abuso-policiaco-y-tortura-en-queretaro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/%E2%80%9CTenemos-la-recomendaci%C3%B3n-pero-lo-que-nosotros-queremos-es-a-H%C3%A9ctor%E2%80%9D-Brenda-Rangel-qro-nov.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/%E2%80%9CTenemos-la-recomendaci%C3%B3n-pero-lo-que-nosotros-queremos-es-a-H%C3%A9ctor%E2%80%9D-Brenda-Rangel-qro-nov.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/11\/%E2%80%9CTenemos-la-recomendaci%C3%B3n-pero-lo-que-nosotros-queremos-es-a-H%C3%A9ctor%E2%80%9D-Brenda-Rangel-qro-nov.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4629,"url":"https:\/\/www.grieta.org.mx\/index.php\/2015\/11\/18\/reporta-tek-332-desaparecidos-en-queretaro-durante-2015\/","url_meta":{"origin":17351,"position":3},"title":"Reporta T\u2019ek\u2019 332 desaparecidos en Quer\u00e9taro durante 2015","author":"grieta","date":"18 noviembre, 2015","format":false,"excerpt":"Redacci\u00f3n\/Quadrat\u00edn El Grupo T\u00b4ek\u00b4ei exigi\u00f3 informaci\u00f3n sobre la situaci\u00f3n actual de las personas que siguen o estuvieron en condici\u00f3n de desaparici\u00f3n El Grupo T\u00b4ek\u00b4ei inform\u00f3 que de enero al 15 de noviembre de 2015 fueron reportadas como desaparecidas 332 personas; 174 de ellas son mujeres (116 ni\u00f1as y 58 adultas)\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22961,"url":"https:\/\/www.grieta.org.mx\/index.php\/2017\/04\/26\/urgen-ongs-ley-de-desaparicion-forzada-tamaulipas\/","url_meta":{"origin":17351,"position":4},"title":"Urgen ONGs ley de desaparici\u00f3n forzada (Tamaulipas)","author":"grieta","date":"26 abril, 2017","format":false,"excerpt":"Redacci\u00f3n\/El Ma\u00f1ana Colectivos de familiares de personas desaparecidas y organizaciones civiles que las acompa\u00f1an exigieron al Congreso de la Uni\u00f3n aprobar ya la Ley General sobre Desaparici\u00f3n Forzada y Desaparici\u00f3n por Particulares, aunque a\u00fan advierten deficiencias. \"Invitamos al Senado a que apruebe la Ley, pero s\u00ed manifestamos algunas reservas, que\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/05\/d5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/05\/d5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/05\/d5.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3533,"url":"https:\/\/www.grieta.org.mx\/index.php\/2015\/07\/31\/en-zacatecas-4-militares-estan-procesados-por-desaparicion-forzada\/","url_meta":{"origin":17351,"position":5},"title":"En Zacatecas, 4 militares est\u00e1n procesados por desaparici\u00f3n forzada","author":"grieta","date":"31 julio, 2015","format":false,"excerpt":"31 julio, 2015 Sopitas.com Cuatro militares del 97 Batall\u00f3n de Infanter\u00eda de la onceava zona militar de Guadalupe, Zacatecas est\u00e1n siendo investigados por desaparici\u00f3n forzada y homicidio calificado contra siete personas por una ejecuci\u00f3n ocurrida el pasado 7 de julio en el municipio de Calera del estado. De acuerdo con\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"https:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/17351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=17351"}],"version-history":[{"count":1,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/17351\/revisions"}],"predecessor-version":[{"id":17353,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/17351\/revisions\/17353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/21928"}],"wp:attachment":[{"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=17351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=17351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=17351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}