{"id":970,"date":"2016-03-02T01:35:04","date_gmt":"2016-03-02T01:35:04","guid":{"rendered":"http:\/\/50.22.11.12\/~grietaor\/?p=970"},"modified":"2016-03-03T01:43:52","modified_gmt":"2016-03-03T01:43:52","slug":"hasta-policias-utiliza-seduc-para-retirar-a-maestros-en-resistencia","status":"publish","type":"post","link":"http:\/\/www.grieta.org.mx\/index.php\/2016\/03\/02\/hasta-policias-utiliza-seduc-para-retirar-a-maestros-en-resistencia\/","title":{"rendered":"Hasta polic\u00edas utiliza Seduc para retirar a maestros en resistencia"},"content":{"rendered":"<p>Por Ronny Aguilar<\/p>\n<p>CAMPECHE, Cam. 1 de marzo del 2016.- Padres de familia respaldaron a docentes cesados el d\u00eda de ayer, exigieron a las autoridades que se les permita terminar el ciclo escolar y se\u00f1alaron que loa maestros no son flojos, como se difunde oficialmente, despu\u00e9s de que les fue impedido el paso a su centro laboral.<\/p>\n<p>El secretario estatal de Educaci\u00f3n, Ricardo Medina Farf\u00e1n, afirm\u00f3 que solo est\u00e1 cumpliendo la ley y que no hay marcha atr\u00e1s en el cese, y expres\u00f3 que los profesores se van por acciones legales.<\/p>\n<p>El d\u00eda de hoy, la entrada a clases para los alumnos de los maestros cesados se complic\u00f3, pues las madres de familia, en su mayor\u00eda, no permitieron el acceso de los menores, sino era con sus respectivos maestros, a quienes los directores de las escuelas no permitieron ingresar, adem\u00e1s de estar acompa\u00f1ados por los supervisores de zona y personal, que se dijo jur\u00eddico, de la Secretar\u00eda de Educaci\u00f3n.<\/p>\n<p>La jornada de resistencia de los maestros comenz\u00f3 en la emblem\u00e1tica escuela \u201cJusto Sierra M\u00e9ndez\u201d, en donde no se le dej\u00f3 entrar al docente Oscar Manuel Uc Tuz, del segundo grado, grupo C, lo que caus\u00f3 la molestia de los paterfamilias que dieron a conocer en d\u00edas pasados el respaldo al docente.<\/p>\n<p>Los progenitores se confrontaron verbalmente con la direcci\u00f3n de la escuela y la representaci\u00f3n de la secretar\u00eda, pues se\u00f1alaron que no puede ser que le quiten a sus hijos al maestro a mediados de ciclo escolar, maestro que ha sido su gu\u00eda en los dos primeros a\u00f1os de escolaridad primaria.<\/p>\n<p>Asimismo, manifestaron que el maestro ha demostrado una verdadera vocaci\u00f3n, pues incluso enfermo y con problemas en la voz, ha estado presente atendiendo a los menores, por lo que no cesaron de manifestar su inconformidad ante la presencia del profesor que, durante todo el tiempo que duran las clases, estuvo de pie junto a la puerta, hasta terminado su horario de clase, cuando se retir\u00f3.<\/p>\n<p>En donde las acciones de los maestros tomaron otro nivel fue en la escuela preescolar \u201cJoaquin Lanz Paullada\u201d o por su raz\u00f3n social de \u201cNueva Creaci\u00f3n\u201d, en donde el respaldo de las madres y padres de familia permiti\u00f3 el acceso de las maestras a la escuela y con eso se origin\u00f3 la intervenci\u00f3n de los polic\u00edas estatales, autoridades educativas e incluso, el mismo secretario de Educaci\u00f3n, Ricardo Medina, acudi\u00f3 para intentar dar soluci\u00f3n a la problem\u00e1tica.<\/p>\n<p>Y es que los padres de familia tampoco dejaron pasar a sus hijos, aunque hay que mencionar la presencia de la sociedad de tres madres de familia, ligadas a la burocracia local, que en todo momento expresaron su molestia por la acci\u00f3n de las maestras y denostando su trabajo, mientras que los dem\u00e1s padres de familia con competencia directa, manifestaron su apoyo y el repudio a la Reforma Educativa.<\/p>\n<p>Justamente, la presi\u00f3n de los padres provoc\u00f3 que la reja de la escuela cediera ante empujones y permitiera la entrada a las maestras cesadas, Cristina Ku Dzul y Diana Karina Coll\u00ed Uc, ambas con m\u00e1s de 10 a\u00f1os de servicio.<\/p>\n<p>Los empujones y jalones a la hora del ingreso de maestras ocasiono las l\u00e1grimas de varios menores, por lo que puso tenso el ambiente por unos minutos, una vez adentro, las maestras se dirigieron a sus salones y de ah\u00ed no se movieron hasta pasadas las dos de la tarde.<\/p>\n<p>Durante ese tiempo, se aperson\u00f3 la Polic\u00eda Estatal a las afueras de la escuela, y por orden de la supervisora de zona, se pidi\u00f3 a los progenitores que formaran una comitiva, que ingresara y se le expresara c\u00f3mo estaba la circunstancia de las maestras, acci\u00f3n que se realiz\u00f3 alrededor de las 10 de la ma\u00f1ana, con la presencia del subsecretario de Educaci\u00f3n B\u00e1sica, Rafael Mart\u00ednez Castro, quien fue el primer funcionario en apersonarse.<\/p>\n<p>No hay marcha atr\u00e1s de la Seduc<\/p>\n<p>Posteriormente, al lugar tambi\u00e9n lleg\u00f3 el secretario de Educaci\u00f3n, quien en entrevista exclusiva a Paginabierta.mx, dijo que el cese esta realizado y no hay marcha atr\u00e1s de parte de la Secretar\u00eda, y expres\u00f3 que las oportunidades fueron dadas y lo maestros las rechazaron.<\/p>\n<p>Plante\u00f3 que los docentes tendr\u00e1n lo que a su derecho convenga en relaci\u00f3n al cese, o sea, que est\u00e1n conscientes de las diversas acciones que han manifestado que iniciar\u00e1n, aunque afirm\u00f3 que la Suprema Corte de Justicia de la Naci\u00f3n ha determinado la procedencia de la Reforma Educativa y la no retroactividad de la ley en el caso espec\u00edfico.<\/p>\n<p>De la misma forma, mencion\u00f3 que la notificaci\u00f3n realizada por la Secretar\u00eda local tiene validez y que no es necesario que la Federaci\u00f3n intervenga, aun con la centralizaci\u00f3n de la educaci\u00f3n, ya que los maestros son empleados de Campeche.<\/p>\n<p>\u201cLos trabajadores son trabajadores de esta Secretar\u00eda, dependen administrativamente de la Secretar\u00eda de Educaci\u00f3n del Estado de Campeche, nosotros, en nuestro car\u00e1cter de patr\u00f3n, tenemos el derecho de ejecutar este tipo de acciones, porque son maestros que no participaron en la evaluaci\u00f3n, a pesar de estar programados, eventualmente, el servicio profesional docente nos avisa que estos maestros no ten\u00edan registro de evaluaci\u00f3n y nos emplaza para que se obtenga el registro para acciones de ley\u201d, explic\u00f3.<\/p>\n<p>Dio a conocer que no habr\u00e1 acciones legales contra las maestras por la irrupci\u00f3n en la escuela, aunque se les demandar\u00e1, en caso de que se repita.<\/p>\n<p>Regresar\u00e1n ma\u00f1ana maestras<\/p>\n<p>Las docentes, al salir de la escuela, indicaron que se les hizo sacar, con ayuda de los padres de familia, todo su material did\u00e1ctico, adem\u00e1s de diferentes amenazas legales de parte de la autoridad educativa por el ingreso a la escuela, asimismo, se les indic\u00f3 que no hay procedimiento legal que puedan emplear para con relaci\u00f3n a su cese.<\/p>\n<p>Dieron a conocer que ma\u00f1ana estar\u00e1n presentes nuevamente a la hora de ingreso, para que no se les acuse de abandono de labores, adem\u00e1s de que se realizar\u00e1n acciones de brigadeo para dar a conocer los pormenores de la situaci\u00f3n educativa nacional, acciones que iniciaron el d\u00eda de hoy con un mitin en el municipio de Calkin\u00ed.<\/p>\n<p><a href=\"http:\/\/paginabierta.mx\/sitio\/hasta-policias-utiliza-seduc-para-retirar-a-maestros-en-resistencia\/\" target=\"_blank\">paginabierta.mx\/sitio\/hasta-policias-utiliza-seduc-para-retirar-a-maestros-en-resistencia\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ronny Aguilar CAMPECHE, Cam. 1 de marzo del 2016.- Padres de familia respaldaron a docentes cesados el d\u00eda de ayer, exigieron a las autoridades que se les permita terminar &hellip; <a href=\"http:\/\/www.grieta.org.mx\/index.php\/2016\/03\/02\/hasta-policias-utiliza-seduc-para-retirar-a-maestros-en-resistencia\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":21928,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[123,80],"tags":[163,132,133],"class_list":["post-970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campeche","category-cintillo","tag-despidos","tag-evaluacion-al-desempeno","tag-maestros","entry"],"jetpack_featured_media_url":"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-fE","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":17442,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/07\/17\/maestros-de-cetec-exigen-abrogar-reforma-educativa-campeche\/","url_meta":{"origin":970,"position":0},"title":"Maestros de Cetec exigen abrogar reforma educativa  (Campeche)","author":"grieta","date":"17 julio, 2016","format":false,"excerpt":"Alrededor de 200 maestros de la Coordinadora Estatal de Trabajadores de la Educaci\u00f3n (Cetec) en Campeche, a trav\u00e9s de una marcha exigieron la abrogaci\u00f3n de la reforma educativa, el pago de la Carrera Magisterial, la anulaci\u00f3n del aumento de la jornada laboral en el nivel preescolar y la reintegraci\u00f3n de\u2026","rel":"","context":"En &quot;campeche&quot;","block_context":{"text":"campeche","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":21680,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/09\/13\/mantienen-lucha-maestros-cesados-sinaloa\/","url_meta":{"origin":970,"position":1},"title":"Mantienen lucha maestros cesados (Sinaloa)","author":"grieta","date":"13 septiembre, 2016","format":false,"excerpt":"MAZATL\u00c1N._ En pie de lucha contin\u00faan los 24 maestros mazatlecos que fueron cesados por la Secretar\u00eda de Educaci\u00f3n P\u00fablica y Cultura, luego de que se negaran a ser evaluados como lo exige la nueva reforma educativa. Esteban Guerra Jim\u00e9nez, integrante del Movimiento Magisterial, dijo que en Sinaloa fueron cesados 49\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":12229,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/05\/14\/exigen-con-caravana-reinstalar-a-maestros-cesados\/","url_meta":{"origin":970,"position":2},"title":"Exigen con caravana reinstalar a maestros cesados","author":"grieta","date":"14 mayo, 2016","format":false,"excerpt":"Sab\u00e1s Espinoza, Sinaloa Guam\u00fachil, Sinaloa.- Con la exigencia de que se reinstale a 49 maestros que fueron cesados en Sinaloa por no presentarse a la evaluaci\u00f3n docente que marca la reforma educativa, integrantes de la Coalici\u00f3n Magisterial Sinaloense realizan una marcha-caravana que tiene como prop\u00f3sito llegar a Culiac\u00e1n para manifestarse\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":15411,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/06\/22\/maestros-en-resistencia-presentan-demanda-laboral-campeche\/","url_meta":{"origin":970,"position":3},"title":"Maestros en resistencia presentan demanda laboral (Campeche)","author":"grieta","date":"22 junio, 2016","format":false,"excerpt":"Por Ronny Aguilar CAMPECHE, Cam. 22 de junio del 2016.- Maestros cesados presentaron una demanda laboral ante la Junta Federal de Conciliaci\u00f3n y Arbitraje contra la Secretar\u00eda de Educaci\u00f3n P\u00fablica, que constan de 239 p\u00e1ginas, en las que se evidencian todas las irregularidades en el cese de los cinco docentes.\u2026","rel":"","context":"En &quot;campeche&quot;","block_context":{"text":"campeche","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":17811,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/07\/21\/no-pagaron-quincenas-atrasadas-a-maestros-cesados-mmb-morelos\/","url_meta":{"origin":970,"position":4},"title":"No pagaron quincenas atrasadas a maestros cesados: MMB (Morelos)","author":"grieta","date":"21 julio, 2016","format":false,"excerpt":"Tlaulli Preciado, Morelos. Profesores disidentes informan que continuar\u00e1n las movilizaciones en varias entidades contra la reforma educativa, independientemente de las negociaciones con la Segob Cuernavaca, Morelos.- Maestros del Movimiento Magisterial de Bases (MMB) y del Comit\u00e9 Democr\u00e1tico Nacional de Trabajadores de la Educaci\u00f3n, advirtieron que independientemente de las negociaciones que\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":709,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/02\/29\/maestros-van-por-lucha-de-resistencia-ante-notificacion-de-cese\/","url_meta":{"origin":970,"position":5},"title":"Maestros van por lucha de resistencia, ante notificaci\u00f3n de cese","author":"grieta","date":"29 febrero, 2016","format":false,"excerpt":"Por Ronny Aguilar CAMPECHE, Cam. 29 de febrero del 2016.- La Secretar\u00eda estatal de Educaci\u00f3n (Seduc) notific\u00f3 el cese a los maestros que no presentaron examen de permanencia docente, por lo que anunciaron que realizar\u00e1n diversas acciones, aunque aseguran tener el respaldo de los padres de familia y de sus\u2026","rel":"","context":"En &quot;campeche&quot;","block_context":{"text":"campeche","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":1,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"predecessor-version":[{"id":971,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/970\/revisions\/971"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/21928"}],"wp:attachment":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}