{"id":70590,"date":"2024-11-28T09:38:47","date_gmt":"2024-11-28T15:38:47","guid":{"rendered":"https:\/\/www.grieta.org.mx\/?p=70590"},"modified":"2024-12-01T10:11:42","modified_gmt":"2024-12-01T16:11:42","slug":"despues-de-encontrarlos-las-trabas-del-sistema-a-las-familias-colima","status":"publish","type":"post","link":"http:\/\/www.grieta.org.mx\/index.php\/2024\/11\/28\/despues-de-encontrarlos-las-trabas-del-sistema-a-las-familias-colima\/","title":{"rendered":"Despu\u00e9s de encontrarlos: las trabas del sistema a las familias (Michoac\u00e1n)"},"content":{"rendered":"<p>Imagen: Unos d\u00edas despu\u00e9s de reconocer las prendas que vest\u00eda su hijo Ra\u00fal \u00c1vila P\u00e9rez cuando desapareci\u00f3, Gabriela coloc\u00f3 una cruz en la fosa clandestina donde encontraron su cuerpo. \/ Santiago Reyes<\/p>\n<p><em>Entre marzo y junio de este a\u00f1o, el colectivo Decofem localiz\u00f3 32 cuerpos enterrados en el Cerro de la Cruz de Jacona, en Michoac\u00e1n. Siete han sido identificados. Sobre Ra\u00fal y Mario \u2014dos de las v\u00edctimas\u2014 y sus familias, de su b\u00fasqueda y de los obst\u00e1culos que les pusieron las autoridades cuando los hallaron, es esta historia<\/em><\/p>\n<p>Santiago Reyes \/ Diario Avanzada<\/p>\n<p style=\"font-weight: 400;\">Lo primero en salir de la tierra son un par de tenis id\u00e9nticos a los que Gabriela P\u00e9rez Ram\u00edrez regal\u00f3 a su hijo en la Navidad previa a su desaparici\u00f3n. Despu\u00e9s, una chamarra negra con gris, igual o parecida a la que vest\u00eda Ra\u00fal \u00c1vila P\u00e9rez aquel lunes 14 de marzo de 2022 en que no regres\u00f3 del Cerro de la Cruz.<\/p>\n<p style=\"font-weight: 400;\">Hoy es lunes 10 de junio de 2024. Los peritos escarban en la parte baja del cerro; a unos metros, Gabriela est\u00e1 comiendo con sus compa\u00f1eras de b\u00fasqueda. No sabe todav\u00eda que ese cr\u00e1neo agujereado que una de las forenses sostiene en sus manos puede ser el de Ra\u00fal.<\/p>\n<p style=\"font-weight: 400;\">Veinte minutos despu\u00e9s del hallazgo, regreso junto al \u00e1rbol donde las integrantes del colectivo Desaparecidos de la Costa y Feminicidios de Michoac\u00e1n (Decofem) comparten un t\u00e1per lleno de arroz y carne guisada. Desde esta altura del cerro a\u00fan se alcanza a escuchar el murmullo de los autos. Un muro de ladrillos con agujeros de bala y grafitis con el nombre de Los Viagras \u2014un grupo criminal de la regi\u00f3n\u2014 es lo \u00fanico que separa este lugar de los barrios perif\u00e9ricos de la ciudad de Jacona de Plancarte, en Michoac\u00e1n.<\/p>\n<p style=\"font-weight: 400;\">Para cerciorarme de que la informaci\u00f3n que acabo de escribir en mi libreta es correcta, le pregunto a un compa\u00f1ero periodista si recuerda cu\u00e1l era la marca de los tenis.<\/p>\n<p style=\"font-weight: 400;\">\u201cSeg\u00fan yo, eran Nike\u201d, me dice.<\/p>\n<p style=\"font-weight: 400;\">\u201c\u00bfDe qu\u00e9 color?\u201d, pregunta una de las madres. Es Gabriela, de 42 a\u00f1os, quien tuvo que trasladarse desde Guadalajara, donde trabaja en una ferreter\u00eda, para poder buscar a su hijo. Viste una sudadera gris que contrasta con el calor del verano, una gorra tambi\u00e9n gris de los Dodgers, y un paliacate rojo que mantiene amarrado su cabello, pintado de un tono rojizo decolorado por el tiempo.<\/p>\n<p style=\"font-weight: 400;\">Reviso entre las fotograf\u00edas que acabo de tomar y ah\u00ed est\u00e1n: dos tenis azules cubiertos de tierra que quiz\u00e1 sean suficientes para responder a la pregunta que ha atormentado a Gabriela desde el momento en que su hijo, un comerciante y alba\u00f1il de 23 a\u00f1os, desapareci\u00f3.<\/p>\n<p style=\"font-weight: 400;\">\u201cAzul marino. Y encontraron tambi\u00e9n esta chamarra camuflajeada\u201d, le digo mostr\u00e1ndole una foto en la que se ve a un perito revisar la prenda.<\/p>\n<p style=\"font-weight: 400;\">Gabriela est\u00e1 congelada, sus pies inm\u00f3viles sobre el pastizal seco. Apenas respira. Sus compa\u00f1eras la miran, pero nadie dice nada. En cuesti\u00f3n de segundos, su cuerpo se destensa como quien durante toda una vida contuvo un quejido y finalmente puede respirar.\u00a0 Porque los dos a\u00f1os y cuatro meses sin Ra\u00fal fueron, sobre todo, eso: una vida entera.<\/p>\n<p style=\"font-weight: 400;\">\u201cS\u00ed, esa es. Esa es su chamarra\u201d, murmura.<\/p>\n<p style=\"font-weight: 400;\">\u201cCreo que la compa\u00f1era encontr\u00f3 a su hijo\u201d, advierte una de las buscadoras.<\/p>\n<p style=\"font-weight: 400;\">Algunas madres, aquellas que llevan m\u00e1s tiempo buscando a sus familiares, se acercan a abrazarla. \u201cEs feo, pero ya tendr\u00e1s donde llorarle\u201d, susurra una. Solo se escucha el ruido de los insectos, m\u00e1s fuerte que cualquier sonido: un sollozo, un grito, un suspiro de alivio.<\/p>\n<p style=\"font-weight: 400;\">Esa noche, al llegar a casa, Gabriela dese\u00f3 con todas sus fuerzas que ese cr\u00e1neo no fuera el de su hijo, y anhel\u00f3, tambi\u00e9n, que s\u00ed lo fuera.<\/p>\n<p style=\"font-weight: 400;\">Unos tenis azul marino fue lo primero que descubrieron los peritos en la fosa clandestina donde estaba enterrado Ra\u00fal \u00c1vila P\u00e9rez.<\/p>\n<p style=\"font-weight: 400;\"><strong>Sin registro<\/strong><\/p>\n<p style=\"font-weight: 400;\">Entre marzo y junio de 2024, integrantes de Decofem realizaron dos jornadas de b\u00fasqueda en el Cerro de la Cruz, donde hallaron 32 cuerpos enterrados \u2014la mayor\u00eda en estado esquel\u00e9tico\u2014 en 30 fosas clandestinas. Supieron del lugar por una llamada an\u00f3nima; la persona les dijo que, presuntamente, hab\u00eda ochenta cad\u00e1veres en la zona. \u201cLos van a encontrar si siguen la barda de ladrillo, a la altura de donde est\u00e1 el hoyo, ah\u00ed donde dice Los Viagras\u201d, afirm\u00f3.<\/p>\n<p style=\"font-weight: 400;\">A este cerro, localizado en el predio de Tamandaro, suelen ir los pobladores de Jacona a hacer ejercicio, desde caminatas en familia hasta senderismo. Se ubica entre el Cerro del Curutar\u00e1n y un lugar conocido como la Casa del Agua, una construcci\u00f3n de ladrillos abandonada que formaba parte de la antigua planta hidroel\u00e9ctrica del municipio.<\/p>\n<p style=\"font-weight: 400;\">La gran cantidad de cuerpos enterrados en la zona puede deberse a que, anteriormente, exist\u00eda un campamento del crimen organizado en las faldas del Curutar\u00e1n y, para evitar llamar la atenci\u00f3n sobre su ubicaci\u00f3n, los delincuentes trasladaron a sus v\u00edctimas al Cerro de la Cruz, considera la fundadora de Decofem Evangelina Contreras Ceja, quien busca a su hija Tania, desaparecida el 11 de julio de 2012.<\/p>\n<p style=\"font-weight: 400;\">\u201cAparte, como aqu\u00ed cerquita hay casas, pues pueden subir los cuerpos en carro y pasarlos por los hoyos de la barda. Y aunque la gente los vea, todo mundo se calla. Porque el terror que ejercen es para dominar a la sociedad y, desgraciadamente, estando en una ciudad como Jacona o Zamora, la poblaci\u00f3n est\u00e1 aterrada\u201d.<\/p>\n<p style=\"font-weight: 400;\">A los c\u00e1rteles les interesa esta regi\u00f3n porque genera mucho dinero por la industria de las frutas, considera una persona observadora de derechos humanos de Michoac\u00e1n que pide, por razones de seguridad, no mencionar su nombre. \u201cAs\u00ed como en otras partes del estado pasa con el aguacate, ac\u00e1 se quieren apoderar de las empresas que producen la fresa y la\u00a0<em>berrie<\/em>\u00a0a trav\u00e9s del cobro de piso\u201d, sostiene.\u00a0<a href=\"https:\/\/elpais.com\/mexico\/economia\/2024-09-23\/todo-el-sexenio-ha-habido-extorsiones-los-carteles-se-crecieron-los-cobros-del-narcotrafico-se-ceban-con-el-campo-en-michoacan.html\">Desde hace a\u00f1os<\/a>, empresarios y productores agr\u00edcolas de la entidad han denunciado amenazas y extorsiones por parte de las organizaciones criminales.<\/p>\n<p style=\"font-weight: 400;\">Ante la sospecha de que pueda haber m\u00e1s personas enterradas en el Cerro de la Cruz, Decofem reanudar\u00e1 las labores de b\u00fasqueda a inicios del pr\u00f3ximo a\u00f1o. Hasta la publicaci\u00f3n de este texto, solo siete v\u00edctimas hab\u00edan sido identificadas por las autoridades tras un proceso de confronta de ADN. Sus nombres y las edades que ten\u00edan cuando desaparecieron son: Marcos Quintero Ayala de 36 a\u00f1os, Alejandro Gil Garc\u00eda de 42 a\u00f1os, Anayeli Delgado Linares de 22 a\u00f1os, Miguel \u00c1ngel Mendoza Garibay de 32 a\u00f1os, Luis Adri\u00e1n Gallardo Sandoval de 30 a\u00f1os, Ra\u00fal \u00c1vila P\u00e9rez de 23 a\u00f1os, y Mario Alberto Le\u00f3n P\u00e9rez de 34 a\u00f1os. Este \u00faltimo todav\u00eda figura en el Registro Nacional de Personas Desaparecidas y No Localizadas\u00a0 (RNPDNO)\u00a0<a href=\"https:\/\/consultapublicarnpdno.segob.gob.mx\/consulta\">con el estatus de \u201cdesaparecido\u201d<\/a>.<\/p>\n<p style=\"font-weight: 400;\">El registro nacional tampoco ha actualizado la cifra de personas localizadas sin vida en Jacona, a pesar de los cuerpos identificados; desde marzo, cuando comenz\u00f3 la b\u00fasqueda, solo ha agregado una v\u00edctima, para sumar catorce. \u201cEs muy probable que la instituci\u00f3n encargada de registrar estas desapariciones en el RNPDNO, que en este caso ser\u00eda el Ministerio P\u00fablico de la Fiscal\u00eda Regional de Zamora, no haya hecho los reportes. Por eso no se actualizan los datos de que ya hay m\u00e1s localizados, porque tal vez ni siquiera estaban contados en la cifra de desaparecidos\u201d, explica Laura Contreras, hija de Evangelina y tambi\u00e9n integrante de Decofem. De modo que, para el Estado, estas personas nunca fueron localizadas, porque para empezar tal vez nunca figuraron como desaparecidas.<\/p>\n<p style=\"font-weight: 400;\">Una llamada an\u00f3nima dio como referencia un muro de ladrillo, con el nombre pintado de Los Viagras, para que se iniciara una b\u00fasqueda en ese lugar.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>La espera<\/strong><\/p>\n<p style=\"font-weight: 400;\">El 11 de junio, eran m\u00e1s de las dos de la tarde cuando un polic\u00eda de investigaci\u00f3n lleg\u00f3 al \u00e1rbol del Cerro de la Cruz donde las madres descansaban para darles la noticia: los peritos hab\u00edan encontrado una identificaci\u00f3n oficial a un costado del cuerpo hallado en la fosa n\u00famero seis.<\/p>\n<p style=\"font-weight: 400;\">Todo fue por culpa de un animal \u2014un perro o una rata\u2014 que, d\u00edas antes, guiado por el olor a descomposici\u00f3n desenterr\u00f3 un par de huesos peque\u00f1os. Esto permiti\u00f3 que Evangelina descubriera un\u00a0<em>tesoro<\/em>\u00a0\u2014como llaman a los restos de sus seres queridos desaparecidos\u2014 oculto bajo el peso de una enorme roca. \u201cYa no siga buscando ah\u00ed, esa piedra es muy grande como para que hayan escarbado debajo\u201d, le hab\u00eda dicho segundos antes un funcionario de la Comisi\u00f3n Nacional de B\u00fasqueda (CNB).<\/p>\n<p style=\"font-weight: 400;\">\u201cLa INE es de Mario Alberto Le\u00f3n P\u00e9rez, \u00bfalguien lo reconoce?\u201d, pregunt\u00f3 el polic\u00eda.<\/p>\n<p style=\"font-weight: 400;\">\u201cS\u00ed, es de mi t\u00edo. Es a quien estoy buscando\u201d, respondi\u00f3 Yaneth Barriga Le\u00f3n, de 36 a\u00f1os, una ingeniera industrial de semblante sobrio y ojos grandes y verdes que rara vez parpadean, quien desde marzo de este a\u00f1o abandon\u00f3 su profesi\u00f3n para ser buscadora de tiempo completo.<\/p>\n<p style=\"font-weight: 400;\">\u201cA\u00fan no es seguro que sea \u00e9l, solo es su identificaci\u00f3n\u201d, advirti\u00f3 el polic\u00eda. Despu\u00e9s, Yaneth se enter\u00f3 de que la credencial de su t\u00edo fue encontrada junto a los pies del cuerpo. \u201c\u00c9l siempre guardaba su INE en la planta de los zapatos\u201d, afirma. Mario, un comerciante de ropa de 34 a\u00f1os, desapareci\u00f3 la ma\u00f1ana del 10 de diciembre de 2020, cuando sali\u00f3 a trabajar con su pareja, Irma Leticia Le\u00f3n Ayala, de 48 a\u00f1os.<\/p>\n<p style=\"font-weight: 400;\">Acompa\u00f1ada de otra buscadora, Yaneth decidi\u00f3 bajar a la fosa para ver el cuerpo. Como si esos huesos pudieran hablarle, contar lo que pas\u00f3. Pero al llegar, ya no estaban. Solo hab\u00eda el hoyo en la tierra, una cinta amarilla que delimitaba el \u00e1rea, y una bocina colgada de un \u00e1rbol; al ritmo de\u00a0<em>Stand by me\u00a0<\/em>de Ben E. King, un grupo de peritos bailaba mientras terminaba de recoger sus herramientas.<\/p>\n<p style=\"font-weight: 400;\">Al regresar con sus dem\u00e1s compa\u00f1eras, la cuesta arriba se le volvi\u00f3 a\u00fan m\u00e1s pesada. A lo largo de la ladera, banderillas azules clavadas en el suelo indicaban el hallazgo de una osamenta cada diez o quince metros. Lo \u00fanico\u00a0 visible era el relieve de los cr\u00e1neos o de alguna v\u00e9rtebra, pues el resto del cad\u00e1ver segu\u00eda enterrado.<\/p>\n<p style=\"font-weight: 400;\">Esto es as\u00ed porque, seg\u00fan las buscadoras de Decofem, la Fiscal\u00eda Especializada para la Investigaci\u00f3n y Persecuci\u00f3n de los Delitos de Desaparici\u00f3n Forzada de Personas y Desaparici\u00f3n cometida por Particulares, adscrita a la Fiscal\u00eda General del Estado de Michoac\u00e1n, pide a los colectivos que, si encuentran un cuerpo, se limiten a marcar el lugar y contin\u00faen avanzando para no alterar la escena del delito; los servicios periciales son los encargados de procesar la fosa.<\/p>\n<p style=\"font-weight: 400;\">Cuenta Yaneth que, en ocasiones, cuando realizan un hallazgo, antes de notificarlo a la fiscal\u00eda remueven algunos cent\u00edmetros de tierra de la fosa para tomar una fotograf\u00eda como registro, y luego vuelven a cubrir el cuerpo, ya que no siempre les permiten acercarse a observar el trabajo de los peritos.<\/p>\n<p style=\"font-weight: 400;\">Yaneth Barriga, junto a la fosa donde encontraron a su t\u00edo Mario Alberto Le\u00f3n P\u00e9rez, minutos despu\u00e9s de que los peritos se llevaran el cuerpo.<\/p>\n<p style=\"font-weight: 400;\">En pocas palabras, como lo expresan Gabriela y Yaneth, en el momento en que una persona podr\u00eda ser identificada por una madre que quiz\u00e1 reconozca una imperfecci\u00f3n en la dentadura o una cicatriz \u2014cuando vio las fotos de la osamenta de Ra\u00fal, Gabriela not\u00f3 que a la mand\u00edbula le faltaba la misma muela que a su hijo\u2014, el cuerpo queda a merced de las fiscal\u00edas y los Servicios M\u00e9dicos Forenses (Semefos), que env\u00edan la mayor\u00eda de los cad\u00e1veres a una fosa com\u00fan o a un refrigerador mortuorio. La crisis forense en M\u00e9xico\u00a0<a href=\"https:\/\/adondevanlosdesaparecidos.org\/2024\/09\/24\/cierra-sexenio-con-mas-de-72100-cuerpos-sin-identificar\/\">supera los 72,100 cuerpos sin identificar<\/a>.<\/p>\n<p style=\"font-weight: 400;\">Al caer la tarde, concluida la jornada, las familias escucharon el reporte de las instituciones que acompa\u00f1aron y custodiaron la b\u00fasqueda: la fiscal\u00eda especializada, la CNB, la Guardia Nacional y la polic\u00eda municipal. \u201cEn cuanto a los dos cuerpos que tienen indicios de poder ser identificados, ya mandamos el oficio para que sean procesados en situaci\u00f3n de urgencia y puedan hacerse los an\u00e1lisis de ADN\u201d, anunci\u00f3 el polic\u00eda de investigaci\u00f3n a Gabriela y a Yaneth. \u201cM\u00e1s o menos un mes nos van a tener que esperar\u201d.<\/p>\n<p style=\"font-weight: 400;\">Esa \u00faltima palabra se qued\u00f3 en el aire. Como si haber pasado a\u00f1os sin avances en la carpeta de investigaci\u00f3n no hubiera sido suficiente para ellas. Esperar, esperar y esperar\u2026 la cruz que no pidieron cargar las familias de las\u00a0<a href=\"https:\/\/adondevanlosdesaparecidos.org\/2024\/11\/14\/un-ano-de-reyes-sahagun-en-la-cnb-crece-inconformidad-conserva-apoyos\/\">118,000 personas desaparecidas en el pa\u00eds<\/a>.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u201cM\u00e1s vale seguir adelante\u201d<\/strong><\/p>\n<p style=\"font-weight: 400;\">Un ej\u00e9rcito de moscas sobrevuela un puesto de donas de az\u00facar, junto al que desfilan cabizbajos los jornaleros al regresar de los campos de cultivo que se extienden en las afueras de Jacona. Van con el rostro a\u00fan cubierto por el paliacate que los protege de los qu\u00edmicos utilizados por las empresas en la siembra de fresas, ar\u00e1ndanos y frambuesas, la principal industria de la regi\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">Una jornalera cuenta que se cruz\u00f3 en su camino al trabajo con una camioneta llena de hombres armados que \u201ctan solo iban de paso por el monte\u201d. Otra escuch\u00f3 gritos y detonaciones en una casa, pero \u201cm\u00e1s vale seguir adelante que andar de chismosa\u201d. Y una m\u00e1s vio a lo lejos dos personas que cargaban una bolsa negra en direcci\u00f3n al cerro. Son secretos que se cuentan \u00fanicamente en la intimidad, entre cuatro paredes, o eso afirman los habitantes de Jacona, cabecera del municipio del mismo nombre, con una poblaci\u00f3n de cerca de<a href=\"https:\/\/www.economia.gob.mx\/datamexico\/es\/profile\/geo\/jacona#:~:text=Pir%C3%A1mide%20poblacional&amp;text=La%20poblaci%C3%B3n%20total%20de%20Jacona,%25%20mujeres%20y%2048.5%25%20hombres.\">\u00a069,000 habitantes<\/a>.<\/p>\n<p style=\"font-weight: 400;\">Cuando llegu\u00e9 a esta ciudad, el pasado 10 de junio, la noticia en los titulares era que el regidor suplente electo del municipio, el morenista Mario L\u00e1zaro Mendoza, hab\u00eda sido asesinado. Al caminar por una de las calles aleda\u00f1as al Cerro de la Cruz, vi las fichas de b\u00fasqueda de cinco personas pegadas en la pared de una tienda de abarrotes; en poco tiempo descubr\u00ed que los rostros de los desaparecidos estaban en varios puntos de la localidad.<\/p>\n<p style=\"font-weight: 400;\">Solo el r\u00edo Duero, uno de los m\u00e1s contaminados del estado, divide al municipio de Jacona del de Zamora \u2014con m\u00e1s de 200,000 habitantes\u2014, y ambos conforman el \u00e1rea metropolitana de Zamora. De acuerdo con el RNPDNO, en Jacona han desaparecido 158 personas, mientras que en Zamora suman 566. El total de v\u00edctimas de desaparici\u00f3n en Michoac\u00e1n es de 6,149 personas (hasta el 18 de noviembre).<\/p>\n<p style=\"font-weight: 400;\">Seg\u00fan el\u00a0<a href=\"https:\/\/static1.squarespace.com\/static\/5eaa390ddf0dcb548e9dd5da\/t\/66f4e7475d78640d228b11fa\/1727326056124\/MPI-ESP-2024-web.pdf\"><em>\u00cdndice de paz M\u00e9xico 2024<\/em><\/a>, del Instituto para la Econom\u00eda y la Paz, Jacona y Zamoraregistraron, respectivamente, 116 y 114 muertes por cada 100,000 habitantes en 2023, \u201clas tasas m\u00e1s altas entre los municipios con al menos 50,000 habitantes\u201d en la entidad.<\/p>\n<p style=\"font-weight: 400;\">\u00a0En la zona donde se desarroll\u00f3 la b\u00fasqueda es posible observar, a lo lejos, la ciudad de Jacona.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u201cAl rato vengo, ma\u201d<\/strong><\/p>\n<p style=\"font-weight: 400;\">\u201cPueden ir en paz\u201d, concluye el sacerdote tras bendecir a las seis personas que acudieron a la Capilla de la Santa Cruz en Jacona para estar presentes en la \u00faltima misa del novenario en memoria de Ra\u00fal. Quiz\u00e1 s\u00ed, a partir de hoy, su familia pueda volver a sentir algo de paz.<\/p>\n<p style=\"font-weight: 400;\">Techo de l\u00e1mina, unas cuantas bancas de madera y las catorce estaciones del viacrucis colgadas en la pared componen esta iglesia ubicada en la colonia Buenos Aires. Gabriela toma la fotograf\u00eda de Ra\u00fal y sale acompa\u00f1ada de su hija menor Estefany, quien se aferra a una caja de cart\u00f3n cubierta de papel mach\u00e9 que contiene las cenizas de la cruz que acompa\u00f1\u00f3 el novenario. \u201cPor lo menos lo encontraron, yo al m\u00edo nunca lo encontr\u00e9. Ojal\u00e1 Dios me d\u00e9 licencia de volver a verlo alg\u00fan d\u00eda\u201d, murmura en el atrio una se\u00f1ora que espera la siguiente misa.<\/p>\n<p style=\"font-weight: 400;\">En la entrada de la casa de Rosa Ram\u00edrez Navarro, abuela de Ra\u00fal, una buganvilia desborda la jardinera de ladrillos que su nieto construy\u00f3. En uno de los cuartos, sobre una mesa, est\u00e1n las flores ya marchitas y, en el suelo, las velas que iluminaron el velorio. En otra mesa permanecen un plato de pozole y un vaso de cocacola, como si el tiempo no pasara. La comida favorita de Ra\u00fal.<\/p>\n<p style=\"font-weight: 400;\">\u201cRa\u00fal vivi\u00f3 casi toda su vida aqu\u00ed en esta casa con mi mam\u00e1. Yo vivo en Guadalajara porque all\u00e1 trabajo en una ferreter\u00eda. Siempre que ven\u00eda a visitarlo, \u00e9l estaba sentado ac\u00e1 afuera partiendo le\u00f1a, y en cuanto me ve\u00eda se arrimaba y me daba mi abrazo. Porque me quer\u00eda, como yo lo quer\u00eda a \u00e9l, aunque no haya vivido todo el tiempo conmigo\u201d, cuenta Gabriela mientras coloca la foto de su hijo junto a las flores. \u201cYo siempre estuve al pendiente de \u00e9l\u201d.<\/p>\n<p style=\"font-weight: 400;\">Ra\u00fal es recordado en la casa donde viv\u00eda con su abuela Rosa, en Jacona.<\/p>\n<p style=\"font-weight: 400;\">El d\u00eda de su desaparici\u00f3n, Ra\u00fal rompi\u00f3 con su rutina. Ese lunes no tom\u00f3 su caf\u00e9 con galletas, como sol\u00eda hacerlo todas las ma\u00f1anas. Lo que su abuela Rosa vio fue lo de siempre. A su nieto que sal\u00eda por la puerta dici\u00e9ndole: \u201cAl rato vengo, ma\u201d.<\/p>\n<p style=\"font-weight: 400;\">\u201cY yo le dije: \u2018S\u00ed, hijo, que Dios te acompa\u00f1e, que te vaya bien\u2019, y me estuve ah\u00ed en la calle mir\u00e1ndolo hasta que ya no se mir\u00f3 m\u00e1s\u201d, dice Rosa. Al igual que su hija Gabriela, tiene el cabello pintado de rojo; tambi\u00e9n la misma nariz curva y los p\u00f3mulos marcados.<\/p>\n<p style=\"font-weight: 400;\">Ra\u00fal acostumbraba subir al Cerro de la Cruz en \u00e9poca de guam\u00fachiles para recolectarlos y venderlos en Jacona. Cuando se acercaba el 12 de diciembre, tra\u00eda tambi\u00e9n semillas para hacer cascabeles para los danzantes que celebraban a la Virgen de Guadalupe. Recolectaba de todo: le\u00f1a, ciruelas, nueces. Tra\u00eda lo que hubiera para sacar algo de dinero. El 14 de marzo del 2022, como casi todos los d\u00edas, Ra\u00fal se dirigi\u00f3 al cerro, ubicado a menos de dos kil\u00f3metros de su casa.<\/p>\n<p style=\"font-weight: 400;\">\u201cLleg\u00f3 la hora de acostarse y Ra\u00fal no llegaba. Yo lloraba y lloraba, y no me quer\u00eda ni ir a dormir porque tra\u00eda mucho pendiente. Mi esposo me dec\u00eda \u2018ya tranquil\u00edzate, al rato llega, a lo mejor se qued\u00f3 con un amigo\u2019. Pero no, lleg\u00f3 el otro d\u00eda y nada: ya nunca volvimos a saber de \u00e9l\u201d, recuerda su abuela.<\/p>\n<p style=\"font-weight: 400;\">Gabriela recibi\u00f3 la noticia un d\u00eda despu\u00e9s. Estaba en Guadalajara y lleg\u00f3 a Jacona la noche del mi\u00e9rcoles. El 17 de marzo acudi\u00f3 a la Fiscal\u00eda Regional de Zamora para hacer la denuncia por desaparici\u00f3n y, desde entonces, busc\u00f3 a Ra\u00fal en el monte, en hospitales, barrios, c\u00e1rceles, terrenos bald\u00edos y centros de rehabilitaci\u00f3n. Pero en ning\u00fan lado estaba.<\/p>\n<p style=\"font-weight: 400;\">\u201cAl principio busc\u00e1bamos solas mi sobrina y yo, pero era muy peligroso. Ya luego conocimos al colectivo y empezamos a buscar acompa\u00f1adas\u201d.<\/p>\n<p style=\"font-weight: 400;\">Antes escuchaba m\u00fasica todo el d\u00eda, cuenta Gabriela. Sus artistas favoritos eran Jenny Rivera, Gloria Trevi y, de vez en cuando, la banda M\u00e4go de Oz. Pero despu\u00e9s dej\u00f3 de hacerlo porque en su cabeza no hab\u00eda lugar para otra cosa que no fuera preguntarse: \u201c\u00bfc\u00f3mo estar\u00e1?, \u00bfle doler\u00e1 algo?, \u00bftendr\u00e1 fr\u00edo?, \u00bfle dar\u00e1n de comer?, \u00bfseguir\u00e1 vivo?\u201d.<\/p>\n<p style=\"font-weight: 400;\">Las madres buscadoras abrazaron a Gabriela despu\u00e9s de que le notificaron el posible hallazgo del cuerpo de su hijo.<\/p>\n<p style=\"font-weight: 400;\">Un mes y doce d\u00edas tard\u00f3 la fiscal\u00eda de Morelia en entregar el cuerpo de Ra\u00fal a su familia tras su hallazgo en el Cerro de la Cruz. Al d\u00eda siguiente, el martes 23 de julio, lo llevaron al pante\u00f3n, y la banda toc\u00f3 y toc\u00f3 hasta que la gente se cans\u00f3 de bailar y de llorar. Dice Rosa que su hija no le permiti\u00f3 ver el cuerpo de su nieto ni en fotos. Gabriela no quer\u00eda que recordara a Ra\u00fal muerto y con rastros de violencia. El agujero en el lado derecho del cr\u00e1neo determin\u00f3, seg\u00fan los peritos, que hab\u00eda sido asesinado de un balazo poco despu\u00e9s de su desaparici\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">\u201cNuestra cabeza s\u00ed va a descansar un poco m\u00e1s de ahora en adelante porque ya sabemos que, a lo mejor, pues no sufri\u00f3 hambre ni lo torturaron ni estuvo enfermo\u201d, dice Gabriela.<\/p>\n<p style=\"font-weight: 400;\">Despu\u00e9s de que identificaron a Ra\u00fal, su abuela dej\u00f3 de salir en las noches a esperarlo junto a la ventana. \u201cCreo que, ahora s\u00ed, ya me siento un poco m\u00e1s tranquila porque s\u00e9 que \u00e9l ya est\u00e1 descansando. Lo que s\u00ed es que el dolor ah\u00ed se va a quedar para siempre\u201d.<\/p>\n<p style=\"font-weight: 400;\">\u201cAunque la verdad\u201d, reconoce Gabriela, \u201ces que yo no quer\u00eda encontrarlo as\u00ed, mi esperanza era encontrarlo vivo. Una dice \u2018yo quiero encontrarlo de la forma que sea\u2019, pero cuando lo ves ah\u00ed, en un ata\u00fad, no quieres que sea \u00e9l. Piensas \u2018jam\u00e1s lo voy a poder volver a abrazar, jam\u00e1s podr\u00e9 verlo como era antes\u2019. Cuando la realidad te dice que ya est\u00e1 muerto, te duele tu coraz\u00f3n y sientes que ah\u00ed se acaba todo, sientes mucho coraje e impotencia porque ya no va a estar. Al final son sentimientos encontrados porque, al mismo tiempo, quieres que s\u00ed sea para poder descansar\u201d.<\/p>\n<p style=\"font-weight: 400;\">Pero, aunque Ra\u00fal yace bajo tierra, el Estado no permite a Gabriela descansar en paz. A los pocos d\u00edas de recibir la noticia de que el ADN del cuerpo de la fosa n\u00famero dos coincid\u00eda con el suyo, Gabriela fue a tramitar el acta de defunci\u00f3n de su hijo en el Registro Civil de Jacona. Ah\u00ed, uno de los funcionarios le inform\u00f3: \u201cEl plazo m\u00e1ximo para registrar el fallecimiento de una persona es de seis meses; de lo contrario, esta instituci\u00f3n solo puede hacer entrega de dicho documento por orden de una autoridad judicial emitida a trav\u00e9s de un juicio de levantamiento extempor\u00e1neo de acta de defunci\u00f3n\u201d.<\/p>\n<p style=\"font-weight: 400;\">Como el certificado de defunci\u00f3n que el Semefo emiti\u00f3 tras realizar el peritaje indica como fecha de la muerte de Ra\u00fal el d\u00eda de su desaparici\u00f3n, el 14 de marzo, Gabriela debi\u00f3 hacer el tr\u00e1mite antes del 15 de septiembre de 2022.<\/p>\n<p style=\"font-weight: 400;\">\u201cEs il\u00f3gico que hagan esto porque yo c\u00f3mo iba a pedir un acta de defunci\u00f3n antes de saber que \u00e9l estaba muerto\u201d, afirma Gabriela. \u201cPara m\u00ed, \u00e9l no estaba muerto. Dur\u00f3 dos a\u00f1os y cuatro meses desaparecido. Nosotros ya solo queremos descansar, ni siquiera queremos saber qu\u00e9 pas\u00f3. Yo pienso que Dios le da a cada quien lo que merece, y a lo mejor esa persona que mat\u00f3 a mi hijo ya tampoco est\u00e1. Quiz\u00e1s lo va a pagar de otra forma\u201d.<\/p>\n<p style=\"font-weight: 400;\">Una perito sostiene el cr\u00e1neo de Ra\u00fal, hallado en una fosa del Cerro de la Cruz, junto a la ciudad de Jacona.<\/p>\n<p style=\"font-weight: 400;\">Volga de Pina Ravest, abogada y exintegrante del Consejo Nacional Ciudadano del Sistema Nacional de B\u00fasqueda de Personas, se\u00f1ala que las autoridades mexicanas siguen sin entender que, por la complejidad de los casos de desaparici\u00f3n, es un acto de revictimizaci\u00f3n someter a las familias a este tipo de requisitos gravosos y de dif\u00edcil cumplimiento.<\/p>\n<p style=\"font-weight: 400;\">\u201cLo que se acostumbra hacer en estos casos es que el Semefo ponga como fecha de defunci\u00f3n el d\u00eda en que se realiz\u00f3 la identificaci\u00f3n del cuerpo, ya que es muy dif\u00edcil saber con precisi\u00f3n el momento exacto en que falleci\u00f3, a menos que se haga un an\u00e1lisis muy arduo. De esta manera, las familias no tienen que enfrentarse a este tipo de obst\u00e1culos burocr\u00e1ticos ni a juicios que suelen ser muy desgastantes\u201d, explica la abogada.<\/p>\n<p style=\"font-weight: 400;\">\u201cA m\u00ed me da la impresi\u00f3n de que es un tr\u00e1mite extra para recaudar dinero\u201d, agrega.<\/p>\n<p style=\"font-weight: 400;\">La p\u00e1gina web de la Direcci\u00f3n del Registro Civil de Michoac\u00e1n indica que el tr\u00e1mite del acta de defunci\u00f3n es gratuito, pero si el registro es extempor\u00e1neo cuesta 377 pesos. A esta cantidad hay que sumar el costo del juicio y los honorarios del abogado, que puede oscilar entre 10,000 y 23,000 pesos en un despacho privado.<\/p>\n<p style=\"font-weight: 400;\">\u201cEs el colmo que encima de que te desaparecen y matan a un familiar\u201d, lamenta la abogada, \u201clas autoridades te pidan tambi\u00e9n promover un juicio y pagar por \u00e9l\u201d.<\/p>\n<p style=\"font-weight: 400;\">Gabriela dice que solicitar\u00e1 a la Comisi\u00f3n Ejecutiva Estatal de Atenci\u00f3n a V\u00edctimas en Zamora que se hagan cargo del juicio necesario para poder gestionar el acta de defunci\u00f3n de Ra\u00fal, mientras que Decofem estudia la posibilidad de lanzar una iniciativa ciudadana ante el Congreso del estado para que, en casos de desaparici\u00f3n, no aplique el plazo de seis meses para realizar el tr\u00e1mite.<\/p>\n<p style=\"font-weight: 400;\"><strong>An\u00e1lisis perdidos<\/strong><\/p>\n<p style=\"font-weight: 400;\">Era agosto, hab\u00edan pasado casi dos meses desde el hallazgo del cuerpo de su t\u00edo Mario Alberto Le\u00f3n P\u00e9rez, y Yaneth Barriga segu\u00eda sin tener una respuesta. Debido a las lluvias, un herbaje de m\u00e1s de un metro de altura hab\u00eda devorado los tonos c\u00e1lidos del Cerro de la Cruz. \u201cNosotros le vamos a llamar, no tiene que estar viniendo\u201d, le dec\u00edan en la fiscal\u00eda de Zamora cuando iba a pedir informaci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">Con cada minuto que pasaba, desconfiaba m\u00e1s de la labor de las autoridades, pero la ropa y los objetos descubiertos en la fosa la hac\u00edan sentirse segura de que los restos eran de Mario: una playera gris sin mangas \u2014que se pon\u00eda siempre porque era su favorita\u2014, unos\u00a0<em>brackets<\/em>\u00a0de metal \u2014que utilizaba desde los quince a\u00f1os\u2014, y una pulsera negra de obsidiana \u2014que ten\u00edan todos en la familia porque las hac\u00eda otro de sus t\u00edos\u2014.<\/p>\n<p style=\"font-weight: 400;\">Un d\u00eda, Yaneth volvi\u00f3 a la fiscal\u00eda, no para preguntar si hab\u00eda avances en la identificaci\u00f3n, sino para solicitar una copia de la carpeta de investigaci\u00f3n del caso, porque no se la hab\u00edan proporcionado en los m\u00e1s de tres a\u00f1os que Mario llevaba desaparecido. Lo que menos esperaba era que alguien le dijera:\u00a0 \u201cPerdimos los an\u00e1lisis de ADN del ni\u00f1o\u201d, el hijo de su t\u00edo. Toda la angustia de esos meses fue en vano. Tendr\u00edan que reiniciar el tr\u00e1mite.<\/p>\n<p style=\"font-weight: 400;\">El m\u00e9todo obligatorio para identificar a una persona desaparecida, cuando el estado de los restos cadav\u00e9ricos lo permite, es la confronta de ADN, que consiste en comparar el perfil gen\u00e9tico de la v\u00edctima con el de un familiar consangu\u00edneo. En el caso de Mario, se decidi\u00f3 hacer la confronta con el ADN de su hijo Gabriel, de doce a\u00f1os, pero durante m\u00e1s de un mes las autoridades ocultaron que hab\u00edan extraviado la muestra de sangre entregada el 19 de marzo, cuando se hallaron los primeros cuerpos en el Cerro de la Cruz.<\/p>\n<p style=\"font-weight: 400;\">\u201cTuvimos que ir hasta la fiscal\u00eda de Morelia [a tres horas de distancia en autom\u00f3vil] para que le volvieran a sacar los estudios al ni\u00f1o porque en Zamora los iban a volver a perder\u201d, cuenta Silvia Le\u00f3n P\u00e9rez, hermana de Mario y madre de Yaneth. \u201cY aqu\u00ed nos tienen esperando otra vez. Ellos firmaron una acci\u00f3n urgente de que estaban comprometidos a entregarnos los resultados lo m\u00e1s pronto posible, y mira con qu\u00e9 salieron. \u00bfCu\u00e1nto tiempo nos han hecho perder?\u201d.<\/p>\n<p style=\"font-weight: 400;\">Si bien las autoridades ya hab\u00edan realizado una confronta con una muestra de ADN de Silvia, el resultado fue de un 60% de coincidencia, y para que este an\u00e1lisis sea confiable, el porcentaje debe ser del 99.999999%, seg\u00fan el antrop\u00f3logo f\u00edsico Israel Lira Garc\u00eda.<\/p>\n<p style=\"font-weight: 400;\">\u201c\u00bfQu\u00e9 m\u00e1s quieren saber si mi mam\u00e1 y yo ya estamos seguras? Todo coincide. La ropa, la identificaci\u00f3n, sus cosas. Y ni as\u00ed nos quieren entregar el cuerpo. Ya nos cansamos de esperar\u201d, afirma Yaneth.<\/p>\n<p style=\"font-weight: 400;\">Yaneth esparce agua bendita en el lugar donde enterraron a su t\u00edo Mario.<\/p>\n<p style=\"font-weight: 400;\"><strong>El mejor cocinero de Jacona<\/strong><\/p>\n<p style=\"font-weight: 400;\">Varias colillas de cigarro, un\u00a0<em>grinder<\/em>\u00a0para moler marihuana, un frasco de perfume, caramelo derretido en los asientos, un bote de crema corporal y tres casquillos de bala fue lo \u00fanico que encontraron en el veh\u00edculo en que viajaban Mario y su pareja Irma Leticia Le\u00f3n Ayala la ma\u00f1ana del 10 de diciembre de 2020. Ambos se dedicaban a vender ropa y viv\u00edan en una peque\u00f1a casa en Jacona, con sus hijos Valeria y Gabriel, que ten\u00edan de relaciones anteriores. Ese jueves, despu\u00e9s de llevar el desayuno a casa, salieron en el carro para ir a trabajar. No deb\u00edan tardar mucho porque Valeria, de 26 a\u00f1os, ten\u00eda una cita con el doctor. Pero nunca regresaron.<\/p>\n<p style=\"font-weight: 400;\">El autom\u00f3vil lo encontraron a dos cuadras del Cerro de la Cruz, cinco d\u00edas despu\u00e9s de que fueran vistos por \u00faltima vez. Todo apunta a que quienes los desaparecieron estuvieron utilizando el auto porque, a excepci\u00f3n del perfume y la crema, nada de lo que encontraron pertenec\u00eda a la pareja. Incluso los perpetradores tuvieron tiempo de ponerle vidrios polarizados.<\/p>\n<p style=\"font-weight: 400;\">Hoy, Gabriel vive con su t\u00eda Silvia, y Valeria con su familia materna.<\/p>\n<p style=\"font-weight: 400;\">\u201cYo soy la que sostiene al ni\u00f1o\u201d, dice Silvia, de 55 a\u00f1os. Viste una camisa blanca y un chaleco de mezclilla de la empresa agroindustrial en la que trabaja en el \u00e1rea de calidad. A su lado est\u00e1 Yaneth, sentada en el sill\u00f3n de la sala. Lucen casi iguales, salvo porque el pelo de la madre tiene algunas canas. \u201cSi dejo de trabajar, los dejo sin comer; por eso, mi hija tuvo que salir a buscar a Mario, y a m\u00ed eso me da una tranquilidad enorme porque nos est\u00e1 ayudando a salir de este pozo en el que est\u00e1 sumida toda la familia\u201d.<\/p>\n<p style=\"font-weight: 400;\">Desde que Mario desapareci\u00f3, su familia se separ\u00f3. Valeria y Gabriel pasaron cuatro a\u00f1os sin verse. La madre de Mario decidi\u00f3 mudarse porque le irritaba cualquier muestra de alegr\u00eda mientras su hijo permanec\u00eda ausente. Le reclamaba a Silvia que hubiera tardado m\u00e1s de tres a\u00f1os en empezar a buscarlo. A Yaneth, sus familiares le dec\u00edan que para qu\u00e9 pegaba fichas de b\u00fasqueda en Jacona si de todos modos no iban a encontrarlo.<\/p>\n<p style=\"font-weight: 400;\">Yaneth y Mario, aunque eran sobrina y t\u00edo, se llevaban solo tres a\u00f1os de diferencia. De ni\u00f1os hac\u00edan todo juntos: iban a la misma escuela, sal\u00edan a jugar por las tardes, se trepaban a la barda del vecino, y robaban guayabas y naranjas de las huertas de la cuadra.<\/p>\n<p style=\"font-weight: 400;\">\u201cCuando yo ocupaba algo, \u00e9l siempre estaba ah\u00ed para m\u00ed. Y tambi\u00e9n para \u00e9l yo era su apoyo. Siempre me andaba buscando cuando ten\u00eda un problema. Entonces, a m\u00ed s\u00ed me doli\u00f3 mucho cuando desapareci\u00f3 porque \u00e9ramos como hermanos\u201d, recuerda Yaneth.<\/p>\n<p style=\"font-weight: 400;\">\u201cY mira qui\u00e9n fue a encontrarlo\u201d, interrumpe Silvia sonri\u00e9ndole a su hija. \u201cPorque ya no hay dudas. Al menos para m\u00ed; yo s\u00ed estoy segura de que es \u00e9l. Y tendremos que aprender a seguir en el camino a como d\u00e9 lugar, aunque nos haga mucha falta\u201d.<\/p>\n<p style=\"font-weight: 400;\">Silvia cuenta que Mario trabaj\u00f3 desde peque\u00f1o en una pizzer\u00eda y, con el tiempo, pas\u00f3 de ser el barrendero del negocio a convertirse en el mejor cocinero de Jacona. Dice que la masa de sus pizzas era riqu\u00edsima y que, en los d\u00edas buenos, disfrutaba preparando espagueti a la bolo\u00f1esa. Recuerda tambi\u00e9n que, cuando ella cocinaba, Mario siempre met\u00eda las manos en la olla y cambiaba las recetas. \u201cAy, prietita, no te enojes\u201d, sol\u00eda decirle. Cuenta que a su hermano le gustaba corretear a las gallinas incluso de adulto, y que poco antes de su desaparici\u00f3n practicaban juntos\u00a0<em>kick boxing\u00a0<\/em>por las tardes.<\/p>\n<p style=\"font-weight: 400;\">\u201cPero a quien m\u00e1s le va a hacer falta es al ni\u00f1o. Porque Gabriel sigue todav\u00eda esperando a su pap\u00e1 y vamos a tener que explicarle qu\u00e9 le pas\u00f3. La fiscal\u00eda nos estuvo pagando como tres meses un psic\u00f3logo para \u00e9l, porque desde que desapareci\u00f3 Mario se puso muy mal, pero ya nos quitaron ese apoyo\u201d.<\/p>\n<p style=\"font-weight: 400;\">Afuera ha dejado de llover. Es de noche, el olor a tierra mojada impregna la sala, y yo me pregunto si realmente todo termina al encontrarlos.<\/p>\n<p style=\"font-weight: 400;\">\u201cEl ni\u00f1o me dice: \u2018T\u00eda, y si ya encontraron a mi papi, \u00bfmi mami d\u00f3nde est\u00e1?\u2019. Entonces, aunque s\u00ed sea el cuerpo de mi hermano, ah\u00ed no termina todo. El ni\u00f1o necesita a su padre y a su madre. El otro d\u00eda nos preguntaron en la fiscal\u00eda de Morelia si ya quer\u00edamos cerrar la carpeta de investigaci\u00f3n. Les dijimos que no, que no la vamos a cerrar hasta encontrar a Leti tambi\u00e9n. La espera va a seguir porque todav\u00eda falta ella de encontrarse\u201d.<\/p>\n<p style=\"font-weight: 400;\">Falta ella, insiste Silvia.<\/p>\n<p style=\"font-weight: 400;\">D\u00edas despu\u00e9s, el 15 de agosto de 2024, la fiscal\u00eda de Zamora entreg\u00f3 el cuerpo de Mario Alberto Le\u00f3n P\u00e9rez a sus familiares. Hasta la publicaci\u00f3n de esta historia, Irma Leticia Le\u00f3n Ayala sigue desaparecida.<\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/adondevanlosdesaparecidos.org\/\"><strong><em>www.adondevanlosdesaparecidos.org<\/em><\/strong><\/a><strong><em>\u00a0es un sitio de investigaci\u00f3n y memoria sobre las l\u00f3gicas de la desaparici\u00f3n en M\u00e9xico. Este material puede ser libremente reproducido, siempre y cuando se respete el cr\u00e9dito de la persona autora y de A d\u00f3nde van los desaparecidos (<\/em><\/strong><a href=\"https:\/\/twitter.com\/desaparecerenmx\"><strong><em>@DesaparecerEnMx<\/em><\/strong><\/a><strong><em>).<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/diarioavanzada.com.mx\/?p=66868\">https:\/\/diarioavanzada.com.mx\/?p=66868<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagen: Unos d\u00edas despu\u00e9s de reconocer las prendas que vest\u00eda su hijo Ra\u00fal \u00c1vila P\u00e9rez cuando desapareci\u00f3, Gabriela coloc\u00f3 una cruz en la fosa clandestina donde encontraron su cuerpo. \/ &hellip; <a href=\"http:\/\/www.grieta.org.mx\/index.php\/2024\/11\/28\/despues-de-encontrarlos-las-trabas-del-sistema-a-las-familias-colima\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":70592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,87,1201,21,2,83],"tags":[1828,3018,121,3775,1668,3660,856,3975,3592],"class_list":["post-70590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-desaparecidos","category-desaparecidos-en-michoacan","category-michoacan","category-noticias-nacionales","category-temas-nacionales","tag-busqueda-de-desaparecidos","tag-colectivos-de-busqueda-de-desaparecidos","tag-desaparecidos","tag-estadisticas-de-desaparecidos","tag-familiares-de-desaparecidos","tag-fiscalia","tag-fosas-clandestinas","tag-madres-de-desaparecidos","tag-semefo","entry"],"jetpack_featured_media_url":"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2024\/12\/img_4757-1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-imy","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":32605,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/04\/26\/anuncian-nueva-caravana-de-busqueda-de-desaparecidos-en-michoacan\/","url_meta":{"origin":70590,"position":0},"title":"Anuncian nueva caravana de b\u00fasqueda de desaparecidos en Michoac\u00e1n","author":"grieta","date":"26 abril, 2019","format":false,"excerpt":"V\u00edctimas de desaparici\u00f3n forzada en Michoac\u00e1n piden justicia al gobierno federal MVS Noticias, Nora Bucio ?26\/Abr\/19 13:45 Familiares Caminando por la Justicia, anunciaron que realizar\u00e1n la V Caravana \u201cBuscando, encontraremos\u201d, la cual se realizar\u00e1 en Michoac\u00e1n, la cual pretende encontrar vivos y post mortem a personas denunciadas como desaparecidas. Evangelina\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/dc3ffd0d-d5git5zx4aipsz1-1024x768.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/dc3ffd0d-d5git5zx4aipsz1-1024x768.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/dc3ffd0d-d5git5zx4aipsz1-1024x768.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/dc3ffd0d-d5git5zx4aipsz1-1024x768.jpg?resize=700%2C400 2x"},"classes":[]},{"id":61774,"url":"http:\/\/www.grieta.org.mx\/index.php\/2021\/09\/14\/realizara-colectivo-tecomense-colima-busqueda-de-desaparecidos-en-michoacan\/","url_meta":{"origin":70590,"position":1},"title":"Realizar\u00e1 colectivo tecomense (Colima) b\u00fasqueda de desaparecidos en Michoac\u00e1n","author":"grieta","date":"14 septiembre, 2021","format":false,"excerpt":"Imagen: Colectivo Solidarios de B\u00fasqueda de Personas Desaparecidas Yensuni L\u00f3pez Aldape \/ El Comentario Candelaria Huerta Pizano, representante en el estado del colectivo\u00a0Solidarios de B\u00fasqueda de Persona Desaparecidas, se\u00f1al\u00f3 que a poco menos de 2 meses de cumplir un a\u00f1o de creado, el n\u00famero de v\u00edctimas desaparecidas que est\u00e1n buscando\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/09\/9a168857263cfe222d4e3e69f34ea7b9.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/09\/9a168857263cfe222d4e3e69f34ea7b9.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/09\/9a168857263cfe222d4e3e69f34ea7b9.jpeg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/09\/9a168857263cfe222d4e3e69f34ea7b9.jpeg?resize=700%2C400 2x"},"classes":[]},{"id":64753,"url":"http:\/\/www.grieta.org.mx\/index.php\/2022\/05\/12\/por-falta-de-resultados-familias-de-desaparecidos-toman-la-comision-estatal-de-busqueda-michoacan\/","url_meta":{"origin":70590,"position":2},"title":"Por falta de resultados, familias de desaparecidos toman la Comisi\u00f3n Estatal de B\u00fasqueda (Michoac\u00e1n)","author":"grieta","date":"12 mayo, 2022","format":false,"excerpt":"F\u00e1tima Paz, 27 de mayo de 2022, primeraplana.mx Moelia, Michoac\u00e1n.- \u201c\u00bfY si fuera tu familiar el que estuviera desaparecido?\u201d, cuestionaron familiares y colectivos de familiares de personas desaparecidas, quienes tomaron la Comisi\u00f3n Estatal de B\u00fasqueda de Personas Desaparecidas, ante la falta de resultados que, aseveraron, presenta la instancia. Con carteles\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/familiares-de-desaparecidos-toma-de-comision-1392x1044-1.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/familiares-de-desaparecidos-toma-de-comision-1392x1044-1.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/familiares-de-desaparecidos-toma-de-comision-1392x1044-1.jpeg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/familiares-de-desaparecidos-toma-de-comision-1392x1044-1.jpeg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2022\/08\/familiares-de-desaparecidos-toma-de-comision-1392x1044-1.jpeg?resize=1050%2C600 3x"},"classes":[]},{"id":32364,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/04\/19\/madres-y-familias-de-desaparecidos-en-apatzingan-michoacan-se-suman-al-viacrucis-y-dicen-basta-a-la-violencia\/","url_meta":{"origin":70590,"position":3},"title":"Madres y familias de desaparecidos en Apatzing\u00e1n, Michoac\u00e1n se suman al Viacrucis y dicen basta a la violencia","author":"grieta","date":"19 abril, 2019","format":false,"excerpt":"Redacci\u00f3n, 90 grados APATZINGAN, MICH., 19 DE ABRIL DEL 2019.- Madres de desaparecidos, familias de quienes han sido v\u00edctimas de desapariciones forzadas, trata y feminicidios se han sumado al viacrucis de la v\u00eda de la cruz que hoy se hace visible con los dolores de estas familias que estuvieron presentes\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/0-grande-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/0-grande-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/0-grande-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/04\/0-grande-1.jpg?resize=700%2C400 2x"},"classes":[]},{"id":58849,"url":"http:\/\/www.grieta.org.mx\/index.php\/2021\/04\/15\/exigen-familias-la-localizacion-de-sus-desaparecidos-frente-a-casa-jalisco\/","url_meta":{"origin":70590,"position":4},"title":"Exigen familias la localizaci\u00f3n de sus desaparecidos frente a Casa Jalisco","author":"grieta","date":"15 abril, 2021","format":false,"excerpt":"Foto: F\u00e1tima Aguilar Equipo Editorial \/ UDGTV Un grupo de m\u00e1s de 100 familias acudieron la tarde de este jueves a Casa Jalisco\u00a0para evidenciar las omisiones desde la Fiscal\u00eda Estatal en la\u00a0b\u00fasqueda de sus desaparecidos\u00a0y exigir su localizaci\u00f3n. Convocados desde el colectivo Huellas de Amor, acudieron con fotograf\u00edas de sus\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/Manifestacion-Fatima-Aguilar-696x521-1.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/Manifestacion-Fatima-Aguilar-696x521-1.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/Manifestacion-Fatima-Aguilar-696x521-1.jpeg?resize=525%2C300 1.5x"},"classes":[]},{"id":66105,"url":"http:\/\/www.grieta.org.mx\/index.php\/2023\/01\/20\/bloqueo-carretero-permanente-por-los-2-lideres-desaparecidos-colima\/","url_meta":{"origin":70590,"position":5},"title":"Bloqueo carretero permanente por los 2 l\u00edderes desaparecidos (Colima)","author":"grieta","date":"20 enero, 2023","format":false,"excerpt":"Imagen: El Noticiero en L\u00ednea Anil\u00fa Salazar Mej\u00eda\u00a0 \/\u00a0 El Noticiero en L\u00ednea Cuando se est\u00e1n cumpliendo cinco d\u00edas de la desaparici\u00f3n del abogado y defensor de derechos humanos Ricardo Lagunes y el l\u00edder comunitario de Aquila, Michoac\u00e1n, Antonio D\u00edaz Valencia, persiste el bloqueo de la carretera que colinda a\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/p02-t3-12-777x374-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/p02-t3-12-777x374-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/p02-t3-12-777x374-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/p02-t3-12-777x374-1.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/70590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=70590"}],"version-history":[{"count":1,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/70590\/revisions"}],"predecessor-version":[{"id":70599,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/70590\/revisions\/70599"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/70592"}],"wp:attachment":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=70590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=70590"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=70590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}