{"id":42078,"date":"2019-12-09T13:26:21","date_gmt":"2019-12-09T19:26:21","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=42078"},"modified":"2019-12-11T13:34:26","modified_gmt":"2019-12-11T19:34:26","slug":"ante-violencia-en-mexico-militares-alcanzan-despliegue-historico","status":"publish","type":"post","link":"http:\/\/www.grieta.org.mx\/index.php\/2019\/12\/09\/ante-violencia-en-mexico-militares-alcanzan-despliegue-historico\/","title":{"rendered":"ANTE VIOLENCIA EN M\u00c9XICO, MILITARES ALCANZAN DESPLIEGUE HIST\u00d3RICO"},"content":{"rendered":"<p>Redacci\u00f3n\/Reporte Indigo<br \/>\n9 diciembre 2019<\/p>\n<blockquote><p>La cifra de militares en el pa\u00eds asciende actualmente a 62 mil 954: 14.5 por ciento m\u00e1s que los de Pe\u00f1a y 19.48 por ciento respecto de la tropa que us\u00f3 Calder\u00f3n en 2011<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"42079\" data-permalink=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/12\/09\/ante-violencia-en-mexico-militares-alcanzan-despliegue-historico\/soldados\/\" data-orig-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/soldados.png\" data-orig-size=\"751,475\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"soldados\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/soldados-300x190.png\" data-large-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/soldados.png\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/soldados.png\" alt=\"\" width=\"751\" height=\"475\" class=\"aligncenter size-full wp-image-42079\" srcset=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/soldados.png 751w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/soldados-300x190.png 300w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/p>\n<p>A pesar de que el gobierno de Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO) asegura que en la estrategia contra la inseguridad en el pa\u00eds no est\u00e1 declarada la guerra contra el crimen, el despliegue de militares es hist\u00f3rico.<\/p>\n<p>De acuerdo con Reforma, esta administraci\u00f3n ya super\u00f3 los despliegues de soldados que los sexenios de Felipe Calder\u00f3n y Enrique Pe\u00f1a Nieto implementaron. <\/p>\n<p>La cifra de militares en el pa\u00eds asciende actualmente a 62 mil 954: 14.5 por ciento m\u00e1s que los de Pe\u00f1a y 19.48 por ciento respecto de la tropa que us\u00f3 Calder\u00f3n en 2011<\/p>\n<p>Sin embargo la violencia en el pa\u00eds ha aumentado: el promedio de v\u00edctimas por d\u00eda \u2013seg\u00fan este diario\u2013 aument\u00f3 a 94, en contraste con las 61, 79, y 92 por d\u00eda del 2016, 2017 y 2018, respectivamente.<\/p>\n<p>TE PUEDE INTERESAR: SEDENA: M\u00c1S DE 14 MIL MILITARES SE INCORPORARON A LA GUARDIA NACIONAL<br \/>\nDe acuerdo a lo proyectado para este 2019, el Ej\u00e9rcito Mexicano logr\u00f3 el objetivo establecido por el Gobierno de M\u00e9xico para incorporar a la Guardia Nacional a 14 mil 833 j\u00f3venes.<\/p>\n<p>Seg\u00fan informaci\u00f3n de la Secretar\u00eda de la Defensa Nacional (Sedena), la captaci\u00f3n de personal civil se realizar\u00e1 en tres a\u00f1os, hasta completar 50 mil 000 efectivos, de los cuales 43 mil 663 corresponden al Ej\u00e9rcito mexicano dividi\u00e9ndose de la siguiente manera:<\/p>\n<p>\u2022 14 Mil 833 efectivos en el a\u00f1o 2019.<br \/>\n\u2022 14 Mil 430 efectivos en el a\u00f1o 2020.<br \/>\n\u2022 14 Mil 400 efectivos en el a\u00f1o 2021.<\/p>\n<p>La Sedena, destac\u00f3, que el proceso de reclutamiento crea oportunidades para los j\u00f3venes que deseen desarrollarse profesionalmente con la convicci\u00f3n de servir a la patria y comprometerse con el pueblo de M\u00e9xico, siempre apegados a la legalidad, \u00e9tica y pleno respeto a los derechos humanos.<\/p>\n<p><a href=\"https:\/\/www.reporteindigo.com\/reporte\/ante-la-ola-de-violencia-en-mexico-militares-alcanzan-despliegue-historico\/\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/www.reporteindigo.com\/reporte\/ante-la-ola-de-violencia-en-mexico-militares-alcanzan-despliegue-historico\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n\/Reporte Indigo 9 diciembre 2019 La cifra de militares en el pa\u00eds asciende actualmente a 62 mil 954: 14.5 por ciento m\u00e1s que los de Pe\u00f1a y 19.48 por ciento &hellip; <a href=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/12\/09\/ante-violencia-en-mexico-militares-alcanzan-despliegue-historico\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":42079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,913,83],"tags":[2974],"class_list":["post-42078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-militarizacion-analisis","category-temas-nacionales","tag-aumento-de-la-militarizacion","entry"],"jetpack_featured_media_url":"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/soldados.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-aWG","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":42081,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/12\/09\/lopez-obrador-aumento-la-presencia-militar-en-las-calles-al-maximo-historico\/","url_meta":{"origin":42078,"position":0},"title":"L\u00f3pez Obrador aument\u00f3 la presencia militar en las calles al m\u00e1ximo hist\u00f3rico","author":"grieta","date":"9 diciembre, 2019","format":false,"excerpt":"Tel\u00e1m\/Redacci\u00f3n 9 diciembre 2019 El despliegue de militares para prevenir y combatir la violencia en las calles de M\u00e9xico aument\u00f3 14,5% durante el primer a\u00f1o de gesti\u00f3n del presidente Andr\u00e9s L\u00f3pez Obrador y lleg\u00f3 al m\u00e1ximo hist\u00f3rico de casi 63.000 efectivos, seg\u00fan un informe oficial divulgado hoy. Actualmente hay 62.954\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/http___www.telam_.com_.ar_advf_imagenes_2019_08_5d66a6b83e535_1004x564.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/http___www.telam_.com_.ar_advf_imagenes_2019_08_5d66a6b83e535_1004x564.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/http___www.telam_.com_.ar_advf_imagenes_2019_08_5d66a6b83e535_1004x564.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/http___www.telam_.com_.ar_advf_imagenes_2019_08_5d66a6b83e535_1004x564.jpg?resize=700%2C400 2x"},"classes":[]},{"id":44385,"url":"http:\/\/www.grieta.org.mx\/index.php\/2020\/02\/03\/el-discurso-de-la-militarizacion\/","url_meta":{"origin":42078,"position":1},"title":"El discurso de la militarizaci\u00f3n","author":"grieta","date":"3 febrero, 2020","format":false,"excerpt":"Rebeca Calzada\/Animal Pol\u00edtico 3 febrero 2020 Durante las administraciones de Calder\u00f3n y Pe\u00f1a Nieto, la militarizaci\u00f3n de la seguridad p\u00fablica fue promovida y echada a andar como un medio para recuperar y mejorar la seguridad p\u00fablica en el pa\u00eds, en el caso de L\u00f3pez Obrador, ha sido promovida y echada\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/militares-1-950x500.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/militares-1-950x500.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/militares-1-950x500.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/02\/militares-1-950x500.jpg?resize=700%2C400 2x"},"classes":[]},{"id":26626,"url":"http:\/\/www.grieta.org.mx\/index.php\/2018\/09\/14\/mexico-militarizado-un-pais-de-cotidianos-crimenes-de-lesa-humanidad\/","url_meta":{"origin":42078,"position":2},"title":"M\u00e9xico militarizado, un pa\u00eds de cotidianos cr\u00edmenes de lesa humanidad","author":"grieta","date":"14 septiembre, 2018","format":false,"excerpt":"AUTOR: Z\u00d3SIMO CAMACHO Los problemas ven\u00edan de mucho antes. Pero al incendio que ya era M\u00e9xico, se le ech\u00f3 gasolina: se orden\u00f3 la militarizaci\u00f3n del pa\u00eds. Hoy se trata de una maltrecha naci\u00f3n bajo \u201cataque sistem\u00e1tico y generalizado contra la poblaci\u00f3n civil\u201d. Es una de las conclusiones de un informe\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/09\/zonaja-cerro-a.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/09\/zonaja-cerro-a.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/09\/zonaja-cerro-a.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/09\/zonaja-cerro-a.jpg?resize=700%2C400 2x"},"classes":[]},{"id":58240,"url":"http:\/\/www.grieta.org.mx\/index.php\/2021\/04\/07\/ha-militarizado-amlo-mas-a-mexico-que-pena-nieto-y-calderon-amnistia-internacional\/","url_meta":{"origin":42078,"position":3},"title":"Ha militarizado AMLO m\u00e1s a M\u00e9xico que Pe\u00f1a Nieto y Calder\u00f3n: Amnist\u00eda Internacional","author":"grieta","date":"7 abril, 2021","format":false,"excerpt":"Foto: cortes\u00eda Cristina Herrera\/Debate 7 abril 2021 M\u00e9xico.- A pesar de que en m\u00faltiples ocasiones lo ha negado, el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador ha desplegado a m\u00e1s elementos del Ej\u00e9rcito en M\u00e9xico, esto como factor de su plan de seguridad p\u00fablica, que en las administraciones de los\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/amlo-gn.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/amlo-gn.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/amlo-gn.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/amlo-gn.png?resize=700%2C400 2x"},"classes":[]},{"id":58234,"url":"http:\/\/www.grieta.org.mx\/index.php\/2021\/04\/07\/violencia-crece-en-diez-estados-pese-a-mayor-despliegue-de-la-guardia-nacional\/","url_meta":{"origin":42078,"position":4},"title":"Violencia crece en diez estados, pese a mayor despliegue de la Guardia Nacional","author":"grieta","date":"7 abril, 2021","format":false,"excerpt":"FOTO: MARGARITO P\u00c9REZ RETANA \/CUARTOSCURO Arturo Angel\/Animal Pol\u00edtico 7 abril 2021 En el primer bimestre de 2021 los asesinatos crecieron o se mantuvieron en niveles similares a los del a\u00f1o pasado en casi la mitad de los estados, mientras que la certificaci\u00f3n y depuraci\u00f3n de polic\u00edas locales est\u00e1 inconclusa. En\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/violencia_estados_guardia_nacional.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/violencia_estados_guardia_nacional.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/violencia_estados_guardia_nacional.jpeg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/violencia_estados_guardia_nacional.jpeg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/violencia_estados_guardia_nacional.jpeg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2021\/04\/violencia_estados_guardia_nacional.jpeg?resize=1400%2C800 4x"},"classes":[]},{"id":49473,"url":"http:\/\/www.grieta.org.mx\/index.php\/2020\/05\/15\/el-ejercito-con-historial-de-quejas-e-investigaciones-en-su-contra-y-ahora-con-aval-legal-para-seguridad-publica\/","url_meta":{"origin":42078,"position":5},"title":"El Ej\u00e9rcito, con historial de quejas e investigaciones en su contra, y ahora con aval legal para seguridad p\u00fablica","author":"grieta","date":"15 mayo, 2020","format":false,"excerpt":"Alberto Pradilla\/Animal Pol\u00edtico 15 mayo 2020 La Sedena es la instituci\u00f3n que acumul\u00f3 m\u00e1s quejas entre 2006 y 2019 por desaparici\u00f3n forzada, tortura y ejecuci\u00f3n extrajudicial. Cuartoscuro Una orden presidencial de Andr\u00e9s Manuel L\u00f3pez Obrador legaliza que el Ej\u00e9rcito haga labores de seguridad p\u00fablica durante los pr\u00f3ximos cinco a\u00f1os. La\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/ejercito-militares.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/ejercito-militares.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/ejercito-militares.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/ejercito-militares.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/42078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=42078"}],"version-history":[{"count":1,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/42078\/revisions"}],"predecessor-version":[{"id":42080,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/42078\/revisions\/42080"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/42079"}],"wp:attachment":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=42078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=42078"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=42078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}