{"id":36056,"date":"2019-07-05T17:57:51","date_gmt":"2019-07-05T22:57:51","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=36056"},"modified":"2019-07-06T18:05:21","modified_gmt":"2019-07-06T23:05:21","slug":"onu-dh-condena-el-asesinato-de-la-activista-cristina-vazquez-en-la-cdmx","status":"publish","type":"post","link":"http:\/\/www.grieta.org.mx\/index.php\/2019\/07\/05\/onu-dh-condena-el-asesinato-de-la-activista-cristina-vazquez-en-la-cdmx\/","title":{"rendered":"ONU-DH condena el asesinato de la activista Cristina V\u00e1zquez en la CDMX"},"content":{"rendered":"<figure id=\"attachment_36057\" aria-describedby=\"caption-attachment-36057\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36057\" data-permalink=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/07\/05\/onu-dh-condena-el-asesinato-de-la-activista-cristina-vazquez-en-la-cdmx\/onu-dh\/\" data-orig-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh.jpg\" data-orig-size=\"635,356\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"onu-dh\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh-300x168.jpg\" data-large-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh.jpg\" class=\"wp-image-36057\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh-300x168.jpg\" alt=\"\" width=\"800\" height=\"449\" srcset=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh-300x168.jpg 300w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh.jpg 635w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-36057\" class=\"wp-caption-text\">Foto: Twitter @unmexicodigital<\/figcaption><\/figure>\n<p>Itzel Garc\u00eda \/ RADIO F\u00d3RMULA<\/p>\n<p>El asesinato de la defensora de derechos humanos Mar\u00eda Cristina V\u00e1zquez Chavarr\u00eda fue condenado por  la Oficina en M\u00e9xico del Alto Comisionado de las Naciones Unidas para los Derechos Humanos (ONU-DH).<\/p>\n<p>V\u00e1zquez Chavarr\u00eda, quien fue asesinada en la Ciudad de M\u00e9xico, colaboraba en un movimiento vecinal de una colonia de la Ciudad de M\u00e9xico.<\/p>\n<p>Adem\u00e1s, particip\u00f3 en denuncias p\u00fablicas relativas al uso del espacio p\u00fablico, la corrupci\u00f3n urban\u00edstica y la inseguridad en la zona.<\/p>\n<p>A trav\u00e9s de un comunicado, ONU-DH se\u00f1al\u00f3 que con la muerte de V\u00e1zquez Chavarr\u00eda ya son 13 los defensores de derechos humanos asesinados en M\u00e9xico durante 2019.<\/p>\n<p>La ONU-DH exhort\u00f3 a las autoridades de la capital mexicana a realizar las investigaciones correspondientes para esclarecer el asesinato de la activista y dar con los responsables.<\/p>\n<p>El organismo tambi\u00e9n detall\u00f3 que la investigaci\u00f3n debe realizarse con perspectiva de g\u00e9nero y deben agotarse todas las hip\u00f3tesis en torno al caso.<\/p>\n<p>La ONU-DH expres\u00f3 sus condolencias y su solidaridad con la familia, amistades y colegas de V\u00e1zquez Chavarr\u00eda; adem\u00e1s, hizo un llamado al Gobierno de la Ciudad de M\u00e9xico a garantizar su seguridad.<\/p>\n<p><a href=\"https:\/\/www.radioformula.com.mx\/noticias\/20190705\/onu-dh-condena-el-asesinato-de-la-activista-cristina-vazquez-en-la-cdmx\/\">https:\/\/www.radioformula.com.mx\/noticias\/20190705\/onu-dh-condena-el-asesinato-de-la-activista-cristina-vazquez-en-la-cdmx\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Itzel Garc\u00eda \/ RADIO F\u00d3RMULA El asesinato de la defensora de derechos humanos Mar\u00eda Cristina V\u00e1zquez Chavarr\u00eda fue condenado por la Oficina en M\u00e9xico del Alto Comisionado de las Naciones &hellip; <a href=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/07\/05\/onu-dh-condena-el-asesinato-de-la-activista-cristina-vazquez-en-la-cdmx\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":36057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80,14,1044,1141,1138,2],"tags":[2140,1210],"class_list":["post-36056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","category-ciudad-de-mexico","category-desarrollos-inmobiliarios-en-la-ciudad-de-mexico","category-feminicidios-en-la-ciudad-de-mexico","category-incremento-de-la-violencia-en-la-ciudad-de-mexico","category-noticias-nacionales","tag-asesinato-de-activistas","tag-conflictos-por-desarrollos-inmobiliarios","entry"],"jetpack_featured_media_url":"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/07\/onu-dh.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-9ny","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":37822,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/08\/11\/antes-de-ser-asesinada-en-la-alcaldia-cuauhtemoc-en-la-ciudad-de-mexico-cristina-vazquez-chavarria-pidio-que-fuera-aumentada-la-seguridad-de-su-zona-informo-el-comite-fundacional-de-la-asociacion-d\/","url_meta":{"origin":36056,"position":0},"title":"Antes de ser asesinada en la Alcald\u00eda Cuauht\u00e9moc, en la Ciudad de M\u00e9xico, Cristina V\u00e1zquez Chavarr\u00eda pidi\u00f3 que fuera aumentada la seguridad de su zona, inform\u00f3 el Comit\u00e9 Fundacional de la Asociaci\u00f3n de Residentes de la Colonia Hip\u00f3dromo.","author":"grieta","date":"11 agosto, 2019","format":false,"excerpt":"<iframe width=\"1188\" height=\"693\" src=\"https:\/\/www.youtube.com\/embed\/4r4-dJgY5NQ\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe> Redacci\u00f3n\/ SIN EMBARGO Antes de ser asesinada en la Alcald\u00eda Cuauht\u00e9moc, en la Ciudad de M\u00e9xico, Cristina V\u00e1zquez Chavarr\u00eda pidi\u00f3 que fuera aumentada la seguridad de su zona, inform\u00f3 el Comit\u00e9 Fundacional de la Asociaci\u00f3n de Residentes de la\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":25050,"url":"http:\/\/www.grieta.org.mx\/index.php\/2018\/07\/20\/preocupa-a-onu-dh-que-oaxaca-sume-4-asesinatos-de-defensores-de-derechos-humanos-en-2018\/","url_meta":{"origin":36056,"position":1},"title":"Preocupa a ONU-DH que Oaxaca sume 4 asesinatos de defensores de derechos humanos en 2018","author":"grieta","date":"20 julio, 2018","format":false,"excerpt":"P\u00e1gina 3. Pedro Mat\u00edas, Oaxaca.- La Oficina en M\u00e9xico del Alto Comisionado de las Naciones Unidas para los Derechos Humanos (ONU-DH) conden\u00f3 el asesinato del coordinador regional del Comit\u00e9 por la Defensa de los Derechos Ind\u00edgenas (CODEDI) en Pochutla, Abraham Hern\u00e1ndez Gonz\u00e1lez. *ONU-DH condena asesinado de l\u00edder ind\u00edgena y exige\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/07\/Codedi-Pag3.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/07\/Codedi-Pag3.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/07\/Codedi-Pag3.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":42173,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/12\/07\/temen-desalojo-contra-comunidad-otomi-en-la-ciudad-de-mexico\/","url_meta":{"origin":36056,"position":2},"title":"Temen desalojo contra comunidad otom\u00ed en la Ciudad de M\u00e9xico","author":"grieta","date":"7 diciembre, 2019","format":false,"excerpt":"Foto: Notoriox Mercedes Matz \/ Notoriox Integrantes de la comunidad Ind\u00edgena Otom\u00ed Residente en la Ciudad de M\u00e9xico denunciaron la amenaza de un desalojo en su contra que podr\u00eda llevarse \u201cen cualquier momento\u201d por parte de las autoridades de la alcald\u00eda Cuauht\u00e9moc y del gobierno capitalino. El pasado mi\u00e9rcoles 4\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Temen-desalojo-contra-comunidad-otom%C3%AD-en-la-Ciudad-de-M%C3%A9xico-dic.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Temen-desalojo-contra-comunidad-otom%C3%AD-en-la-Ciudad-de-M%C3%A9xico-dic.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Temen-desalojo-contra-comunidad-otom%C3%AD-en-la-Ciudad-de-M%C3%A9xico-dic.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":27175,"url":"http:\/\/www.grieta.org.mx\/index.php\/2018\/09\/22\/damnificados-del-edificio-centauro-perdieron-sus-escrituras-el-19s-y-no-saben-si-recuperaran-su-hogar\/","url_meta":{"origin":36056,"position":3},"title":"Damnificados del edificio Centauro perdieron sus escrituras el 19S y no saben si recuperar\u00e1n su hogar","author":"grieta","date":"22 septiembre, 2018","format":false,"excerpt":"","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/10\/Demolicion_Edificio_Osa_Mayor-5-e1537582336854-960x500.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/10\/Demolicion_Edificio_Osa_Mayor-5-e1537582336854-960x500.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/10\/Demolicion_Edificio_Osa_Mayor-5-e1537582336854-960x500.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/10\/Demolicion_Edificio_Osa_Mayor-5-e1537582336854-960x500.jpg?resize=700%2C400 2x"},"classes":[]},{"id":41934,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/12\/03\/plan-de-mitikah-requiere-talar-60-arboles-mas-denuncian-ciudad-de-mexico\/","url_meta":{"origin":36056,"position":4},"title":"Plan de M\u00edtikah requiere talar 60 \u00e1rboles m\u00e1s, denuncian (Ciudad de M\u00e9xico)","author":"grieta","date":"3 diciembre, 2019","format":false,"excerpt":"La Silla Rota De acuerdo con un proyecto presentado por la Secretar\u00eda de Medio Ambiente a los habitantes de Xoco, el pozo se construir\u00eda en el \u00e1rea donde se ubicaba el Centro La posible construcci\u00f3n de un pozo de agua, como parte de las obras de mitigaci\u00f3n por el desarrollo\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/Plan-de-M%C3%ADtikah-requiere-talar-60-cdmx-dic.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":48526,"url":"http:\/\/www.grieta.org.mx\/index.php\/2020\/03\/25\/matan-a-ambientalista-en-jiutepec-morelos-es-el-segundo-defensor-asesinado-en-2020\/","url_meta":{"origin":36056,"position":5},"title":"Matan a ambientalista en Jiutepec, Morelos; es el segundo defensor asesinado en 2020","author":"Admin","date":"25 marzo, 2020","format":false,"excerpt":"Redacci\u00f3n \/ Animal Pol\u00edtico La Oficina en M\u00e9xico del Alto Comisionado de las Naciones Unidas para los Derechos Humanos (ONU-DH) y la Comisi\u00f3n Nacional de los Derechos Humanos (CNDH) condenaron el homicidio del ambientalista Isaac Medardo Herrera y exigieron que no haya impunidad en el caso. La noche del pasado\u2026","rel":"","context":"En &quot;Asesinato de activistas en Morelos&quot;","block_context":{"text":"Asesinato de activistas en Morelos","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/morelos\/asesinato-de-activistas-en-morelos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/asesinan_ambientalista_jiutepec_morelos-e1585188696795.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/asesinan_ambientalista_jiutepec_morelos-e1585188696795.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/asesinan_ambientalista_jiutepec_morelos-e1585188696795.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/asesinan_ambientalista_jiutepec_morelos-e1585188696795.png?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/asesinan_ambientalista_jiutepec_morelos-e1585188696795.png?resize=1050%2C600 3x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/05\/asesinan_ambientalista_jiutepec_morelos-e1585188696795.png?resize=1400%2C800 4x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/36056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=36056"}],"version-history":[{"count":1,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/36056\/revisions"}],"predecessor-version":[{"id":36058,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/36056\/revisions\/36058"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/36057"}],"wp:attachment":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=36056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=36056"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=36056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}