{"id":35233,"date":"2019-06-20T17:08:05","date_gmt":"2019-06-20T22:08:05","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=35233"},"modified":"2019-06-22T17:57:31","modified_gmt":"2019-06-22T22:57:31","slug":"el-tren-maya-por-que-estan-tan-preocupados-los-biologos","status":"publish","type":"post","link":"http:\/\/www.grieta.org.mx\/index.php\/2019\/06\/20\/el-tren-maya-por-que-estan-tan-preocupados-los-biologos\/","title":{"rendered":"El tren maya \u00bfPor qu\u00e9 est\u00e1n tan preocupados los bi\u00f3logos?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"35234\" data-permalink=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/06\/20\/el-tren-maya-por-que-estan-tan-preocupados-los-biologos\/ruta-tren\/\" data-orig-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Ruta-Tren.png\" data-orig-size=\"676,756\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ruta Tren\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Ruta-Tren-268x300.png\" data-large-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Ruta-Tren.png\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Ruta-Tren.png\" alt=\"\" width=\"676\" height=\"756\" class=\"alignleft size-full wp-image-35234\" srcset=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Ruta-Tren.png 676w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Ruta-Tren-268x300.png 268w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Ruta-Tren-447x500.png 447w\" sizes=\"auto, (max-width: 676px) 100vw, 676px\" \/><\/p>\n<p>CASANDRA REYES GARC\u00cdA1,CELENE ESPADAS MANRIQUE1,ALEJANDRA GARC\u00cdA QUINTANILLA2Y MANUELA TAMAYO CHIM1<\/p>\n<p>El tren maya es un proyecto de infraestructura, relevante para la movilidad en la pen\u00ednsula de Yucat\u00e1n. Sin embargo,se desconoce el impacto social  y  ambiental que ocasio-nar\u00e1 sobre ecosistemas de gran importancia biol\u00f3gica, ecol\u00f3gica y cultural como la Re-serva de la Bi\u00f3sfera de Calakmul. De ah\u00ed la importancia de dar a conocer los servicios que las selvas nos proporcionan y los impactos ambientales, que desarrollos como elca-so de la Riviera Maya, causan sobre los ecosistemas en la pen\u00ednsula de Yucat\u00e1n.Palabras clave:Ambiente,Calakmul, conectividad, servicios,turismo.<\/p>\n<p>Ante las  declaraciones  del  5  de febrero del  director  de  FONATUR  Arq.  Rogelio Jim\u00e9nez Pons \u201cEs  muy  f\u00e1cil  decir  de  repente  que  no  haya  desarrollo.  No  podemos   ser   a   ultranza   conservacionistas cuando  tenemos  tanta  miseria;  tenemos que  crear  desarrollo  y  el  desarrollo  va  a tener afectaciones al medio ambiente, obvio.  Pero  primero  va  la  gente.  No  ganamos  nada  como  pa\u00eds  con  tener  jaguares gordos y ni\u00f1os fam\u00e9licos; tiene que haber un equilibrio. S\u00ed tiene que haber jaguares bien  comidos,  pero  con  ni\u00f1os  robustos  y educados  y  capacitados.  \u00c9se  es el  tema: muchas  veces  va  a  implicar  afectar  el medio   ambiente,   pues   remediemos   las afectaciones&#8230;  \u00bfCu\u00e1l  es  la  raz\u00f3n  finalmente  que  un  sant\u00f3n  de  la  ecolog\u00eda  lo quiera  parar?  yo  no  lo  entiendo  a  no  ser que sea de intereses\u201d (Ramos 2019),queda  claro  que  es importante  que  los  bi\u00f3logos difundamos mejor las razones por las cuales estamos preocupados por el impacto  que  el  Tren  Maya  pueda  tener  sobre  la selva  del  sureste  mexicano,  y  las  consecuencias  de  esto  sobre  el  bienestar  de  todos. Nuestra preocupaci\u00f3n es que al entrar el tren a la Reserva de la Bi\u00f3sfera de Calakmul  y  darle  conectividad  con  el  turismo masivo de Canc\u00fan y la Riviera Maya, esto pueda derivar en un colapso ecol\u00f3gico.  Un  colapso  ecol\u00f3gico  se  define  como una  situaci\u00f3n  donde  el  ecosistema  sufre una  serie  de  cambios  irreversibles  que afectan  a  gran  parte  de  sus  organismos  y resulta  en  una  extinci\u00f3n  masiva.  Este  colapso ecol\u00f3gico no s\u00f3lo compete a la flora y  fauna  del  lugar,  sino  que  repercute  directamente  sobre  todos  los  seres  vivos, incluyendo  los  humanos, que  nos  beneficiamos  de  los  servicios  que  la  selva  nos brinda.  Son  estos  servicios  los  que  no  se han valorado en las sociedades occidentales actuales y que requieren ser visibilizados  y  se\u00f1alados  ante  declaraciones  como la arriba citada.<\/p>\n<p>Servicios Ecosist\u00e9micos de la Selva<br \/>\nDentro  de  los  servicios  m\u00e1s  importantes que las selvas nos proveen,est\u00e1 el de ser los pulmones del planeta; la densa vegetaci\u00f3n de la selva absorbe el di\u00f3xido de carbono  y  libera  el  ox\u00edgeno  que  respiramos. El di\u00f3xido de carbono es liberado al aire  al  quemar combustibles  y  es  hoy  en d\u00eda uno de los principales gases de  efecto invernadero,  que  contribuye  al  calentamiento  global.  Los  \u00e1rboles  lo  absorben  y lo  fijan  en  sus  troncos  y  ra\u00edces  por  un tiempo  prolongado,  siendo  el  arma  m\u00e1s importante  con  que  contamos  para  frenar el cambio clim\u00e1tico. <\/p>\n<p>Los  \u00e1rboles  tambi\u00e9n  regulan  la  temperatura  del  ambiente  al  captarla  radiaci\u00f3n del  sol en sus  hojas  y  utilizar  su  energ\u00eda para construir az\u00facares en el proceso de la fotos\u00edntesis.  Para  evitar  sobre calentarse, las plantas liberan peque\u00f1as gotas de agua por sus hojas, las cuales al evaporarse absorben  gran  cantidad  de  energ\u00eda  disminuyendo  la  temperatura  en  un  proceso  llamado transpiraci\u00f3n. Esto hace que, en las horas  de  m\u00e1s  calor,  la  diferencia de  temperatura bajo un \u00e1rbol y a pleno sol pueda llegar  a  ser  de  10\u00b0C  (Reyes-Garc\u00eda  y  Espadas-Manrique 2016). <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"35235\" data-permalink=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/06\/20\/el-tren-maya-por-que-estan-tan-preocupados-los-biologos\/calakmul\/\" data-orig-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Calakmul.png\" data-orig-size=\"682,819\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Calakmul\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Calakmul-250x300.png\" data-large-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Calakmul.png\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Calakmul.png\" alt=\"\" width=\"682\" height=\"819\" class=\"alignleft size-full wp-image-35235\" srcset=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Calakmul.png 682w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Calakmul-250x300.png 250w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Calakmul-416x500.png 416w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/p>\n<p>Otro  de  los  grandes  servicios  es  el  de proveer agua. Se ha visto que las grandes extensiones de bosques o selvas favorecen la  formaci\u00f3n  de  nubes  por  el  vapor  de  la transpiraci\u00f3n  (Moreira et  al.  1997),  promueven  la  lluvia  localmente  porque  las masas  de  aire  cargadas  de  agua  chocan contra ellos e incluso se plantea la hip\u00f3tesis  de  que  los  \u00e1rboles  liberan  compuestos vol\u00e1tiles  que  favorecen  la  formaci\u00f3n  de gotas  de  lluvia  (Andreae et  al.  2002). Tambi\u00e9n se ha visto que las ra\u00edces favorecen la infiltraci\u00f3n del agua al manto fre\u00e1tico. Todo esto contribuye aque las zonas de  selva  fomenten  la  recarga  de  agua  al manto  fre\u00e1tico  (Orellana-Lanza  y  Espa-das-Manrique 2016)<\/p>\n<p>La  fauna  de  las  selvas  contribuye  al control  natural  de  plagas,  as\u00ed  como  a  servicios  como  la  polinizaci\u00f3n.  La  polinizaci\u00f3n  por  vertebrados  e insectos  permite que  las  plantas  puedan  producir  frutos. Este tipo de polinizaci\u00f3n es requerida por la  gran  mayor\u00eda  de  los  vegetales  que  comemos,  por  lo  que  la  muerte  masiva  de las abejas o los murci\u00e9lagos podr\u00eda atentar contra  la  producci\u00f3n  de  alimentos.  Finalmente, los grandes mam\u00edferos como el jaguar  y  el  puma,  controlan  poblaciones  de herb\u00edvoros ayudando a la regeneraci\u00f3n de las plantas en los bosques.<\/p>\n<p>Tambi\u00e9n  hay  servicios  ambientales  de aprovisionamiento, que son tangibles, que se extraen de la selva, como madera, le\u00f1a, frutos,   plantas   medicinales,   colorantes, especias, animales para caza (ver revisi\u00f3n de   servicios   ecosist\u00e9micos   en   Myers 1996).<\/p>\n<p>Por  \u00faltimo,  hay  servicios  culturales, pues  la  naturaleza  es  parte  intr\u00ednseca  del ser de los pueblos originarios, son un importante  valor  intangible  no  s\u00f3lo  para  el bienestar  de  esos  mismos  pueblos  (su  derecho   fundamental)   sino   para   la   selva misma, pues sus pr\u00e1cticas y pensamientos buscan  establecer  una  relaci\u00f3n  de  armon\u00eda, lo menos depredadora posible con la naturaleza.  Adem\u00e1s,  independientemente de  la  cultura,  se  ha  visto  que  el  contacto con  la  naturaleza  reduce  el  estr\u00e9s  y  pro-mueve  la  socializaci\u00f3n,  haci\u00e9ndonos  m\u00e1s felices y sanos (James et al. 2015).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"35236\" data-permalink=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/06\/20\/el-tren-maya-por-que-estan-tan-preocupados-los-biologos\/uso-suelo\/\" data-orig-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo.png\" data-orig-size=\"702,587\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Uso suelo\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo-300x251.png\" data-large-file=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo.png\" src=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo.png\" alt=\"\" width=\"702\" height=\"587\" class=\"alignleft size-full wp-image-35236\" srcset=\"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo.png 702w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo-300x251.png 300w, http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo-598x500.png 598w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/p>\n<p>Posible colapso ecol\u00f3gico en el sur de la Pen\u00ednsula de Yucat\u00e1n<br \/>\nTeniendo  en  cuenta  la  importancia  de los  servicios  ambientales,  es  preocupante el  efecto  que  puede  tener  la  construcci\u00f3n de  la  ruta  que  recorre  las  estaciones  de Tulum-Carrillo  Puerto-Bacalar y  Bacalar-Calakmul-Esc\u00e1rcega, denominadas Caribe I  y  Selva  2 respectivamente(Figura  1). Estas  rutas  atraviesan  porciones  de  la  pen\u00ednsula  de  Yucat\u00e1n  que  a\u00fan albergan zonasde  vegetaci\u00f3n  conservada,  donde  se encuentran dos de las \u00e1reas naturales protegidas  m\u00e1s  importantes  de M\u00e9xico:  la Reserva de la Bi\u00f3sfera de Calakmul, que por su extensi\u00f3n de selva continua constituye  la  segunda  reserva  de  selva  m\u00e1s  importante  de  Am\u00e9rica  tropical,  s\u00f3lo  despu\u00e9s  de  la  Amazonia  y la  Reserva  de  la Bi\u00f3sfera  de  Sian  Ka&#8217;an,  que  alberga  un sistema de r\u00edos subterr\u00e1neos de agua dulce que  interconectan  cenotes  y  petenes,  y que  ha  sido  declarada  Patrimonio  de  la Humanidad  por  la  UNESCO.  Las  v\u00edas acrecentar\u00edan la fragmentaci\u00f3n  y la p\u00e9rdida de  conectividad ecol\u00f3gica entre ambas Reservas.  Cabe  aclarar  que,  si  bien  nos preocupa salvaguardar los ecosistemas durante la construcci\u00f3n y operaci\u00f3n del tren, esta  puede  ser  la  menor  amenaza,  si  se compara con el efecto del llamado \u201cprogreso y desarrollo\u201d que viene despu\u00e9s.<\/p>\n<p>En  el  coraz\u00f3n  de  la  Reserva  de  Calakmul  se  encuentra  una  zona  arqueol\u00f3gica que    ha    sido    denominada    Patrimonio Mundial Mixto por la UNESCO (Secreta-r\u00eda de Cultura 2014) y que se pretende potenciar  como  un  nuevo  atractivo  tur\u00edstico (Figura 2). Actualmente, la zona es de dif\u00edcil acceso, debido a su rol principal en la conservaci\u00f3n.  Posee  muy  poca  infraestructura en restaurantes  y  hoteles  y recibe menos de 40 mil turistas al a\u00f1o. Al conectarla  con  el  tren  se  espera  que  de  los  casi 17 millones de turistas que llegan al a\u00f1o a Canc\u00fan   (Secretar\u00eda   de   Turismo   2018),unos  3  millones  lleguen  a  visitar  Calakmul. El  crecimiento  de  la  Riviera  Maya nos  da  un  claro  ejemplo  de  lo  que  pasa con  estos  tipos  de  desarrollos.  Ah\u00ed se  ha tenido  un  crecimiento  poblacional  exponencial desde 1980, aumentando en un 70%;  la  gran  mayor\u00eda  de  los  habitantes  han llegado  de  fuera  del  estado de  Quintana Roo paral a construcci\u00f3n de la infraestructura hotelera, restaurantera, etc.  y la prestaci\u00f3n de servicios (datos 1980-2005; Rubio Maldonado et al. 2010). En el proyecto  Riviera  Maya  se  dijo  en  repetidas  oca-siones que se iba a mantener un desarrollo responsable  con  el  medio  ambiente  y  de bajo  impacto,  y  que  traer\u00eda  consigo  bienestar; pero la situaci\u00f3n muestra un panorama  donde  la  poblaci\u00f3n  local  fue  reubicada  y  donde  la  biodiversidad  ha sido fuertemente  impactada;  muestra  de  ello son los ecocidios tanto en el mar como en la  tierra,  donde  el  coral,  las  selvas  y  los manglares  han  muerto (Revisado  en  Rubio Maldonado et al. 2010). Las promesas del  desarrollo  sostenible  han  sucumbido ante  la constante  presi\u00f3n  de  expandir  la oferta tur\u00edstica, con una demanda de cuartos e infraestructura  creciente. En las playas  de  Tulum  a\u00fan  no  hay  electricidad, acorde  con  la  idea  de  que  esas  zonas  no iban  a  desarrollarse  para  el  turismo  masivo.  Sin  embargo,los  hoteles  ya  no  son ecol\u00f3gicos.   Ahora   hay generadores   de di\u00e9sel  para  mantener  los  aires  acondicionados que requieren los turistas, contaminando  de  ruido  las  playas  d\u00eda  y  noche,  y que  junto  con  los  RAVES, inundan  de ruido y luces una selva,donde quien tiene patas  ya  habr\u00e1  corrido  (Wiedeman  2019). \u00bfEs  este  el  futuro  que  queremos  para  Ca-lakmul?  \u00bfPuede  este  tipo  de  perturbaci\u00f3n derivar en un colapso ecol\u00f3gico?<\/p>\n<p>La vegetaci\u00f3n primaria de la pen\u00ednsula de Yucat\u00e1n pr\u00e1cticamente est\u00e1 restringida dentro  de  las \u00e1reas  naturales  protegidas, en  su  mayor\u00eda  dentro  del  per\u00edmetro  de  la reserva  de  Calakmul  (Figura  3).  Este  tipo de vegetaci\u00f3n  es  el  que  no  ha  sido  aun fuertemente perturbada ya sea por las personas  o  por  causas  naturales,  como  los huracanes.  La  vegetaci\u00f3n primaria  conserva  por  lo  general  una  estructura  m\u00e1s compleja   y   de   mayor   diversidad.   Una gran parte de la Pen\u00ednsula est\u00e1 cubierta de vegetaci\u00f3n  secundaria,  la  cual  ya  ha  sido fuertemente  perturbada  y  se  encuentra  en alg\u00fan punto de regeneraci\u00f3n.<\/p>\n<p>Los  servicios  ambientales  de  la  selva se  dan  por  sentados  y  se  piensa  que,  si siempre  han  sido  as\u00ed,  lo  seguir\u00e1n  siendo. Sin  embargo,  antes  tambi\u00e9n  ve\u00edamos  como la basura tirada en el mar desaparec\u00eda en  su  vasta  extensi\u00f3n  sin  aparente  consecuencia; mientras que hoy en d\u00eda sabemos que  hay  islas  enteras  de  basura  y  que  las poblaciones  de  peces  y  mam\u00edferos  marinos han deca\u00eddo a causa de la gran contaminaci\u00f3n.  Lo  mismo  suceder\u00e1  con  la  selva, solo ser\u00e1 visible su colapso cuando es-te  se  acerque  al  punto  de  quiebre,  donde dif\u00edcilmente  podr\u00e1  ser  reversible.  La  destrucci\u00f3n  de  la  poca  selva  que  nos  quede puede llevar a que los grandes mam\u00edferos no  tengan  suficiente  comida  y  refugio  y mueran.  Con  esto  los  herb\u00edvoros  aumentan, y disminuye la regeneraci\u00f3n de la vegetaci\u00f3n, que igualmente ya se habr\u00e1 visto afectada  por  la  falta  de  polinizadores  y por el calentamiento en las zonas deforestadas. Esto deriva en que una vez que los grandes  \u00e1rboles  mueran,  no  haya  reclutamiento  de  individuos  j\u00f3venes.  Entonces cambiar\u00e1n   las   lluvias,   se   vaciar\u00e1n   los mantos fre\u00e1ticos, subir\u00e1n las temperaturas y los cultivos no ser\u00e1n polinizados.<\/p>\n<p>Si  bien  este  escenario  es  catastr\u00f3fico, ya  la  Organizaci\u00f3n  de  las  Naciones  Unidas (ONU) ha advertido que \u201ces necesario adoptar medidas urgentes a una escala sin precedentes para detener y revertir esta situaci\u00f3n  y  proteger  as\u00ed  la  salud  humana  y ambiental\u201d  (S\u00e1nchez  y  Planelles  2019). M\u00e9xico  es  el  primer  pa\u00eds  en  elaborar  y aplicar una ley General de Cambio Clim\u00e1-tico  (2012)  y  ha  desarrollado  estrategias comoel  Programa  especial  de  Cambio Clim\u00e1tico  2014-2018(2014),  ha  firmado acuerdos  internacionales  donde  se  compromete  a  disminuir  las  emisiones  de  gases de efecto invernadero y frenar la deforestaci\u00f3n.  Sin  embargo,  si,  el  proyecto Tren Maya no hace un an\u00e1lisis exhaustivo del  impacto  ambiental,  social  y  econ\u00f3mico que causar\u00eda, claramente impactar\u00eda en direcci\u00f3n  opuesta  a  estos  acuerdos.  La destrucci\u00f3n de la selva impactar\u00e1 primero a los m\u00e1s pobres. Estos ser\u00e1n los primeros en  ver  la  disminuci\u00f3n  de  la  miel en  sus apiarios y  de  las  cosechas  en  sus  milpas. Por  esta  raz\u00f3n,  es  importante  detenerse  y hacer un verdadero an\u00e1lisis de los impactos del Tren Maya y modificar su ruta para salvaguardar la selva.<\/p>\n<p>Referencias<br \/>\nAndreae  M.O,  Artaxo  P.,  Brand\u00e3o  C., Carswell  F.E.,  Ciccioli  P.,  da  Costa A.L.,  Culf  A.D.,  Esteves  J.L.,  Gash J.H.C., Grace J., Kabat P., Lelieveld J.,  Malhi  Y.,  Manzi  A.O.,  Meixner F.X.,  Nobre  A.D.,  Nobre  C.,  Ruivo M.d.L.P.,   Silva-Dias   M.A.,   Stefani P.,  Valentini  R.,  von  Jouanne  J.  y Waterloo  M.J.  2002.Biogeochemical cycling  of  carbon,  water,  energy,  trace gases,  and  aerosols  in  Amazonia:  The LBA-EUSTACH experiments. Journal of   Geophysical   Research107(D20): 8066. Doi:10.1029\/2001JD000524<br \/>\nDiario  Oficial  de  la  Federaci\u00f3n.  2012. Ley General de Cambio Clim\u00e1tico.http:\/\/www.diputados.gob.mx\/LeyesBiblio\/pdf\/LGCC_130718.pdf(consultado6 de junio 2019).<br \/>\nDiario  Oficial  de la  Federaci\u00f3n.  2014. Programa  Especial  de  Cambio  Clim\u00e1-tico 2014-2018.http:\/\/www.sectur.gob.mx\/wp-content\/uploads\/2014\/09\/PECC-2014-2018.pdf(consultado    14    de    junio 2019)<br \/>\nJames  P.,  Banay  R.F.,  HartJ.E.  y  La-den  F.  2015. A  review  of  the  health benefits  of  greenness.Current  epide-miology reports2(2): 131-142<br \/>\nMoreira  M.,  Sternberg  L.,  Martinelli L.,  Victoria  R.,  Barbosa  E.,  Bonates L. y Nepstad D.1997. Contribution of transpiration  to  forest  ambient  vapour based  on  isotopic  measurements. Glo-bal Change Biology3(5):439-450.<br \/>\nMyers  N.1996.  Environmental  services of biodiversity. Proceedings of the Na-tional   Academy   of   Sciences93(7):2764-2769.<br \/>\nOrellana-LanzaR.y Espadas-Manrique C. 2016.El   Papel   de   la   Cubierta Vegetal  en  la  Conservaci\u00f3n  del  Agua en   la   Pen\u00ednsula   de   Yucat\u00e1n.   En: Ch\u00e1vez-Guzm\u00e1n M. Ed.El Manejo del agua a trav\u00e9s el tiempo en la pen\u00ednsula de  Yucat\u00e1n,  pp. 161-177.  Universidad Aut\u00f3noma  de Yucat\u00e1n,  Secretar\u00eda  de Desarrollo Urbano  y  Medio Ambiente, Consejo  de  la  Cuenca  de  La  Pen\u00ednsula de  Yucat\u00e1n, Fundaci\u00f3n  Gonzalo  R\u00edo Arronte, IAP. M\u00e9rida, Yucat\u00e1n,M\u00e9xico.<br \/>\nRamos C. 2019. Animal pol\u00edtico. Nota de prensa.  Tren  Maya:  el  beneficio  social compensa el  impacto  ambiental,  justifica FONATUR. https:\/\/www.animalpolitico.com\/2019\/02\/tren-maya-proyecto-construccion-comunidades-indigenas\/(consultado  6 Febrero 2019).<br \/>\nReyes-Garc\u00eda  C.  y  Espadas-Manrique C.2016.Oleadas  de  calor  y  el  efecto de  la  vegetaci\u00f3n  en  Yucat\u00e1n. Desde  el herbario CICY8:97-101.<br \/>\nRubio  Maldonado  E.,  Murad  Robles M.  y  Rovira  Sanroque  J.V.  2010. Crisis ambiental en la costa de QuintanaRoo como consecuenciade una visi\u00f3n  limitada  de  lo  que  representa  el desarrollo     sustentable. Argumentos 23(63): 161-185.<br \/>\nS\u00e1nchez E. y Planelles M. 2019.Nota de Prensa. El Pa\u00eds. https:\/\/elpais.com\/sociedad\/2019\/03\/12\/actualidad\/1552409167_549272.html(consultado 13 Marzo2019).<br \/>\nSecretar\u00eda  de  cultura.  2014.UNESCO extiende  la  inscripci\u00f3n  de  Calakmul  a Bien  Mixto  en  la  lista  del  Patrimonio Mundial.https:\/\/www.gob.mx\/cultura\/prensa\/unesco-extiende-la-inscripcion-de-calakmul-a-bien-mixto-en-la-lista-del-patrimonio-mundial(consultado 13 Marzo 2019).<br \/>\nSecretar\u00eda   de Turismo. Secretar\u00eda   deTurismo.   2018. Reporte anual de turismo Quintana Roo 2017. http:\/\/caribemexicano.travel\/ARCHIVOS\/REPORTE%20TURISMO%202017.pdf(Consultado 12 de Marzo 2019).Wiedeman  R.  2019.Nota de prensa.The Cut. https:\/\/www.thecut.com\/2019\/02\/who-killed-tulum.html(consultado  14  mar-zo2019).<\/p>\n<p><a href=\"https:\/\/www.cicy.mx\/Documentos\/CICY\/Desde_Herbario\/2019\/2019-06-20-Reyes-et-al.-El-Tren-maya.pdf\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/www.cicy.mx\/Documentos\/CICY\/Desde_Herbario\/2019\/2019-06-20-Reyes-et-al.-El-Tren-maya.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASANDRA REYES GARC\u00cdA1,CELENE ESPADAS MANRIQUE1,ALEJANDRA GARC\u00cdA QUINTANILLA2Y MANUELA TAMAYO CHIM1 El tren maya es un proyecto de infraestructura, relevante para la movilidad en la pen\u00ednsula de Yucat\u00e1n. Sin embargo,se desconoce &hellip; <a href=\"http:\/\/www.grieta.org.mx\/index.php\/2019\/06\/20\/el-tren-maya-por-que-estan-tan-preocupados-los-biologos\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":35236,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,2044],"tags":[],"class_list":["post-35233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-megaproyectos","category-tren-maya-analisis","entry"],"jetpack_featured_media_url":"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/Uso-suelo.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-9ah","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":42576,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/12\/23\/alertan-que-construccion-del-tren-maya-matara-a-calakmul\/","url_meta":{"origin":35233,"position":0},"title":"Alertan que construcci\u00f3n del Tren Maya &#8216;matar\u00e1&#8217; a Calakmul","author":"grieta","date":"23 diciembre, 2019","format":false,"excerpt":"Diario de M\u00e9xico M\u00e9xico.- La Reserva de la Biosfera de Calakmul, considerada Patrimonio Mixto de la Humanidad por la Unesco, estar\u00eda en grave riesgo de perderse al construirse el Tren Maya y dise\u00f1arse un \u201ctren interior\u201d en la zona n\u00facleo del \u00e1rea protegida. Con las consignas #NOAlTrenMayaEsEcocidio + Despojos +\u2026","rel":"","context":"En &quot;Campeche&quot;","block_context":{"text":"Campeche","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/calakmul-e1577656275525.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/calakmul-e1577656275525.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/calakmul-e1577656275525.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/12\/calakmul-e1577656275525.jpg?resize=700%2C400 2x"},"classes":[]},{"id":35222,"url":"http:\/\/www.grieta.org.mx\/index.php\/2019\/06\/21\/el-tren-maya-ocasionaria-un-colapso-ecologico-en-la-peninsula-de-yucatan\/","url_meta":{"origin":35233,"position":1},"title":"El Tren Maya ocasionar\u00eda un colapso ecol\u00f3gico en la Pen\u00ednsula de Yucat\u00e1n","author":"grieta","date":"21 junio, 2019","format":false,"excerpt":"Jessica Ruiz\/Diario de Yucat\u00e1n La ruta del Tren Maya a su paso por la Reserva de la Bi\u00f3sfera de Calakmul ocasionar\u00eda un colapso ecol\u00f3gico en la Pen\u00ednsula de Yucat\u00e1n, el cual ser\u00eda irreversible e implicar\u00eda una extinci\u00f3n masiva de especies. Esta es la principal preocupaci\u00f3n de cient\u00edficos yucatecos, de acuerdo\u2026","rel":"","context":"En &quot;16. Pueblo Maya&quot;","block_context":{"text":"16. Pueblo Maya","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/espejos-de-la-resistencia\/16-pueblo-maya\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/tren.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/tren.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/tren.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2019\/06\/tren.jpg?resize=700%2C400 2x"},"classes":[]},{"id":66234,"url":"http:\/\/www.grieta.org.mx\/index.php\/2023\/01\/29\/construccion-de-hotel-tren-maya-en-calakmul-genera-molestia-campeche\/","url_meta":{"origin":35233,"position":2},"title":"Construcci\u00f3n de Hotel Tren Maya en Calakmul genera molestia (Campeche)","author":"grieta","date":"29 enero, 2023","format":false,"excerpt":"Jairo Maga\u00f1a \/ Foto: Gobierno de M\u00e9xico \/ La Jornada Maya Ejidatarios se\u00f1alan que no se les ense\u00f1\u00f3 una MIA para el proyecto Calakmul, Campeche Video revela cuestionamientos y quejas sobre la construcci\u00f3n del hotel Edzn\u00e1, proyecto tur\u00edstico innovador (anunciado por Andr\u00e9s Manuel L\u00f3pez Obrador, presidente de M\u00e9xico, el 23\u2026","rel":"","context":"En &quot;Campeche&quot;","block_context":{"text":"Campeche","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/CalakmulHotel-e1676393960214.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/CalakmulHotel-e1676393960214.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/CalakmulHotel-e1676393960214.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/01\/CalakmulHotel-e1676393960214.jpg?resize=700%2C400 2x"},"classes":[]},{"id":50692,"url":"http:\/\/www.grieta.org.mx\/index.php\/2020\/06\/09\/con-diesel-sin-estudios-y-en-tierra-de-jaguares-5-danos-ecologicos-del-tren-maya\/","url_meta":{"origin":35233,"position":3},"title":"Con diesel, sin estudios y en tierra de jaguares: 5 da\u00f1os ecol\u00f3gicos del Tren Maya","author":"grieta","date":"9 junio, 2020","format":false,"excerpt":"Maximiliano Carranza \/ Sopitas.com El Tren Maya ha quedado una vez m\u00e1s en el centro de la discusi\u00f3n. A menos de una semana de que se celebrara el D\u00eda Mundial del Medio Ambiente y mientras una emergencia sanitaria tiene a M\u00e9xico pr\u00e1cticamente encerrado, este proyecto emblem\u00e1tico de la administraci\u00f3n actual\u2026","rel":"","context":"En &quot;Campeche&quot;","block_context":{"text":"Campeche","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/06\/diesel-combustible-contaminacion-danos-ecologicos-selva-reserva-tren-maya-yucatan-agua-jaguares-1110x581-e1592002212370.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/06\/diesel-combustible-contaminacion-danos-ecologicos-selva-reserva-tren-maya-yucatan-agua-jaguares-1110x581-e1592002212370.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/06\/diesel-combustible-contaminacion-danos-ecologicos-selva-reserva-tren-maya-yucatan-agua-jaguares-1110x581-e1592002212370.jpeg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2020\/06\/diesel-combustible-contaminacion-danos-ecologicos-selva-reserva-tren-maya-yucatan-agua-jaguares-1110x581-e1592002212370.jpeg?resize=700%2C400 2x"},"classes":[]},{"id":66252,"url":"http:\/\/www.grieta.org.mx\/index.php\/2023\/02\/10\/el-tren-maya-perpetra-la-destruccion-de-la-selva-mas-grande-de-america-central\/","url_meta":{"origin":35233,"position":4},"title":"El Tren Maya perpetra la destrucci\u00f3n de la selva m\u00e1s grande de Am\u00e9rica Central","author":"grieta","date":"10 febrero, 2023","format":false,"excerpt":"Mariela Le\u00f3n \/ Foto: Greenpeace \/ Cambio 16 Los trabajos de construcci\u00f3n del Tren Maya, en la pen\u00ednsula de Yucat\u00e1n, al sureste de M\u00e9xico, no se detienen. A pesar de los cuestionamientos y centenares de demandas (colectivas e individuales) por la impactante, larga y dolorosa deforestaci\u00f3n que deja a su\u2026","rel":"","context":"En &quot;Campeche&quot;","block_context":{"text":"Campeche","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/campeche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/02\/LaSelvaNoSeVende-e1676396740680.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/02\/LaSelvaNoSeVende-e1676396740680.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/02\/LaSelvaNoSeVende-e1676396740680.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/02\/LaSelvaNoSeVende-e1676396740680.jpg?resize=700%2C400 2x"},"classes":[]},{"id":67545,"url":"http:\/\/www.grieta.org.mx\/index.php\/2023\/08\/17\/reserva-de-calakmul-recibira-mas-de-6-mil-autobuses-al-ano-campeche\/","url_meta":{"origin":35233,"position":5},"title":"Reserva de Calakmul recibir\u00e1 m\u00e1s de 6 mil autobuses al a\u00f1o (Campeche)","author":"grieta","date":"17 agosto, 2023","format":false,"excerpt":"Santiago Navarro F \/ Avispa Midia En portada: Fauna al interior de la Reserva de la Biosfera de Calakmul, Campeche. Foto: Santiago Navarro F La majestuosa armon\u00eda de los cantos de las aves, los monos saltando de un \u00e1rbol a otro, el viento marcando el paso; as\u00ed se va pintando\u2026","rel":"","context":"En &quot;25. Xpujil&quot;","block_context":{"text":"25. Xpujil","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/espejos-de-la-resistencia\/25-xpujil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/08\/Calakmul-scaled-e1692661866185.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/08\/Calakmul-scaled-e1692661866185.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/08\/Calakmul-scaled-e1692661866185.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2023\/08\/Calakmul-scaled-e1692661866185.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/35233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35233"}],"version-history":[{"count":1,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/35233\/revisions"}],"predecessor-version":[{"id":35237,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/35233\/revisions\/35237"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/35236"}],"wp:attachment":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35233"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}