{"id":20755,"date":"2016-08-31T20:35:03","date_gmt":"2016-09-01T01:35:03","guid":{"rendered":"http:\/\/www.grieta.org.mx\/?p=20755"},"modified":"2016-09-01T20:35:59","modified_gmt":"2016-09-02T01:35:59","slug":"normalistas-en-planton-frente-a-secretaria-de-finanzas-de-michoacan","status":"publish","type":"post","link":"http:\/\/www.grieta.org.mx\/index.php\/2016\/08\/31\/normalistas-en-planton-frente-a-secretaria-de-finanzas-de-michoacan\/","title":{"rendered":"Normalistas en plant\u00f3n frente a Secretar\u00eda de Finanzas de Michoac\u00e1n"},"content":{"rendered":"<p>Morelia, Mich. Unos 200 integrantes de la Organizaci\u00f3n de Normales Oficiales del Estado (Onem) se plantaron frente a la Secretar\u00eda de Finanzas del gobierno estatal, sobre la avenida Ventura Puente para exigir el pago de becas y apoyo para el mantenimiento de las ocho escuelas formadoras de maestros en Michoac\u00e1n.<\/p>\n<p>Los normalistas a\u00fan mantienen retenidos m\u00e1s de 50 veh\u00edculos en las comunidades de Tur\u00edcuaro y Arantepacua, municipio de Nahuatzen; desde el 25 de julio a la fecha, los normalistas han incendiado cuatro autobuses y tres camionetas repartidoras de mercanc\u00edas.<\/p>\n<p>Los estudiantes tambi\u00e9n demandan la liberaci\u00f3n de ocho normalistas detenidos junto con otros 31 compa\u00f1eros que ya fueron liberados, el pasado 15 de agosto. Asimismo, demandan mil 200 plazas autom\u00e1ticas para los egresados de las escuelas Normales.<\/p>\n<p><a href=\"http:\/\/www.jornada.unam.mx\/ultimas\/2016\/08\/31\/normalistas-en-planton-frente-a-secretaria-de-finanzas-de-michoacan\" target=\"_blank\">http:\/\/www.jornada.unam.mx\/ultimas\/2016\/08\/31\/normalistas-en-planton-frente-a-secretaria-de-finanzas-de-michoacan<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morelia, Mich. Unos 200 integrantes de la Organizaci\u00f3n de Normales Oficiales del Estado (Onem) se plantaron frente a la Secretar\u00eda de Finanzas del gobierno estatal, sobre la avenida Ventura Puente &hellip; <a href=\"http:\/\/www.grieta.org.mx\/index.php\/2016\/08\/31\/normalistas-en-planton-frente-a-secretaria-de-finanzas-de-michoacan\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":21928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[80],"tags":[886,225,885],"class_list":["post-20755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cintillo","tag-creacion-de-plazas","tag-normalistas","tag-pago-de-becas","entry"],"jetpack_featured_media_url":"http:\/\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ZJR4-5oL","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":7388,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/09\/01\/conflictos-y-resistencia-de-las-escuelas-normales-rurales-de-michoacan\/","url_meta":{"origin":20755,"position":0},"title":"Conflictos y resistencia de las Escuelas Normales Rurales de Michoac\u00e1n","author":"Admin","date":"1 septiembre, 2016","format":false,"excerpt":"Movilizaciones de normalistas exigiendo el pago de sus becas y la creaci\u00f3n de plazas en Michoac\u00e1n 01\/09\/16. Marchan en Guerrero y Michoac\u00e1n por plazas y becas Animal Pol\u00edtico 31\/08\/16. Normalistas en plant\u00f3n frente a Secretar\u00eda de Finanzas de Michoac\u00e1n La Jornada 19\/03\/16. Amagan normalistas con movilizarse en vacaciones Quadratin 01\/03\/16.\u2026","rel":"","context":"En &quot;Michoac\u00e1n&quot;","block_context":{"text":"Michoac\u00e1n","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/noticias-nacionales\/michoacan\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":54556,"url":"http:\/\/www.grieta.org.mx\/index.php\/2020\/08\/31\/cnte-protesta-frente-a-secretaria-de-finanzas-de-michoacan\/","url_meta":{"origin":20755,"position":1},"title":"CNTE protesta frente a Secretar\u00eda de Finanzas de Michoac\u00e1n","author":"grieta","date":"31 agosto, 2020","format":false,"excerpt":"Demandan basificaci\u00f3n de todos los egresados de 8 escuelas normales que hay en el Estado. Eje Central, 31 de agosto de 2020 Con la exigencia de plazas para egresados, miembros de la Secci\u00f3n XVIII de la Coordinadora Nacional de Trabajadores de la Educaci\u00f3n (CNTE) y egresados normalistas, protestaron frente a\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":7428,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/03\/01\/exigen-normalistas-de-michoacan-pago-de-adeudos-de-becas\/","url_meta":{"origin":20755,"position":2},"title":"Exigen normalistas de Michoac\u00e1n pago de adeudos de becas","author":"Admin","date":"1 marzo, 2016","format":false,"excerpt":"MORELIA, Mich., 1 de marzo de 2016.- De nueva cuenta, estudiantes normalistas de diferentes planteles del estado se movilizan en las inmediaciones de la Secretar\u00eda de Finanzas y Administraci\u00f3n. De acuerdo con algunos de los presentes, esta manifestaci\u00f3n es pac\u00edfica y no pretenden bloquear vialidades hasta el momento, en demanda\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":20752,"url":"http:\/\/www.grieta.org.mx\/index.php\/2016\/09\/01\/marchan-en-guerrero-y-michoacan-por-plazas-y-becas\/","url_meta":{"origin":20755,"position":3},"title":"Marchan en Guerrero y Michoac\u00e1n por plazas y becas","author":"grieta","date":"1 septiembre, 2016","format":false,"excerpt":"IGNACIO ROQUE MADRIZ EN MORELIA [...] En Michoac\u00e1n, estudiantes de las ocho escuelas normales de la entidad se plantaron este mi\u00e9rcoles frente a la sede de la Secretar\u00eda de Finanzas y Administraci\u00f3n (SFA) del gobierno estatal, ubicada en la avenida Ventura Puente en Morelia, para exigir el pago de becas\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]},{"id":22779,"url":"http:\/\/www.grieta.org.mx\/index.php\/2018\/04\/17\/vive-michoacan-jornada-de-protestas-de-la-cnte-y-normalistas\/","url_meta":{"origin":20755,"position":4},"title":"Vive Michoac\u00e1n jornada de protestas de la CNTE y normalistas","author":"Admin","date":"17 abril, 2018","format":false,"excerpt":"POR FRANCISCO CASTELLANOS J MORELIA, MICH. (apro).- Integrantes de la secci\u00f3n 18 de la Coordinadora Nacional de Trabajadores de la Educaci\u00f3n (CNTE), realizan una jornada de bloqueos en diversas casetas y autopistas de Michoac\u00e1n; los egresados de la Escuela Normal realizan otra protesta afuera de las oficinas de Secretar\u00eda de\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/04\/DbFAc2TUwAET0ki-c.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/04\/DbFAc2TUwAET0ki-c.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/04\/DbFAc2TUwAET0ki-c.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/04\/DbFAc2TUwAET0ki-c.jpg?resize=700%2C400 2x"},"classes":[]},{"id":7431,"url":"http:\/\/www.grieta.org.mx\/index.php\/2015\/11\/27\/normalistas-marchan-en-michoacan-e-inician-planton-indefinido\/","url_meta":{"origin":20755,"position":5},"title":"Normalistas marchan en Michoac\u00e1n e inician plant\u00f3n indefinido","author":"Admin","date":"27 noviembre, 2015","format":false,"excerpt":"FRANCISCO CASTELLANOS J. MORELIA, Mich., (apro).- Integrantes de los diferentes planteles de la Organizaci\u00f3n de Normales Oficiales del Estado de Michoac\u00e1n (ONOEM), respaldados por docentes y habitantes de comunidades ind\u00edgenas, marcharon este viernes a Casa de Gobierno y al centro de la capital michoacana, donde iniciaron un \u201cun plant\u00f3n\u201d indefinido.\u2026","rel":"","context":"En &quot;CINTILLO&quot;","block_context":{"text":"CINTILLO","link":"http:\/\/www.grieta.org.mx\/index.php\/category\/cintillo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.grieta.org.mx\/wp-content\/uploads\/2018\/03\/14524434_1106112876131411_958039263622046936_o.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/20755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=20755"}],"version-history":[{"count":1,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/20755\/revisions"}],"predecessor-version":[{"id":20756,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/20755\/revisions\/20756"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media\/21928"}],"wp:attachment":[{"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=20755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=20755"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.grieta.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=20755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}